{"id":9046,"date":"2020-04-28T13:32:31","date_gmt":"2020-04-28T16:32:31","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=9046"},"modified":"2020-04-28T12:54:34","modified_gmt":"2020-04-28T15:54:34","slug":"coronavoucher-mpf-promove-articulacao-para-reduzir-aglomeracoes-em-agencias-da-caixa-no-rn","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2020\/04\/28\/coronavoucher-mpf-promove-articulacao-para-reduzir-aglomeracoes-em-agencias-da-caixa-no-rn\/","title":{"rendered":"Coronavoucher: MPF promove articula\u00e7\u00e3o para reduzir aglomera\u00e7\u00f5es em ag\u00eancias da Caixa no RN"},"content":{"rendered":"\n<p>Na \u00faltima sexta-feira (24), o Minist\u00e9rio P\u00fablico Federal (MPF) promoveu videoconfer\u00eancia com representantes da Caixa Econ\u00f4mica Federal, prefeituras, MP\/RN, MPT\/RN, defensorias p\u00fablicas, procons e Pol\u00edcia Militar no Rio Grande do Norte para discutir as aglomera\u00e7\u00f5es nos entornos das ag\u00eancias banc\u00e1rias, para cadastramento e pagamento do benef\u00edcio federal denominado \u201ccoronavoucher\u201d. O objetivo \u00e9 coordenar uma atua\u00e7\u00e3o articulada entre os \u00f3rg\u00e3os para organizar as filas com a dist\u00e2ncia adequada entre as pessoas e condi\u00e7\u00f5es de higiene que evitem a propaga\u00e7\u00e3o da covid-19.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" width=\"640\" height=\"480\" src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2020\/04\/images-7-1.jpeg\" alt=\"\" class=\"wp-image-8608\" srcset=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2020\/04\/images-7-1.jpeg 640w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2020\/04\/images-7-1-300x225.jpeg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><figcaption>Reprodu\u00e7\u00e3o<\/figcaption><\/figure>\n\n\n\n<p><br>Para a procuradora-chefe do MPF no RN, Cibele Benevides, \u201cnesse momento de crise na sa\u00fade p\u00fablica, \u00e9 essencial a colabora\u00e7\u00e3o entre os \u00f3rg\u00e3os para encontrar solu\u00e7\u00f5es que reduzam a exposi\u00e7\u00e3o ao v\u00edrus. N\u00e3o podemos permitir que a parcela mais pobre da popula\u00e7\u00e3o, ao buscar acesso ao benef\u00edcio emergencial, corra riscos ainda maiores de se contaminar com a covid-19\u201d, defendeu.<\/p>\n\n\n\n<p><br>Como resultado da reuni\u00e3o, ficou definido que as prefeituras atuar\u00e3o em parceria com a Caixa na demarca\u00e7\u00e3o das cal\u00e7adas e disponibiliza\u00e7\u00e3o de carros de som para orientar os clientes. As prefeituras tamb\u00e9m devem se esfor\u00e7ar para criar a figura do \u201cdesaglomerador\u201d, funcion\u00e1rios para orientar e conscientizar os cidad\u00e3os, sem car\u00e1ter punitivo. Outra solu\u00e7\u00e3o \u00e9 a busca por locais pr\u00f3ximos para acomodar as pessoas, de prefer\u00eancia espa\u00e7os p\u00fablicos, evitando que as filas se formem nas ruas. Caso n\u00e3o seja poss\u00edvel, \u00e9 proposta a coloca\u00e7\u00e3o de toldos e cadeiras, com o devido distanciamento.<\/p><div class=\"idmjy6a981a5c68d41\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.idmjy6a981a5c68d41 {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.idmjy6a981a5c68d41 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.idmjy6a981a5c68d41 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.idmjy6a981a5c68d41 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.idmjy6a981a5c68d41 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.idmjy6a981a5c68d41 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"bikhi6a981a5c68d29\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.bikhi6a981a5c68d29 {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.bikhi6a981a5c68d29 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.bikhi6a981a5c68d29 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.bikhi6a981a5c68d29 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.bikhi6a981a5c68d29 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.bikhi6a981a5c68d29 {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p><br>Os procuradores do MPF que atuam nas Procuradorias da Rep\u00fablica nos Munic\u00edpios, Maria Clara Lucena (Caic\u00f3), Victor Queiroga (Assu) e A\u00e9cio Tarouco (Mossor\u00f3), tamb\u00e9m participaram do encontro e acompanhar\u00e3o o cumprimento das diretrizes nas respectivas regi\u00f5es. A superintend\u00eancia da Caixa e prefeituras t\u00eam prazo de cinco dias para prestar informa\u00e7\u00f5es sobre a situa\u00e7\u00e3o no entorno das ag\u00eancias.<\/p>\n\n\n\n<p><br><strong>Boas pr\u00e1ticas \u2013<\/strong>&nbsp;Uma das prefeituras j\u00e1 encaminhou registros da ado\u00e7\u00e3o de medidas para organiza\u00e7\u00e3o das pessoas que buscam o banco. Em Goianinha, antes mesmo da reuni\u00e3o da \u00faltima sexta-feira, a fila j\u00e1 vinha sendo organizada em um gin\u00e1sio pr\u00f3ximo \u00e0 ag\u00eancia da Caixa, com o distanciamento adequado. Os demais munic\u00edpios v\u00eam buscando formas de garantir o fim das aglomera\u00e7\u00f5es e devem manter o MPF ciente das iniciativas.<\/p>\n\n\n\n<p><br><strong>Atua\u00e7\u00e3o&nbsp;<\/strong>&#8211; A articula\u00e7\u00e3o para organiza\u00e7\u00e3o das filas no entorno das ag\u00eancias da Caixa \u00e9 mais uma linha de atua\u00e7\u00e3o do Grupo de Trabalho Estadual de acompanhamento das medidas governamentais e privadas relacionadas ao novo coronav\u00edrus (GT Covid-19), institu\u00eddo no MPF\/RN. O GT Covid-19 \u00e9 formado pelos procuradores da Rep\u00fablica Caroline Maciel, Victor Mariz, Cibele Benevides, Fernando Rocha, M\u00e1rcio Albuquerque e Maria Clara Lucena. Desde o in\u00edcio da pandemia, o grupo trabalha com a realiza\u00e7\u00e3o de reuni\u00f5es com os demais \u00f3rg\u00e3os envolvidos, expedi\u00e7\u00e3o de recomenda\u00e7\u00f5es, celebra\u00e7\u00e3o de Termos de Ajustamento de Conduta, instaura\u00e7\u00e3o de inqu\u00e9ritos e ajuizamento de a\u00e7\u00f5es.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O objetivo \u00e9 coordenar uma atua\u00e7\u00e3o articulada entre os \u00f3rg\u00e3os para organizar as filas com a dist\u00e2ncia adequada entre as pessoas e condi\u00e7\u00f5es de higiene que evitem a propaga\u00e7\u00e3o da covid-19.<br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2020\/04\/28\/coronavoucher-mpf-promove-articulacao-para-reduzir-aglomeracoes-em-agencias-da-caixa-no-rn\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":5,"featured_media":8608,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9046"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=9046"}],"version-history":[{"count":1,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9046\/revisions"}],"predecessor-version":[{"id":9047,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9046\/revisions\/9047"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media\/8608"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=9046"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=9046"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=9046"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}