{"id":9022,"date":"2020-04-28T09:03:48","date_gmt":"2020-04-28T12:03:48","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=9022"},"modified":"2020-04-28T09:03:48","modified_gmt":"2020-04-28T12:03:48","slug":"na-pandemia-maiores-tribunais-poupam-remuneracoes-de-juizes-em-medida-de-reducao-de-custos","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2020\/04\/28\/na-pandemia-maiores-tribunais-poupam-remuneracoes-de-juizes-em-medida-de-reducao-de-custos\/","title":{"rendered":"Na pandemia, maiores tribunais poupam remunera\u00e7\u00f5es de ju\u00edzes em medida de redu\u00e7\u00e3o de custos"},"content":{"rendered":"\n<p>Os tr\u00eas maiores tribunais estaduais brasileiros pouparam as remunera\u00e7\u00f5es dos magistrados ao adotarem medidas de conten\u00e7\u00e3o de despesas durante a\u00a0<a href=\"https:\/\/www1.folha.uol.com.br\/cotidiano\/coronavirus\/\">pandemia do novo coronav\u00edrus<\/a>.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2019\/11\/tjsp-1024x683.jpg\" alt=\"\" class=\"wp-image-3627\" srcset=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2019\/11\/tjsp.jpg 1024w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2019\/11\/tjsp-300x200.jpg 300w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2019\/11\/tjsp-768x512.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>Reprodu\u00e7\u00e3o<\/figcaption><\/figure>\n\n\n\n<p>Em\u00a0<a href=\"https:\/\/www1.folha.uol.com.br\/folha-topicos\/judiciario-paulista\/\">S\u00e3o Paulo<\/a>, no Rio de Janeiro e em Minas Gerais ficaram de fora desses cortes os penduricalhos aos sal\u00e1rios do ju\u00edzes, como os aux\u00edlios, abonos e os pagamentos de retroativos. Foram suspensos outros benef\u00edcios, que j\u00e1 n\u00e3o t\u00eam sido usados com regularidade por causa da Covid-19, como passagens a\u00e9reas e di\u00e1rias.<\/p>\n\n\n\n<p>Houve Tribunais de Justi\u00e7a, por\u00e9m, que decidiram suspender despesas que costumam ter para turbinar a\u00a0<a href=\"https:\/\/www1.folha.uol.com.br\/poder\/2019\/11\/com-penduricalhos-desembargadores-do-tj-sp-recebem-r-56-mil-por-mes.shtml\">remunera\u00e7\u00e3o dos ju\u00edzes<\/a>, como os do Paran\u00e1, de Santa Catarina, da Bahia, de Sergipe e de Roraima.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.folha.uol.com.br\/\"><\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/www1.folha.uol.com.br\/poder\/2020\/04\/na-pandemia-maiores-tribunais-poupam-penduricalhos-de-juizes-em-plano-de-reducao-de-custos.shtml#\"><\/a><\/p>\n\n\n\n<p><a href=\"javascript:void(0);\"><\/a><\/p>\n\n\n\n<h3><\/h3>\n\n\n\n<p><a href=\"https:\/\/www1.folha.uol.com.br\/poder\/2020\/04\/na-pandemia-maiores-tribunais-poupam-penduricalhos-de-juizes-em-plano-de-reducao-de-custos.shtml#\"><\/a><a href=\"https:\/\/www1.folha.uol.com.br\/poder\/2020\/04\/na-pandemia-maiores-tribunais-poupam-penduricalhos-de-juizes-em-plano-de-reducao-de-custos.shtml#\"><\/a><\/p>\n\n\n\n<p>Al\u00e9m de n\u00e3o cortar penduricalhos, Minas Gerais e Rio de Janeiro prop\u00f5em uma redu\u00e7\u00e3o de gastos bem menor que S\u00e3o Paulo. Ao contr\u00e1rio do Judici\u00e1rio paulista, os dois tribunais nem sequer apresentaram um plano formal de contingenciamento, se restringindo a adotar algumas medidas de economia.<\/p>\n\n\n\n<p>Em parte, isso se explica porque, em rela\u00e7\u00e3o a S\u00e3o Paulo, esses dois tribunais t\u00eam maior autonomia sobre as despesas que fazem e dependem menos de repasses do Executivo.<\/p><div class=\"kcbie6a985901d99d5\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.kcbie6a985901d99d5 {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.kcbie6a985901d99d5 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.kcbie6a985901d99d5 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.kcbie6a985901d99d5 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.kcbie6a985901d99d5 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.kcbie6a985901d99d5 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"ldlbv6a985901d99bb\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.ldlbv6a985901d99bb {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.ldlbv6a985901d99bb {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.ldlbv6a985901d99bb {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.ldlbv6a985901d99bb {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.ldlbv6a985901d99bb {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.ldlbv6a985901d99bb {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>Levantamento&nbsp;<a href=\"https:\/\/www1.folha.uol.com.br\/poder\/2019\/11\/com-penduricalhos-desembargadores-do-tj-sp-recebem-r-56-mil-por-mes.shtml\">feito pela&nbsp;<strong>Folha<\/strong>&nbsp;em 2019<\/a>&nbsp;mostrava que MG era o tribunal que pagou a maior remunera\u00e7\u00e3o m\u00e9dia aos desembargadores \u2014somando sal\u00e1rio, retroativos e outros penduricalhos\u2014 nos sete primeiros meses do ano: cerca de R$ 70 mil mensais.<\/p>\n\n\n\n<p>Os retroativos s\u00e3o compostos principalmente de equipara\u00e7\u00f5es salariais ou, por exemplo, de perda de remunera\u00e7\u00e3o quando a moeda foi convertida para URV. Os valores s\u00e3o corrigidos pela infla\u00e7\u00e3o.<\/p>\n\n\n\n<p>Em rela\u00e7\u00e3o \u00e0 pandemia, o&nbsp;<a href=\"https:\/\/www1.folha.uol.com.br\/poder\/2019\/05\/presidente-do-tj-mg-prestou-favores-a-ex-governador-pimentel-diz-policia-federal.shtml\">Tribunal de Justi\u00e7a de Minas Gerais<\/a>&nbsp;afirma que adotou a\u00e7\u00f5es administrativas como corte de viagens, de pagamentos de di\u00e1rias e de a\u00e7\u00f5es b\u00e1sicas de manuten\u00e7\u00e3o, \u201cque redundar\u00e3o em despesas menores no per\u00edodo, em decorr\u00eancia do trabalho remoto, que j\u00e1 atinge 100% das unidades judici\u00e1rias, com plant\u00e3o presencial apenas onde \u00e9 indispens\u00e1vel\u201d.<\/p>\n\n\n\n<p>Ao ser questionado se havia um plano formal de contingenciamento, apontou que n\u00e3o depende de verbas do Executivo para bancar as suas despesas fora da folha de pagamento. Para isso, o tribunal usa um fundo especial, composto de taxas e dep\u00f3sitos judiciais.<\/p>\n\n\n\n<p>\u201cO TJ-MG recebe verbas do Tesouro (duod\u00e9cimos) apenas para a folha de pagamentos, que n\u00e3o sofre altera\u00e7\u00f5es com a pandemia, ou seja, os recursos devem ser repassados normalmente\u201d.<\/p>\n\n\n\n<p>O tribunal acrescenta que j\u00e1 repassou R$ 15 milh\u00f5es&nbsp;<a href=\"https:\/\/www1.folha.uol.com.br\/poder\/2020\/04\/juizes-destinam-dinheiro-de-multas-e-indenizacoes-para-o-combate-ao-coronavirus.shtml\">provenientes de penas financeiras para o combate ao coronav\u00edrus<\/a>&nbsp;e &#8220;decis\u00e3o judicial liberou para o Governo do Estado, para cobrir despesas com a pandemia, R$ 500 milh\u00f5es dos recursos que estavam retidos da Vale&#8221;.<\/p>\n\n\n\n<p>Tamb\u00e9m sem um plano de contingenciamento, o Tribunal de Justi\u00e7a do Rio de Janeiro diz que \u201ctem contingenciado todos os gastos que n\u00e3o sejam essenciais \u00e0 manuten\u00e7\u00e3o da atividade\u201d.<\/p>\n\n\n\n<p>\u201cO presidente do TJ-RJ, desembargador Claudio de Mello Tavares, determinou a suspens\u00e3o de todas as obras e servi\u00e7os que iriam ser licitados, economia de energia e \u00e1gua dos pr\u00e9dios onde n\u00e3o haja funcionamento de plant\u00e3o extraordin\u00e1rio\u201d, afirma nota da assessoria do TJ-RJ. Tamb\u00e9m foram suspensos concursos p\u00fablicos.<\/p>\n\n\n\n<p>Folha de S\u00e3o Paulo<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em S\u00e3o Paulo, no Rio de Janeiro e em Minas Gerais ficaram de fora desses cortes os penduricalhos aos sal\u00e1rios do ju\u00edzes, como os aux\u00edlios, abonos e os pagamentos de retroativos. <br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2020\/04\/28\/na-pandemia-maiores-tribunais-poupam-remuneracoes-de-juizes-em-medida-de-reducao-de-custos\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":5,"featured_media":3627,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9022"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=9022"}],"version-history":[{"count":1,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9022\/revisions"}],"predecessor-version":[{"id":9023,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9022\/revisions\/9023"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media\/3627"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=9022"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=9022"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=9022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}