{"id":8335,"date":"2020-04-06T14:03:28","date_gmt":"2020-04-06T17:03:28","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=8335"},"modified":"2020-04-06T13:05:48","modified_gmt":"2020-04-06T16:05:48","slug":"presidente-tem-certas-imunidades-diz-aras-apos-cobrancas-contra-pgr","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2020\/04\/06\/presidente-tem-certas-imunidades-diz-aras-apos-cobrancas-contra-pgr\/","title":{"rendered":"&#8220;Presidente tem certas imunidades&#8221;, diz Aras ap\u00f3s cobran\u00e7as contra PGR"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img loading=\"lazy\" width=\"1024\" height=\"492\" src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2019\/09\/aras-1024x492.jpeg\" alt=\"\" class=\"wp-image-1861\" srcset=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2019\/09\/aras-1024x492.jpeg 1024w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2019\/09\/aras-300x144.jpeg 300w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2019\/09\/aras-768x369.jpeg 768w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2019\/09\/aras.jpeg 1250w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>Reprodu\u00e7\u00e3o<\/figcaption><\/figure>\n\n\n\n<p>Pressionado a agir para enquadrar Jair Bolsonaro diante de suas pol\u00eamicas atitudes na condu\u00e7\u00e3o da crise do coronav\u00edrus, o procurador-geral da Rep\u00fablica, Augusto\u00a0Aras, afirmou que a institui\u00e7\u00e3o deve se afastar de disputas pol\u00edticas. Para o chefe do Minist\u00e9rio P\u00fablico Federal, o presidente tem &#8220;liberdade de express\u00e3o&#8221; e os Poderes devem se guiar pelo consenso social.<\/p>\n\n\n\n<p>&#8220;A Procuradoria-Geral da Rep\u00fablica n\u00e3o \u00e9 casa de solu\u00e7\u00e3o pol\u00edtica. \u00c9 casa da legalidade. Para cassar presidente, \u00e9 preciso ir ao Congresso&#8221;, disse&nbsp;Aras&nbsp;ao jornal&nbsp;<strong>O Estado de S. Paulo<\/strong>. &#8220;Os poderes Legislativo e Executivo, eleitos pelo povo, devem se guiar pelo consenso social resultante do amplo debate instalado em todos os seus segmentos. Diversamente, as duas magistraturas, especialmente o Minist\u00e9rio P\u00fablico, devem buscar sua legitima\u00e7\u00e3o no dever de fundamentar seus atos e decis\u00f5es na Constitui\u00e7\u00e3o e nas leis do Pa\u00eds&#8221;, argumentou.<\/p>\n\n\n\n<p>Aras&nbsp;arquivou, recentemente, pedido de subprocuradores para obrigar Bolsonaro a seguir recomenda\u00e7\u00f5es da Organiza\u00e7\u00e3o Mundial da Sa\u00fade (OMS) no combate \u00e0 pandemia. &#8220;\u00c9 preciso separar Estado e governo&#8221;, afirmou ele. &#8220;O Estado brasileiro est\u00e1 funcionando normalmente, com t\u00e9cnicos empenhados no combate \u00e0 covid-19. O governo, na figura do presidente, tem liberdade de express\u00e3o e goza de certas imunidades, assim como os parlamentares. Eventuais medidas que contrariem as orienta\u00e7\u00f5es t\u00e9cnicas poder\u00e3o ser pass\u00edveis de aprecia\u00e7\u00e3o judicial.&#8221;<\/p>\n\n\n\n<p>A falta de rea\u00e7\u00f5es mais enf\u00e1ticas por parte dos Poderes abriu espa\u00e7o para governadores como Jo\u00e3o Doria (PSDB) e Wilson Witzel (PSC) assumirem o papel de antagonistas do presidente.<\/p><div class=\"udyco6a57eb3c9e81f\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.udyco6a57eb3c9e81f {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.udyco6a57eb3c9e81f {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.udyco6a57eb3c9e81f {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.udyco6a57eb3c9e81f {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.udyco6a57eb3c9e81f {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.udyco6a57eb3c9e81f {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"lvcbf6a57eb3c9e80b\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.lvcbf6a57eb3c9e80b {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.lvcbf6a57eb3c9e80b {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.lvcbf6a57eb3c9e80b {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.lvcbf6a57eb3c9e80b {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.lvcbf6a57eb3c9e80b {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.lvcbf6a57eb3c9e80b {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>Doria chegou a pregar a desobedi\u00eancia aos insistentes apelos de Bolsonaro para a abertura do com\u00e9rcio. &#8220;N\u00e3o sigam as orienta\u00e7\u00f5es do presidente&#8221;, aconselhou o governador de S\u00e3o Paulo. Witzel, por sua vez, sugeriu que Bolsonaro seja julgado internacionalmente por &#8220;crime contra a humanidade&#8221;. Doria e Witzel sonham em disputar o Planalto, em 2022, quando o presidente planeja concorrer \u00e0 reelei\u00e7\u00e3o.<\/p>\n\n\n\n<p>Aliados de primeira hora, como o governador de Goi\u00e1s, Ronaldo Caiado (DEM), foram se desgarrando de Bolsonaro no primeiro m\u00eas da pandemia. Embora o caso mais not\u00f3rio seja o de Caiado, o governador do Acre, Gladson Cameli (Progressistas), tamb\u00e9m afirmou que os embates provocados pelo presidente s\u00e3o &#8220;desnecess\u00e1rios&#8221; e acabam por deix\u00e1-lo cada vez mais isolado.<\/p>\n\n\n\n<p>Pr\u00f3ximo de Bolsonaro, Cameli disse n\u00e3o saber quem est\u00e1 aconselhando o presidente. &#8220;Prefiro dizer que n\u00e3o entendo qual \u00e9 a estrat\u00e9gia&#8221;, resumiu o governador do Acre. &#8220;Quando eu falar com ele, vou dizer que ele est\u00e1 tirando autoridade dos ministros e dos governadores. Todos est\u00e3o em alinhamento. Por que s\u00f3 o presidente n\u00e3o est\u00e1? At\u00e9 Donald Trump (presidente dos EUA) est\u00e1 voltando atr\u00e1s, tomando outras medidas. Por que ele n\u00e3o est\u00e1 fazendo isso?&#8221;, questionou. As informa\u00e7\u00f5es s\u00e3o do jornal&nbsp;<strong>O Estado de S. Paulo.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para o chefe do Minist\u00e9rio P\u00fablico Federal, o presidente tem &#8220;liberdade de express\u00e3o&#8221; e os Poderes devem se guiar pelo consenso social.<br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2020\/04\/06\/presidente-tem-certas-imunidades-diz-aras-apos-cobrancas-contra-pgr\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":5,"featured_media":6838,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/8335"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=8335"}],"version-history":[{"count":1,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/8335\/revisions"}],"predecessor-version":[{"id":8336,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/8335\/revisions\/8336"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media\/6838"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=8335"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=8335"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=8335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}