{"id":8319,"date":"2020-04-06T09:33:08","date_gmt":"2020-04-06T12:33:08","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=8319"},"modified":"2020-04-06T08:15:17","modified_gmt":"2020-04-06T11:15:17","slug":"tj-reforma-sentenca-e-condena-acusados-de-fraudarem-licitacao-do-mprn","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2020\/04\/06\/tj-reforma-sentenca-e-condena-acusados-de-fraudarem-licitacao-do-mprn\/","title":{"rendered":"TJ reforma senten\u00e7a e condena acusados de fraudarem licita\u00e7\u00e3o do MPRN"},"content":{"rendered":"\n<p>A C\u00e2mara Criminal do Tribunal de Justi\u00e7a do RN atendeu ao pleito do Minist\u00e9rio P\u00fablico Estadual e reformou senten\u00e7a da 5\u00aa Vara Criminal de Natal que nos autos da A\u00e7\u00e3o Penal n\u00ba 0015053742009.8.20-0001 havia absolvido, por falta de provas, tr\u00eas pessoas acusadas de fraudar o processo licitat\u00f3rio do Preg\u00e3o Presencial n\u00ba 027\/2008 \u2013 PGJ. O \u00f3rg\u00e3o julgador decidiu estabelecer uma pena de dois anos de deten\u00e7\u00e3o e multa de 2% do valor do contrato licitado, item previsto no artigo 99, par\u00e1grafo 1\u00ba, da Lei 8.666\/93 aos r\u00e9us Frank Carlos Dantas C\u00e2ndido, Mariziane da C\u00e2mara Galv\u00e3o de Carvalho e Wagner Lima de Carvalho.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" width=\"730\" height=\"400\" src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2019\/09\/MPRN-730x400.jpg\" alt=\"\" class=\"wp-image-2122\" srcset=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2019\/09\/MPRN-730x400.jpg 730w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2019\/09\/MPRN-730x400-300x164.jpg 300w\" sizes=\"(max-width: 730px) 100vw, 730px\" \/><figcaption>Reprodu\u00e7\u00e3o<\/figcaption><\/figure>\n\n\n\n<p>De acordo com o relator da Apela\u00e7\u00e3o, desembargador Glauber R\u00eago, a autoria do crime est\u00e1 devidamente comprovada pelos interrogat\u00f3rios judiciais dos pr\u00f3prios acusados. A fraude consistia em efetivar a participa\u00e7\u00e3o da empresa Videof\u00f3tica no certame, para execu\u00e7\u00e3o do servi\u00e7o licitado e dela obteriam vantagens ou, como alternativa, a escolha da empresa Francisco Fl\u00e1vio da Silva Lima ME, que contrataria a concorrente para a execu\u00e7\u00e3o das atividades.<\/p>\n\n\n\n<p><strong>Combina\u00e7\u00e3o de pre\u00e7os<\/strong><\/p>\n\n\n\n<p>Segundo os autos, os acusados fraudaram, de forma consciente, o car\u00e1ter competitivo do preg\u00e3o (conforme confiss\u00e3o de todos eles), ajustando e combinando pre\u00e7os, \u00e0 revelia dos demais licitantes.<\/p><div class=\"xkqny6a57eb58e6348\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.xkqny6a57eb58e6348 {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.xkqny6a57eb58e6348 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.xkqny6a57eb58e6348 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.xkqny6a57eb58e6348 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.xkqny6a57eb58e6348 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.xkqny6a57eb58e6348 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"lrywo6a57eb58e6333\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.lrywo6a57eb58e6333 {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.lrywo6a57eb58e6333 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.lrywo6a57eb58e6333 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.lrywo6a57eb58e6333 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.lrywo6a57eb58e6333 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.lrywo6a57eb58e6333 {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>\u201cOra, os recorridos engendraram um acordo para que uma das empresas sa\u00edsse vencedora no certame (fraude ao car\u00e1ter competitivo) e referido acordo foi efetivamente levado a cabo por eles, na medida em que apresentaram as propostas ao \u00f3rg\u00e3o da administra\u00e7\u00e3o p\u00fablica e participaram de todas as etapas poss\u00edveis do certame, tudo conforme previamente concertado entre os envolvidos, n\u00e3o havendo, pois, que se falar em crime tentado\u201d, afirma o desembargador Glauber R\u00eago.<\/p>\n\n\n\n<p>O voto registra que as duas empresas concorrentes apresentaram propostas provenientes de uma mesma fonte, visto que at\u00e9 os erros das cl\u00e1usulas foram iguais, conforme os documentos levados ao processo, tendo os pr\u00f3prios acusados confessado terem agido em uma esp\u00e9cie de parceria.<\/p>\n\n\n\n<p>O relator destacou ainda que \u201ca fraude ao car\u00e1ter competitivo do certame (e sua nefasta consequ\u00eancia para o ente p\u00fablico licitante) tamb\u00e9m fica evidente quando se tem em mira o fato de que, caso n\u00e3o houvesse o pr\u00e9vio ajuste de pre\u00e7os pelos envolvidos (fraude), as propostas poderiam ser mais vantajosas para a administra\u00e7\u00e3o p\u00fablica (in casu, Procuradoria Geral de Justi\u00e7a)\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>De acordo com o relator da Apela\u00e7\u00e3o, desembargador Glauber R\u00eago, a autoria do crime est\u00e1 devidamente comprovada pelos interrogat\u00f3rios judiciais dos pr\u00f3prios acusados<br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2020\/04\/06\/tj-reforma-sentenca-e-condena-acusados-de-fraudarem-licitacao-do-mprn\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":5,"featured_media":2122,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/8319"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=8319"}],"version-history":[{"count":1,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/8319\/revisions"}],"predecessor-version":[{"id":8320,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/8319\/revisions\/8320"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media\/2122"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=8319"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=8319"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=8319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}