{"id":8054,"date":"2020-03-30T12:30:39","date_gmt":"2020-03-30T15:30:39","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=8054"},"modified":"2020-03-30T12:30:39","modified_gmt":"2020-03-30T15:30:39","slug":"correcao-esclarecimento-tribunal-de-justica-do-rio-grande-do-norte","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2020\/03\/30\/correcao-esclarecimento-tribunal-de-justica-do-rio-grande-do-norte\/","title":{"rendered":"CORRE\u00c7\u00c3O: Esclarecimento \u2013 Tribunal de Justi\u00e7a do Rio Grande do Norte"},"content":{"rendered":"\n<p><strong>CORRE\u00c7\u00c3O \u2013 Em rela\u00e7\u00e3o \u00e0 mat\u00e9ria: *Covid-19: Justi\u00e7a determina que 1467 presos no Estado sejam transferidos para regime domiciliar de imediato.<\/strong><\/p>\n\n\n\n<p>O Tribunal de Justi\u00e7a do Rio Grande do Norte esclarece que a informa\u00e7\u00e3o n\u00e3o procede. At\u00e9 o momento, prevalece decis\u00e3o monocr\u00e1tica do desembargador Saraiva Sobrinho, que em 19 de mar\u00e7o, negou Habeas Corpus Coletivo, impetrado pela Defensoria P\u00fablica do Estado. O \u00f3rg\u00e3o pedia que a Justi\u00e7a estadual autorizasse a transfer\u00eancia de presos por crimes praticados sem viol\u00eancia e grave amea\u00e7a, e tamb\u00e9m presos que estejam nos grupos de risco da COVID-19, para o regime domiciliar.<\/p>\n\n\n\n<p>Ap\u00f3s a decis\u00e3o inicial, do membro do Pleno do TJRN, a Defensoria recorreu e o desembargador mandou intimar o Minist\u00e9rio P\u00fablico para que o \u00f3rg\u00e3o apresente suas contrarraz\u00f5es. O agravo foi encaminhado para a aprecia\u00e7\u00e3o do MPRN, que ir\u00e1 apresentar suas contrarraz\u00f5es. Quando o processo retornar, Saraiva Sobrinho, levar\u00e1 o feito para sess\u00e3o virtual da C\u00e2mara Criminal do TJ potiguar.<\/p>\n\n\n\n<p><strong>A decis\u00e3o do dia 19 de mar\u00e7o, permanece em vigor at\u00e9 julgamento na C\u00e2mara Criminal.<\/strong><\/p><div class=\"nmkus6a572315c248f\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.nmkus6a572315c248f {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.nmkus6a572315c248f {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.nmkus6a572315c248f {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.nmkus6a572315c248f {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.nmkus6a572315c248f {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.nmkus6a572315c248f {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"tmtph6a572315c247b\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.tmtph6a572315c247b {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.tmtph6a572315c247b {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.tmtph6a572315c247b {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.tmtph6a572315c247b {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.tmtph6a572315c247b {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.tmtph6a572315c247b {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>A decis\u00e3o do desembargador Saraiva Sobrinho est\u00e1 em vigor. Esta observa a necessidade de se analisar cada caso de maneira individual e sua realidade pr\u00f3pria. Ao analisar o HC, o desembargador salientou que a situa\u00e7\u00e3o atual reclama uma prud\u00eancia conjunta dos Poderes constitu\u00eddos, tendo o Judici\u00e1rio, inclusive o potiguar, expedido recomenda\u00e7\u00f5es com o objetivo de combater a dissemina\u00e7\u00e3o do coronav\u00edrus, com \u201cconsider\u00e1veis\u201d diretrizes para proteger a sa\u00fade de magistrados, agentes p\u00fablicos e pessoas custodiadas.<\/p>\n\n\n\n<p>Destacou o magistrado que o Judici\u00e1rio vem contribuindo, de forma eficiente, harm\u00f4nica e cooperativa, com os demais Poderes do Estado, em meio a um iminente decreto de estado de calamidade oriundo do Poder Executivo Federal aprovado em 18 de mar\u00e7o. Entretanto, quanto ao HC Coletivo, entende que seu exame esbarra numa efetiva supress\u00e3o de inst\u00e2ncia e at\u00e9 na inviabilidade de aprecia\u00e7\u00e3o do seu pr\u00f3prio m\u00e9rito.<\/p>\n\n\n\n<p>Esclareceu Saraiva Sobrinho que, longe de desmerecer a situa\u00e7\u00e3o peculiar de superpopula\u00e7\u00e3o enclausurada, elemento fomentador de propaga\u00e7\u00e3o da atual mol\u00e9stia, entende que o estudo deve ser adstrito, num primeiro momento, ao Juiz da Execu\u00e7\u00e3o, de maneira individualizada (seja encarcerado provis\u00f3rio ou apenado), especialmente em rela\u00e7\u00e3o \u00e0queles alvos do grupo de risco, conforme recomendado pelos atos administrativos expedidos pelo poder p\u00fablico em somat\u00f3rio de esfor\u00e7os junto \u00e0s autoridades sanit\u00e1rias.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ESCLARECIMENTO DO TJRN<br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2020\/03\/30\/correcao-esclarecimento-tribunal-de-justica-do-rio-grande-do-norte\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":6,"featured_media":8055,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/8054"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=8054"}],"version-history":[{"count":2,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/8054\/revisions"}],"predecessor-version":[{"id":8057,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/8054\/revisions\/8057"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media\/8055"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=8054"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=8054"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=8054"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}