{"id":54432,"date":"2026-05-19T09:23:52","date_gmt":"2026-05-19T12:23:52","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=54432"},"modified":"2026-05-19T09:27:08","modified_gmt":"2026-05-19T12:27:08","slug":"aluno-agredido-em-escola-estadual-de-mossoro-recebera-indenizacao-por-danos-morais","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2026\/05\/19\/aluno-agredido-em-escola-estadual-de-mossoro-recebera-indenizacao-por-danos-morais\/","title":{"rendered":"Aluno agredido em escola estadual de Mossor\u00f3 receber\u00e1 indeniza\u00e7\u00e3o por danos morais"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1024\" height=\"613\" src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/05\/escola-1024x613.jpg\" alt=\"\" class=\"wp-image-54434\" srcset=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/05\/escola-1024x613.jpg 1024w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/05\/escola-300x179.jpg 300w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/05\/escola-768x459.jpg 768w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/05\/escola.jpg 1170w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>Foto: Tomaz Silva\/Ag\u00eancia Brasil<\/figcaption><\/figure>\n\n\n\n<p>Um aluno que sofreu agress\u00e3o dentro de uma escola estadual ser\u00e1 indenizado por danos morais ap\u00f3s senten\u00e7a do 2\u00ba Juizado Especial da Fazenda P\u00fablica de Mossor\u00f3. De acordo com o processo, a crian\u00e7a foi agredida por um homem nas depend\u00eancias da escola em mar\u00e7o de 2024. Imagens de c\u00e2meras de seguran\u00e7a confirmaram que houve contato f\u00edsico, incluindo pux\u00e3o de orelha, o que caracterizou a agress\u00e3o.<\/p>\n\n\n\n<p>Ao analisar o caso, a ju\u00edza Giulliana Silveira de Souza entendeu que ficou comprovada a pr\u00e1tica do ato il\u00edcito, sendo desnecess\u00e1ria a comprova\u00e7\u00e3o do dano, j\u00e1 que, em situa\u00e7\u00f5es como essa, ele \u00e9 presumido. A magistrada tamb\u00e9m reconheceu a responsabilidade do Estado, diante da omiss\u00e3o no dever de garantir a seguran\u00e7a do aluno dentro do ambiente escolar.<\/p>\n\n\n\n<p>\u201c<em>In casu<\/em>, a indeniza\u00e7\u00e3o por danos morais \u00e9 medida que se imp\u00f5e, visto que a parte autora teve sua integridade f\u00edsica violada no ambiente escolar, que tinha o dever de zelar pela integridade f\u00edsica daqueles que est\u00e3o sob cust\u00f3dia como os alunos da mencionada escola estadual, estando tais circunst\u00e2ncias tamb\u00e9m comprovadas pela c\u00e2mera de seguran\u00e7a\u201d, ressaltou.<\/p><div class=\"svwqv6a979826d7cb9\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.svwqv6a979826d7cb9 {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.svwqv6a979826d7cb9 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.svwqv6a979826d7cb9 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.svwqv6a979826d7cb9 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.svwqv6a979826d7cb9 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.svwqv6a979826d7cb9 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"eusim6a979826d7ca1\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.eusim6a979826d7ca1 {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.eusim6a979826d7ca1 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.eusim6a979826d7ca1 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.eusim6a979826d7ca1 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.eusim6a979826d7ca1 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.eusim6a979826d7ca1 {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>Com isso, e levando-se em considera\u00e7\u00e3o as peculiaridades do caso, a situa\u00e7\u00e3o econ\u00f4mica das partes, a extens\u00e3o do dano, o car\u00e1ter pedag\u00f3gico, e o princ\u00edpio de veda\u00e7\u00e3o a transforma\u00e7\u00e3o do dano em capta\u00e7\u00e3o de lucro, foi fixada indeniza\u00e7\u00e3o por danos morais, sendo R$ 3 mil a serem pagos pelo agressor e R$ 2 mil pelo Estado. Um pedido de indeniza\u00e7\u00e3o por danos materiais feito pelo autor foi negado por aus\u00eancia de comprova\u00e7\u00e3o.<\/p>\n\n\n\n<p><strong>Processo n\u00ba 0813944-75.2024.8.20.5106<\/strong><br><br><em>Fonte: TJRN<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A magistrada tamb\u00e9m reconheceu a responsabilidade do Estado, diante da omiss\u00e3o no dever de garantir a seguran\u00e7a do aluno dentro do ambiente escolar.<br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2026\/05\/19\/aluno-agredido-em-escola-estadual-de-mossoro-recebera-indenizacao-por-danos-morais\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/54432"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=54432"}],"version-history":[{"count":3,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/54432\/revisions"}],"predecessor-version":[{"id":54436,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/54432\/revisions\/54436"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=54432"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=54432"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=54432"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}