{"id":54257,"date":"2026-05-13T20:10:13","date_gmt":"2026-05-13T23:10:13","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=54257"},"modified":"2026-05-13T20:15:32","modified_gmt":"2026-05-13T23:15:32","slug":"ministro-flavio-dino-pede-providencias-sobre-controle-de-emendas-parlamentares","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2026\/05\/13\/ministro-flavio-dino-pede-providencias-sobre-controle-de-emendas-parlamentares\/","title":{"rendered":"Ministro Fl\u00e1vio Dino pede provid\u00eancias sobre controle de emendas parlamentares"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"800\" height=\"534\" src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/05\/Dino.jpg\" alt=\"\" class=\"wp-image-54259\" srcset=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/05\/Dino.jpg 800w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/05\/Dino-300x200.jpg 300w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/05\/Dino-768x513.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><figcaption>Foto: Antonio Augusto\/STF<\/figcaption><\/figure>\n\n\n\n<p>O ministro Fl\u00e1vio Dino, do Supremo Tribunal Federal, estabeleceu prazos para que \u00f3rg\u00e3os de controle e autoridades apresentem informa\u00e7\u00f5es sobre o monitoramento de emendas parlamentares. As determina\u00e7\u00f5es foram feitas na 2\u00aa feira (12.mai.2026), na ADPF (Argui\u00e7\u00e3o de Descumprimento de Preceito Fundamental) 854.<\/p>\n\n\n\n<p>Dino enviou of\u00edcios ao TSE (Tribunal Superior Eleitoral), ao TCU (Tribunal de Contas da Uni\u00e3o), ao Senado Federal, \u00e0 Procuradoria-Geral do Estado de S\u00e3o Paulo, \u00e0 CGU (Controladoria-Geral da Uni\u00e3o) e \u00e0s assembleias legislativas estaduais. As medidas atendem a pedidos das organiza\u00e7\u00f5es Associa\u00e7\u00e3o Contas Abertas, Transpar\u00eancia Brasil e Transpar\u00eancia Internacional-Brasil, que atuam no processo como amici curiae (amigos da Corte).  <\/p>\n\n\n\n<p>Os solicitantes apontaram poss\u00edveis vulnerabilidades na execu\u00e7\u00e3o de emendas parlamentares, especialmente durante o per\u00edodo eleitoral. Segundo as organiza\u00e7\u00f5es, existe risco de rela\u00e7\u00e3o entre destinat\u00e1rios de emendas e fornecedores de campanhas eleitorais.<\/p>\n\n\n\n<p>O ministro determinou que o TSE e a Procuradoria-Geral Eleitoral avaliem medidas diante desse cen\u00e1rio. J\u00e1 a Procuradoria-Geral do Estado de S\u00e3o Paulo dever\u00e1 esclarecer uma poss\u00edvel permuta de emendas entre parlamentares federais paulistas e o governo estadual.<\/p>\n\n\n\n<p>Segundo as organiza\u00e7\u00f5es, deputados e senadores de S\u00e3o Paulo teriam destinado R$ 316 milh\u00f5es em emendas de bancada para programas selecionados pelo governo estadual. Em contrapartida, cada parlamentar poderia indicar R$ 10 milh\u00f5es no Or\u00e7amento paulista.<\/p><div class=\"qgblg6a97b007cb296\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.qgblg6a97b007cb296 {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.qgblg6a97b007cb296 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.qgblg6a97b007cb296 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.qgblg6a97b007cb296 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.qgblg6a97b007cb296 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.qgblg6a97b007cb296 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"wnrbs6a97b007cb277\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.wnrbs6a97b007cb277 {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.wnrbs6a97b007cb277 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.wnrbs6a97b007cb277 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.wnrbs6a97b007cb277 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.wnrbs6a97b007cb277 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.wnrbs6a97b007cb277 {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>Os grupos afirmaram que o poss\u00edvel acordo pode representar tentativa de burlar a proibi\u00e7\u00e3o de individualiza\u00e7\u00e3o e rateio das emendas de bancada. Tamb\u00e9m solicitaram esclarecimentos sobre a aplica\u00e7\u00e3o das regras de nepotismo na destina\u00e7\u00e3o de emendas por suplentes de senadores, tema sobre o qual o Senado dever\u00e1 prestar informa\u00e7\u00f5es.<\/p>\n\n\n\n<p>O TCU ter\u00e1 cinco dias \u00fateis para informar as condi\u00e7\u00f5es de funcionamento do painel de acompanhamento da execu\u00e7\u00e3o de emendas parlamentares, incluindo eventuais limita\u00e7\u00f5es de acesso p\u00fablico ao sistema.<\/p>\n\n\n\n<p>A CGU dever\u00e1 responder em at\u00e9 10 dias \u00fateis sobre sua capacidade operacional para realizar auditorias relacionadas ao cumprimento das determina\u00e7\u00f5es da ADPF 854. Peti\u00e7\u00e3o apresentada no processo aponta poss\u00edvel insufici\u00eancia de estrutura e necessidade de reestrutura\u00e7\u00e3o do quadro de pessoal do \u00f3rg\u00e3o.<\/p>\n\n\n\n<p>As assembleias legislativas estaduais e a C\u00e2mara Legislativa do Distrito Federal ter\u00e3o 30 dias corridos para comprovar a adapta\u00e7\u00e3o de seus processos or\u00e7ament\u00e1rios ao modelo federal. As mudan\u00e7as dever\u00e3o seguir diretrizes fixadas pelo STF, pela Lei Complementar 210\/2024 e pela Resolu\u00e7\u00e3o 001\/2006 do Congresso Nacional.<\/p>\n\n\n\n<p>Em mar\u00e7o, Dino j\u00e1 havia determinado que os Legislativos estaduais adequassem seus procedimentos \u00e0s regras federais de transpar\u00eancia e rastreabilidade das emendas parlamentares.<br><em><br>Fonte: Poder360<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>As assembleias legislativas estaduais e a C\u00e2mara Legislativa do Distrito Federal ter\u00e3o 30 dias corridos para comprovar a adapta\u00e7\u00e3o de seus processos or\u00e7ament\u00e1rios ao modelo federal.<br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2026\/05\/13\/ministro-flavio-dino-pede-providencias-sobre-controle-de-emendas-parlamentares\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/54257"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=54257"}],"version-history":[{"count":3,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/54257\/revisions"}],"predecessor-version":[{"id":54261,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/54257\/revisions\/54261"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=54257"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=54257"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=54257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}