{"id":54201,"date":"2026-05-12T18:22:13","date_gmt":"2026-05-12T21:22:13","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=54201"},"modified":"2026-05-12T18:23:45","modified_gmt":"2026-05-12T21:23:45","slug":"comissao-da-camara-aprova-projeto-de-lei-que-autoriza-uso-do-fgts-para-comprar-arma-de-fogo","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2026\/05\/12\/comissao-da-camara-aprova-projeto-de-lei-que-autoriza-uso-do-fgts-para-comprar-arma-de-fogo\/","title":{"rendered":"Comiss\u00e3o da C\u00e2mara aprova projeto de lei que autoriza uso do FGTS para comprar arma de fogo"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"860\" height=\"570\" src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/05\/arma.jpg\" alt=\"\" class=\"wp-image-54203\" srcset=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/05\/arma.jpg 860w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/05\/arma-300x199.jpg 300w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/05\/arma-768x509.jpg 768w\" sizes=\"(max-width: 860px) 100vw, 860px\" \/><figcaption>Foto: Marcelo Camargo\/Ag\u00eancia Brasil<\/figcaption><\/figure>\n\n\n\n<p>A Comiss\u00e3o de Seguran\u00e7a P\u00fablica da C\u00e2mara aprovou nesta ter\u00e7a-feira (12) um projeto que autoriza o uso do Fundo de Garantia do Tempo de Servi\u00e7os (FGTS) para comprar armas de fogo.<\/p>\n\n\n\n<p>O projeto foi aprovado em cerca de um minuto, sem discuss\u00e3o dos parlamentares.<\/p>\n\n\n\n<p>A proposta agora seguir\u00e1 para as comiss\u00f5es de Finan\u00e7as e Tributa\u00e7\u00e3o, de Trabalho e Constitui\u00e7\u00e3o e Justi\u00e7a. Como tramita em regime conclusivo pelos colegiados, o projeto pode ir direto ao Senado, sem passar pelo plen\u00e1rio, caso n\u00e3o haja recurso.<\/p>\n\n\n\n<p>O texto \u00e9 de autoria do deputado Marcos Pollon (PL-MS) e foi relatado na comiss\u00e3o pelo deputado Paulo Bilynskyj (PL-SP), que se posicionou favor\u00e1vel \u00e0 proposta.<\/p>\n\n\n\n<p>O valor do saque dever\u00e1 ser igual ao pre\u00e7o da arma, da cota anual de muni\u00e7\u00f5es correspondentes \u00e0 arma adquirida e acess\u00f3rios essenciais \u00e0 sua guarda segura do armamento.<\/p>\n\n\n\n<p>Segundo a proposta, o saque poder\u00e1 ser feito todos os anos no dia do anivers\u00e1rio do trabalhador ou no dia \u00fatil subsequente.<\/p><div class=\"rlonx6a97b0017ea0c\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.rlonx6a97b0017ea0c {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.rlonx6a97b0017ea0c {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.rlonx6a97b0017ea0c {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.rlonx6a97b0017ea0c {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.rlonx6a97b0017ea0c {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.rlonx6a97b0017ea0c {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"wljor6a97b0017e9f6\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.wljor6a97b0017e9f6 {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.wljor6a97b0017e9f6 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.wljor6a97b0017e9f6 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.wljor6a97b0017e9f6 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.wljor6a97b0017e9f6 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.wljor6a97b0017e9f6 {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>Para sacar o dinheiro, o trabalhador precisar\u00e1 apresentar uma autoriza\u00e7\u00e3o v\u00e1lida para compra da arma e comprovante de regularidade nos sistemas de controle da Pol\u00edcia Federal ou do Ex\u00e9rcito.<\/p>\n\n\n\n<p>A proposta n\u00e3o amplia as regras do saque-anivers\u00e1rio, mas cria uma mobilidade de saque que usa a data do anivers\u00e1rio do trabalhador como refer\u00eancia para a nova lei.<\/p>\n\n\n\n<p>A proposta tamb\u00e9m estabelece que o trabalhador precisar\u00e1 cumprir todas as exig\u00eancias previstas na legisla\u00e7\u00e3o atual, como comprova\u00e7\u00e3o de capacidade t\u00e9cnica e psicol\u00f3gica, al\u00e9m da aus\u00eancia de antecedentes criminais.<\/p>\n\n\n\n<p>O autor do projeto argumenta que o alto custo para aquisi\u00e7\u00e3o de armas legalizadas dificulta o acesso da popula\u00e7\u00e3o de baixa renda. O FGTS foi criado para proteger o trabalhador em situa\u00e7\u00f5es espec\u00edficas, como demiss\u00e3o sem justa causa, aposentadoria, doen\u00e7as graves e compra da casa pr\u00f3pria.<\/p>\n\n\n\n<p><em>Fonte: g1<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O autor do projeto argumenta que o alto custo para aquisi\u00e7\u00e3o de armas legalizadas dificulta o acesso da popula\u00e7\u00e3o de baixa renda. <br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2026\/05\/12\/comissao-da-camara-aprova-projeto-de-lei-que-autoriza-uso-do-fgts-para-comprar-arma-de-fogo\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/54201"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=54201"}],"version-history":[{"count":3,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/54201\/revisions"}],"predecessor-version":[{"id":54205,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/54201\/revisions\/54205"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=54201"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=54201"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=54201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}