{"id":54199,"date":"2026-05-12T09:51:56","date_gmt":"2026-05-12T12:51:56","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=54199"},"modified":"2026-05-12T09:51:56","modified_gmt":"2026-05-12T12:51:56","slug":"parelhas-indenizara-em-r-400-mil-paciente-que-perdeu-o-globo-ocular-apos-mutirao-de-catarata","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2026\/05\/12\/parelhas-indenizara-em-r-400-mil-paciente-que-perdeu-o-globo-ocular-apos-mutirao-de-catarata\/","title":{"rendered":"Parelhas indenizar\u00e1 em R$ 400 mil paciente que perdeu o globo ocular ap\u00f3s mutir\u00e3o de catarata"},"content":{"rendered":"\n<p>O Munic\u00edpio de Parelhas ao pagamento de R$ 400 mil por danos morais e est\u00e9ticos a uma mulher que perdeu o globo ocular ap\u00f3s contrair uma infec\u00e7\u00e3o bacteriana durante o mutir\u00e3o de catarata realizado na cidade em 2024. A senten\u00e7a foi proferida pelo juiz Wilson Neves de Medeiros J\u00fanior, Vara \u00danica da Comarca de Parelhas, que reconheceu a gravidade das sequelas sofridas pela v\u00edtima.<\/p>\n\n\n\n<p>Conforme narrado, entre os dias 27 e 28 de setembro de 2024, foi realizado na Maternidade Dr. Graciliano Lord\u00e3o, localizada na cidade de Parelhas, o mutir\u00e3o de cirurgias de catarata financiado pelo ente municipal, por meio da Secretaria Municipal de Sa\u00fade. Assegura que dentre as 48 pessoas que foram submetidas ao referido procedimento cir\u00fargico, 15 apresentaram endoftalmite (infec\u00e7\u00e3o ocular grave causada por bact\u00e9ria), sendo uma das v\u00edtimas a autora.<\/p>\n\n\n\n<p>Em decorr\u00eancia da referida infec\u00e7\u00e3o, necessitou ser encaminhada ao Hospital Universit\u00e1rio Onofre Lopes (HUOL) em Natal, onde foi retirado seu globo ocular. Diante disso, a paciente requereu a condena\u00e7\u00e3o do Munic\u00edpio de Parelhas ao pagamento de R$ 400 mil a t\u00edtulo de indeniza\u00e7\u00e3o por danos morais e est\u00e9ticos. O ente municipal se defendeu requerendo a den\u00fancia \u00e0 empresa de oftalmologia respons\u00e1vel pelo procedimento e \u00e0 Maternidade Dr. Graciliano Lord\u00e3o. No m\u00e9rito, sustenta inexistir ilegalidade por sua parte.<\/p>\n\n\n\n<p>Analisando o caso, o magistrado embasou-se na Constitui\u00e7\u00e3o Federal e no C\u00f3digo de Processo Civil. De acordo com o entendimento estabelecido, as pessoas jur\u00eddicas de direito p\u00fablico e as de direito privado prestadoras de servi\u00e7os p\u00fablicos responder\u00e3o pelos danos que seus agentes, nessa qualidade, causarem a terceiros, assegurado o direito de regresso contra o respons\u00e1vel nos casos de dolo ou culpa.<\/p><div class=\"txoqj6a97af464948e\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.txoqj6a97af464948e {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.txoqj6a97af464948e {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.txoqj6a97af464948e {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.txoqj6a97af464948e {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.txoqj6a97af464948e {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.txoqj6a97af464948e {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"laifl6a97af4649473\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.laifl6a97af4649473 {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.laifl6a97af4649473 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.laifl6a97af4649473 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.laifl6a97af4649473 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.laifl6a97af4649473 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.laifl6a97af4649473 {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>\u201c\u00c9 indiscut\u00edvel que a autora, logo ap\u00f3s a cirurgia, passou a sentir v\u00e1rios sintomas graves, e conforme documenta\u00e7\u00e3o m\u00e9dica que acompanha, foi necess\u00e1ria a realiza\u00e7\u00e3o de consultas, interna\u00e7\u00e3o e realiza\u00e7\u00e3o de cirurgia em car\u00e1ter de urg\u00eancia, a qual precisou proceder com a retirada de globo ocular. Diante dos elementos reunidos, vislumbro que o dano sofrido pela v\u00edtima possui nexo de causalidade com a conduta negligente do r\u00e9u (Munic\u00edpio), que n\u00e3o fiscalizou adequadamente o fornecimento do servi\u00e7o m\u00e9dico prestado no \u00e2mbito de suas atribui\u00e7\u00f5es. A culpa \u00e9 grave, considerando que n\u00e3o se trata de um fato isolado, mas sim que afetou v\u00e1rias outras pessoas\u201d, evidenciou.<\/p>\n\n\n\n<p>Diante do ocorrido, o juiz imp\u00f4s a responsabiliza\u00e7\u00e3o ao r\u00e9u por danos morais, em virtude dos danos causados \u00e0 esfera psicol\u00f3gica da parte autora, a qual chegou a relatar que est\u00e1 sofrendo com uma ansiedade grande. Por fim, destacou que \u201ctamb\u00e9m restou comprovada a ocorr\u00eancia de danos est\u00e9ticos, uma vez que a perda do globo ocular \u00e9 vis\u00edvel pelas fotografias anexadas aos autos, nas quais \u00e9 poss\u00edvel observar claramente a mudan\u00e7a abrupta na apar\u00eancia do paciente ap\u00f3s a retirada do globo ocular\u201d.<\/p>\n\n\n\n<p><em>Fonte: TJRN<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A senten\u00e7a foi proferida pelo juiz Wilson Neves de Medeiros J\u00fanior, Vara \u00danica da Comarca de Parelhas, que reconheceu a gravidade das sequelas sofridas pela v\u00edtima.<br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2026\/05\/12\/parelhas-indenizara-em-r-400-mil-paciente-que-perdeu-o-globo-ocular-apos-mutirao-de-catarata\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/54199"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=54199"}],"version-history":[{"count":1,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/54199\/revisions"}],"predecessor-version":[{"id":54200,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/54199\/revisions\/54200"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=54199"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=54199"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=54199"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}