{"id":54017,"date":"2026-05-05T16:55:16","date_gmt":"2026-05-05T19:55:16","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=54017"},"modified":"2026-05-05T16:57:47","modified_gmt":"2026-05-05T19:57:47","slug":"mprn-recomenda-anulacao-de-eleicao-antecipada-na-camara-de-nisia-floresta","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2026\/05\/05\/mprn-recomenda-anulacao-de-eleicao-antecipada-na-camara-de-nisia-floresta\/","title":{"rendered":"MPRN recomenda anula\u00e7\u00e3o de elei\u00e7\u00e3o antecipada na C\u00e2mara de N\u00edsia Floresta"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"950\" height=\"622\" src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/05\/Camara_Nisia.jpg\" alt=\"\" class=\"wp-image-54019\" srcset=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/05\/Camara_Nisia.jpg 950w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/05\/Camara_Nisia-300x196.jpg 300w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/05\/Camara_Nisia-768x503.jpg 768w\" sizes=\"(max-width: 950px) 100vw, 950px\" \/><figcaption>Foto: Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n\n\n\n<p>O Minist\u00e9rio P\u00fablico do Rio Grande do Norte, por meio da 1\u00aa Promotoria de Justi\u00e7a de N\u00edsia Floresta, recomendou que a C\u00e2mara Municipal anule a elei\u00e7\u00e3o da Mesa Diretora para o per\u00edodo de 2027 a 2028. A vota\u00e7\u00e3o sob questionamento ocorreu no dia 29 de abril de 2025 e resultou na recondu\u00e7\u00e3o do atual presidente da casa legislativa.<\/p>\n\n\n\n<p>A recomenda\u00e7\u00e3o baseia-se em decis\u00f5es do Supremo Tribunal Federal que estabelecem que a elei\u00e7\u00e3o para o segundo bi\u00eanio de uma legislatura deve respeitar o princ\u00edpio da contemporaneidade. De acordo com esse entendimento, a escolha dos integrantes da Mesa Diretora s\u00f3 pode ser realizada a partir de outubro do ano que antecede o in\u00edcio do novo mandato.<\/p>\n\n\n\n<p>A Promotoria de Justi\u00e7a apurou que a elei\u00e7\u00e3o realizada em abril de 2025 foi feita de forma antecipada. A justificativa apresentada pela presid\u00eancia da C\u00e2mara sobre a falta de um prazo espec\u00edfico no regimento interno foi considerada improcedente por contrariar as normas constitucionais e a jurisprud\u00eancia da Suprema Corte.<\/p><div class=\"hcxye6a97c51f63345\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.hcxye6a97c51f63345 {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.hcxye6a97c51f63345 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.hcxye6a97c51f63345 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.hcxye6a97c51f63345 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.hcxye6a97c51f63345 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.hcxye6a97c51f63345 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"noarb6a97c51f63332\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.noarb6a97c51f63332 {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.noarb6a97c51f63332 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.noarb6a97c51f63332 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.noarb6a97c51f63332 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.noarb6a97c51f63332 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.noarb6a97c51f63332 {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>O documento assinado pela Promotora de Justi\u00e7a determina que o presidente da C\u00e2mara adote as medidas necess\u00e1rias para anular o pleito em um prazo de dez dias \u00fateis. Al\u00e9m da anula\u00e7\u00e3o, o MPRN orienta que nenhuma nova elei\u00e7\u00e3o para o bi\u00eanio 2027\/2028 seja convocada antes do m\u00eas de outubro deste ano.<\/p>\n\n\n\n<p>O descumprimento das orienta\u00e7\u00f5es contidas na recomenda\u00e7\u00e3o poder\u00e1 levar o MPRN a tomar medidas judiciais, como a abertura de uma A\u00e7\u00e3o Civil P\u00fablica. A C\u00e2mara Municipal deve informar se vai acatar o pedido e enviar documentos que comprovem a anula\u00e7\u00e3o formal da elei\u00e7\u00e3o dentro do prazo estabelecido.<br><br><em>Fonte: MPRN<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A vota\u00e7\u00e3o sob questionamento ocorreu no dia 29 de abril de 2025 e resultou na recondu\u00e7\u00e3o do atual presidente da casa legislativa.<br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2026\/05\/05\/mprn-recomenda-anulacao-de-eleicao-antecipada-na-camara-de-nisia-floresta\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/54017"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=54017"}],"version-history":[{"count":2,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/54017\/revisions"}],"predecessor-version":[{"id":54021,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/54017\/revisions\/54021"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=54017"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=54017"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=54017"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}