{"id":53946,"date":"2026-05-03T11:35:27","date_gmt":"2026-05-03T14:35:27","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=53946"},"modified":"2026-05-03T11:36:52","modified_gmt":"2026-05-03T14:36:52","slug":"stf-analisara-caso-a-caso-aplicacao-da-dosimetria-a-condenados-do-8-de-janeiro","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2026\/05\/03\/stf-analisara-caso-a-caso-aplicacao-da-dosimetria-a-condenados-do-8-de-janeiro\/","title":{"rendered":"STF analisar\u00e1 caso a caso aplica\u00e7\u00e3o da dosimetria a condenados do 8 de Janeiro"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"800\" height=\"534\" src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/05\/STF.jpg\" alt=\"\" class=\"wp-image-53949\" srcset=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/05\/STF.jpg 800w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/05\/STF-300x200.jpg 300w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/05\/STF-768x513.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><figcaption>Foto: Antonio Augusto\/STF<\/figcaption><\/figure>\n\n\n\n<p>O STF ainda decidir\u00e1 sobre a pena de Jair Bolsonaro mesmo ap\u00f3s a derrubada do veto de Lula ao PL da Dosimetria pelo Congresso. Condenados pelo 8 de Janeiro e por tentativa de golpe de Estado ter\u00e3o de acionar a Suprema Corte para solicitar o benef\u00edcio. Cada caso ser\u00e1 analisado individualmente.<\/p>\n\n\n\n<p>De acordo com o texo aprovado, a pena de Bolsonaro poder\u00e1 ser reduzida de 27 anos e 3 meses de pris\u00e3o para 3 anos e 3 meses. O presidente da C\u00e2mara, deputado Hugo Motta (Republicanos), j\u00e1 se manifestou sobre a prerrogativa do Supremo. De acordo com o parlamentar, os condenados n\u00e3o ser\u00e3o beneficiados automaticamente pela Dosimetria. \u201cO STF decidir\u00e1 sobre isso\u201d, disse Motta.<\/p><div class=\"bsrse6a97c54e49775\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.bsrse6a97c54e49775 {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.bsrse6a97c54e49775 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.bsrse6a97c54e49775 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.bsrse6a97c54e49775 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.bsrse6a97c54e49775 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.bsrse6a97c54e49775 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"rgacf6a97c54e49761\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.rgacf6a97c54e49761 {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.rgacf6a97c54e49761 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.rgacf6a97c54e49761 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.rgacf6a97c54e49761 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.rgacf6a97c54e49761 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.rgacf6a97c54e49761 {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>O veto de Lula ao PL da Dosimetria foi derrubado nesta quinta-feira (30\/4), em sess\u00e3o conjunta do Congresso Nacional. Na C\u00e2mara, o placar foi de 318 votos a favor da derrubada do veto, 144 votos contr\u00e1rios e 5 absten\u00e7\u00f5es. No Senado, foram 49 favor\u00e1veis \u00e0 derrubada e 24 contr\u00e1rios.<\/p>\n\n\n\n<p>Na sess\u00e3o conjunta desta quinta-feira, Alcolumbre decidiu que ficam prejudicados dispositivos vetados no PL da Dosimetria que fragilizariam as regras de progress\u00e3o de regime para outros crimes fora dos cometidos no \u00e2mbito do 8 de Janeiro, o que facilitou a tramita\u00e7\u00e3o do texto.<br><br><em>Fonte: Metr\u00f3poles<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>De acordo com o presidente da C\u00e2mara, deputado Hugo Motta (Republicanos), os condenados n\u00e3o ser\u00e3o beneficiados automaticamente pela Dosimetria.<br \/>\n<br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2026\/05\/03\/stf-analisara-caso-a-caso-aplicacao-da-dosimetria-a-condenados-do-8-de-janeiro\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/53946"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=53946"}],"version-history":[{"count":2,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/53946\/revisions"}],"predecessor-version":[{"id":53950,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/53946\/revisions\/53950"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=53946"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=53946"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=53946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}