{"id":53527,"date":"2026-04-23T09:32:34","date_gmt":"2026-04-23T12:32:34","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=53527"},"modified":"2026-04-23T09:34:41","modified_gmt":"2026-04-23T12:34:41","slug":"alha-na-seguranca-de-dados-em-golpe-do-falso-advogado-resulta-em-indenizacao-de-r-3-mil","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2026\/04\/23\/alha-na-seguranca-de-dados-em-golpe-do-falso-advogado-resulta-em-indenizacao-de-r-3-mil\/","title":{"rendered":"Falha na seguran\u00e7a de dados em golpe do \u201cfalso advogado\u201d resulta em indeniza\u00e7\u00e3o de R$ 3 mil"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"750\" height=\"375\" src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/04\/Whatsapp-750x375-1.jpg\" alt=\"\" class=\"wp-image-53531\" srcset=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/04\/Whatsapp-750x375-1.jpg 750w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/04\/Whatsapp-750x375-1-300x150.jpg 300w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><figcaption>Foto: Reprodu\u00e7\u00e3o<\/figcaption><\/figure>\n\n\n\n<p>O 5\u00b0 Juizado Especial C\u00edvel e Criminal da Comarca de Mossor\u00f3 condenou uma plataforma de rede social ap\u00f3s um advogado ter a sua imagem e dados pessoais utilizados indevidamente na pr\u00e1tica do golpe do \u201cfalso advogado\u201d, realizado por meio de aplicativo de mensagens. Em raz\u00e3o do ocorrido, o juiz Michel Mascarenhas Silva determinou que a empresa indenize a v\u00edtima em R$ 3 mil por danos morais, e efetue o bloqueio definitivo dos n\u00fameros telef\u00f4nicos usados na fraude, no prazo de 15 dias \u00fateis.<\/p>\n\n\n\n<p>Conforme narrado, a v\u00edtima, um advogado, teve sua imagem e informa\u00e7\u00f5es pessoais utilizadas de forma fraudulenta por terceiros, os quais criaram contas falsas no aplicativo de mensagem, por meio de tr\u00eas n\u00fameros de telefone, com o intuito de enganar clientes e outras pessoas, simulando tratar-se de um advogado. Dessa forma, as fraudes tinham o objetivo de ludibriar principalmente os clientes do autor, solicitando dep\u00f3sitos sob falsa justificativa de custas judiciais, taxas e libera\u00e7\u00f5es processuais.<\/p>\n\n\n\n<p>Assim que soube do ocorrido, a v\u00edtima, imediatamente, buscou os meios administrativos ao seu alcance, denunciando a irregularidade \u00e0 plataforma respons\u00e1vel e solicitando a exclus\u00e3o da conta fraudulenta e o bloqueio do referido n\u00famero.<br><br>Entretanto, mesmo ap\u00f3s v\u00e1rios dias de comunica\u00e7\u00e3o, a plataforma permaneceu inerte, permitindo a continuidade da atua\u00e7\u00e3o dos estelionat\u00e1rios. Em raz\u00e3o do ocorrido, requereu a remo\u00e7\u00e3o imediata da conta fraudulenta que utilizava a imagem e os dados do autor, al\u00e9m do bloqueio definitivo dos n\u00fameros telef\u00f4nicos e indeniza\u00e7\u00e3o por danos morais.<\/p>\n\n\n\n<p>De acordo com a an\u00e1lise do caso, a partir das provas juntadas aos autos, o magistrado observou que o autor teve a sua imagem e nomes usados indevidamente por terceiros. \u201cA falha na presta\u00e7\u00e3o de servi\u00e7o se substancia na falha de seguran\u00e7a dos sistemas da plataforma r\u00e9, o que teria viabilizado a a\u00e7\u00e3o de fraudadores, os quais invadiram o perfil de rede social da parte autora, e utilizaram a sua imagem na aplica\u00e7\u00e3o de golpes\u201d, esclareceu.<\/p><div class=\"svkwf6a97eda392345\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.svkwf6a97eda392345 {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.svkwf6a97eda392345 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.svkwf6a97eda392345 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.svkwf6a97eda392345 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.svkwf6a97eda392345 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.svkwf6a97eda392345 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"wmioh6a97eda392330\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.wmioh6a97eda392330 {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.wmioh6a97eda392330 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.wmioh6a97eda392330 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.wmioh6a97eda392330 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.wmioh6a97eda392330 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.wmioh6a97eda392330 {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>Al\u00e9m do mais, o magistrado embasou-se no artigo 14 do C\u00f3digo de Defesa do Consumidor, que trata da responsabilidade dos fornecedores por v\u00edcios de qualidade do servi\u00e7o. De acordo com tal legisla\u00e7\u00e3o, o fornecedor de servi\u00e7os responde, independentemente da exist\u00eancia de culpa, pela repara\u00e7\u00e3o dos danos causados aos consumidores por defeitos relativos \u00e0 presta\u00e7\u00e3o dos servi\u00e7os, bem como por informa\u00e7\u00f5es insuficientes ou inadequadas sobre sua frui\u00e7\u00e3o e riscos. Em rela\u00e7\u00e3o a indeniza\u00e7\u00e3o por danos morais, o juiz verificou a conduta abusiva da plataforma r\u00e9 no fornecimento do servi\u00e7o.<\/p>\n\n\n\n<p>\u201cAs circunst\u00e2ncias apresentadas, com bastante clareza, demonstram a efetiva exist\u00eancia do dano moral suportado pela parte autora, uma vez que o advogado teve a sua imagem utilizada por terceiros, com o objetivo de aplicar golpes. Ademais, deve-se considerar que esses fraudadores tiveram acesso a dados absolutamente privados. Ambas as circunst\u00e2ncias s\u00e3o aptas a lesar o patrim\u00f4nio extraf\u00edsico da v\u00edtima, gerando efetiva viola\u00e7\u00e3o moral que, em muito, ultrapassa a normalidade das rela\u00e7\u00f5es de consumo defeituosas\u201d, salientou.<\/p>\n\n\n\n<p><strong>Processo n\u00ba 0824995-49.2025.8.20.5106<\/strong><br><br><em>Fonte: TJRN<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A v\u00edtima, um advogado, teve sua imagem e informa\u00e7\u00f5es pessoais utilizadas de forma fraudulenta por terceiros, os quais criaram contas falsas no aplicativo de mensagem.<br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2026\/04\/23\/alha-na-seguranca-de-dados-em-golpe-do-falso-advogado-resulta-em-indenizacao-de-r-3-mil\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/53527"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=53527"}],"version-history":[{"count":3,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/53527\/revisions"}],"predecessor-version":[{"id":53532,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/53527\/revisions\/53532"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=53527"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=53527"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=53527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}