{"id":53435,"date":"2026-04-20T08:42:15","date_gmt":"2026-04-20T11:42:15","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=53435"},"modified":"2026-04-20T08:45:51","modified_gmt":"2026-04-20T11:45:51","slug":"plano-pode-negar-custeio-de-medicamento-domiciliar-fora-do-rol-da-ans","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2026\/04\/20\/plano-pode-negar-custeio-de-medicamento-domiciliar-fora-do-rol-da-ans\/","title":{"rendered":"Justi\u00e7a decide que plano pode negar custeio de medicamento domiciliar fora do rol da ANS"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1024\" height=\"613\" src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/04\/injecao-1024x613.jpg\" alt=\"\" class=\"wp-image-53439\" srcset=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/04\/injecao-1024x613.jpg 1024w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/04\/injecao-300x179.jpg 300w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/04\/injecao-768x459.jpg 768w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/04\/injecao.jpg 1170w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>Foto: Marcelo Camargo\/Ag\u00eancia Brasil<\/figcaption><\/figure>\n\n\n\n<p>A 7\u00aa c\u00e2mara C\u00edvel Especializada do TJ\/PE decidiu que \u00e9 leg\u00edtima a negativa de plano de sa\u00fade ao custeio de medicamento de uso domiciliar n\u00e3o previsto no rol da ANS nem no contrato. Por unanimidade, o colegiado deu provimento ao recurso da operadora para julgar improcedentes os pedidos da autora, afastando o fornecimento da Somatropina.<\/p>\n\n\n\n<p>O relator destacou que a cobertura de medicamentos domiciliares \u00e9 exce\u00e7\u00e3o no sistema da sa\u00fade suplementar, restrita \u00e0s hip\u00f3teses legais n\u00e3o verificadas no caso.<\/p>\n\n\n\n<p>A a\u00e7\u00e3o foi proposta por paciente diagnosticada com hipopituarismo que recebeu prescri\u00e7\u00e3o m\u00e9dica para uso da Somatropina (horm\u00f4nio do crescimento).<\/p>\n\n\n\n<p>Em 1\u00aa inst\u00e2ncia, o ju\u00edzo da 10\u00aa vara C\u00edvel da Capital\/PE reconheceu o direito ao tratamento e condenou o plano de sa\u00fade a fornecer o medicamento, al\u00e9m de pagar R$ 5 mil por danos morais e reembolsar R$ 18.379,90 gastos pela autora.<\/p>\n\n\n\n<p>A operadora ent\u00e3o recorreu ao TJ\/PE argumentando que o medicamento \u00e9 de uso domiciliar, n\u00e3o integra o rol da ANS e est\u00e1 exclu\u00eddo contratualmente, inexistindo obriga\u00e7\u00e3o legal de custeio ou ilicitude em sua conduta.<\/p>\n\n\n\n<p>O relator, desembargador Andr\u00e9 Rosa, destacou que a lei 9.656\/98 exclui, como regra, o fornecimento de medicamentos de uso domiciliar pelos planos de sa\u00fade, admitindo cobertura apenas em hip\u00f3teses excepcionais, como medicamentos antineopl\u00e1sicos orais ou tratamentos vinculados \u00e0 interna\u00e7\u00e3o hospitalar \u2014 situa\u00e7\u00f5es n\u00e3o verificadas no caso.<\/p><div class=\"fomgt6a97f8490fdfc\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.fomgt6a97f8490fdfc {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.fomgt6a97f8490fdfc {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.fomgt6a97f8490fdfc {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.fomgt6a97f8490fdfc {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.fomgt6a97f8490fdfc {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.fomgt6a97f8490fdfc {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"ymgqq6a97f8490fde9\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.ymgqq6a97f8490fde9 {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.ymgqq6a97f8490fde9 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.ymgqq6a97f8490fde9 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.ymgqq6a97f8490fde9 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.ymgqq6a97f8490fde9 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.ymgqq6a97f8490fde9 {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>&#8220;A cobertura obrigat\u00f3ria de medicamentos de uso domiciliar constitui exce\u00e7\u00e3o, restrita \u00e0s hip\u00f3teses legalmente delimitadas. Fora desses casos, a exclus\u00e3o contratual mostra-se leg\u00edtima e encontra respaldo expresso na legisla\u00e7\u00e3o, n\u00e3o se configurando cl\u00e1usula abusiva ou restritiva de direitos.&#8221;<\/p>\n\n\n\n<p>O magistrado ressaltou ainda que a Resolu\u00e7\u00e3o Normativa 465\/21 da ANS permite a exclus\u00e3o de medicamentos administrados fora do ambiente hospitalar e que a Somatropina n\u00e3o integra o rol de procedimentos obrigat\u00f3rios.<\/p>\n\n\n\n<p>Destacou tamb\u00e9m que o STJ possui entendimento consolidado pela licitude da exclus\u00e3o de medicamentos de uso domiciliar, salvo nas hip\u00f3teses legalmente previstas.<\/p>\n\n\n\n<p>Por fim, observou que a essencialidade do tratamento n\u00e3o afasta as limita\u00e7\u00f5es legais da sa\u00fade suplementar.<\/p>\n\n\n\n<p>O colegiado acompanhou o voto e deu provimento ao recurso para reformar integralmente a senten\u00e7a, julgando improcedentes os pedidos e invertendo os \u00f4nus da sucumb\u00eancia.<\/p>\n\n\n\n<p><em>Fonte: Migalhas<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A a\u00e7\u00e3o foi proposta por paciente diagnosticada com hipopituarismo que recebeu prescri\u00e7\u00e3o m\u00e9dica para uso da Somatropina. <br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2026\/04\/20\/plano-pode-negar-custeio-de-medicamento-domiciliar-fora-do-rol-da-ans\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/53435"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=53435"}],"version-history":[{"count":3,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/53435\/revisions"}],"predecessor-version":[{"id":53440,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/53435\/revisions\/53440"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=53435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=53435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=53435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}