{"id":53412,"date":"2026-04-19T12:10:57","date_gmt":"2026-04-19T15:10:57","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=53412"},"modified":"2026-04-19T12:11:32","modified_gmt":"2026-04-19T15:11:32","slug":"oab-atua-pelo-afastamento-de-delegado-e-cobra-responsabilizacao-apos-detencao-arbitraria-de-advogada","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2026\/04\/19\/oab-atua-pelo-afastamento-de-delegado-e-cobra-responsabilizacao-apos-detencao-arbitraria-de-advogada\/","title":{"rendered":"OAB atua pelo afastamento de delegado e cobra responsabiliza\u00e7\u00e3o ap\u00f3s deten\u00e7\u00e3o de advogada"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"658\" height=\"900\" src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/04\/d3494227ad633b5041be0c95cce8f82c-folhadoestado-com-br.jpg\" alt=\"\" class=\"wp-image-53413\" srcset=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/04\/d3494227ad633b5041be0c95cce8f82c-folhadoestado-com-br.jpg 658w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/04\/d3494227ad633b5041be0c95cce8f82c-folhadoestado-com-br-219x300.jpg 219w\" sizes=\"(max-width: 658px) 100vw, 658px\" \/><figcaption>Imagem: Reprodu\u00e7\u00e3o Redes Sociais<\/figcaption><\/figure>\n\n\n\n<p>A OAB Nacional e a OAB Goi\u00e1s atuam de forma conjunta para garantir o afastamento do delegado envolvido na deten\u00e7\u00e3o da advogada \u00c1ricka Cunha, ocorrida no interior de seu escrit\u00f3rio, em Piren\u00f3polis (GO), e requerem a apura\u00e7\u00e3o imediata dos fatos, com a aplica\u00e7\u00e3o das san\u00e7\u00f5es previstas em lei.<\/p>\n\n\n\n<p>\u201cA condu\u00e7\u00e3o da profissional, nos moldes em que se deu, \u00e9 incompat\u00edvel com a ordem jur\u00eddica e configura, em tese, abuso de autoridade, al\u00e9m de representar grave viola\u00e7\u00e3o das prerrogativas asseguradas pelo Estatuto da Advocacia (Lei 8.906\/94). O livre exerc\u00edcio da advocacia n\u00e3o admite constrangimentos ilegais nem medidas arbitr\u00e1rias por parte de agentes p\u00fablicos\u201d, afirma Beto Simonetti, presidente nacional da Ordem.<\/p>\n\n\n\n<p>Desde o primeiro momento, o presidente da OAB-GO, Rafael Lara Martins, acompanhou o caso de perto e prestou assist\u00eancia \u00e0 advogada, acionando o Sistema de Defesa das Prerrogativas para ado\u00e7\u00e3o das medidas cab\u00edveis.<\/p>\n\n\n\n<p>\u201c\u00c9 desrespeitosa, ilegal e flagrantemente arbitr\u00e1ria a atitude do delegado. A autoridade que o cargo lhe investe n\u00e3o \u00e9 privil\u00e9gio para que atue em causa pr\u00f3pria, atropelando o direito dos cidad\u00e3os e as leis que deveria proteger. Sua conduta precisa ser investigada pela entidade correicional e punida como exemplo de que fun\u00e7\u00e3o p\u00fablica exige responsabilidade e modera\u00e7\u00e3o\u201d, destaca Rafael Lara.<\/p><div class=\"mjeqx6a97f90664896\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.mjeqx6a97f90664896 {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.mjeqx6a97f90664896 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.mjeqx6a97f90664896 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.mjeqx6a97f90664896 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.mjeqx6a97f90664896 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.mjeqx6a97f90664896 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"pvwgw6a97f90664878\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.pvwgw6a97f90664878 {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.pvwgw6a97f90664878 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.pvwgw6a97f90664878 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.pvwgw6a97f90664878 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.pvwgw6a97f90664878 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.pvwgw6a97f90664878 {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>A estrutura nacional de defesa das prerrogativas do Conselho Federal j\u00e1 est\u00e1 mobilizada e segue atuando em conjunto com a seccional goiana para assegurar a responsabiliza\u00e7\u00e3o dos envolvidos e evitar a repeti\u00e7\u00e3o de epis\u00f3dios dessa natureza.<\/p>\n\n\n\n<p>A OAB reafirma que n\u00e3o tolerar\u00e1 viola\u00e7\u00f5es \u00e0s prerrogativas da advocacia e adotar\u00e1 todas as medidas institucionais necess\u00e1rias para garantir o respeito ao exerc\u00edcio profissional e \u00e0 Constitui\u00e7\u00e3o.<\/p>\n\n\n\n<p><em>Fonte: OAB<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A OAB reafirma que n\u00e3o tolerar\u00e1 viola\u00e7\u00f5es \u00e0s prerrogativas da advocacia e adotar\u00e1 todas as medidas institucionais necess\u00e1rias para garantir o respeito ao exerc\u00edcio profissional e \u00e0 Constitui\u00e7\u00e3o.<br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2026\/04\/19\/oab-atua-pelo-afastamento-de-delegado-e-cobra-responsabilizacao-apos-detencao-arbitraria-de-advogada\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/53412"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=53412"}],"version-history":[{"count":3,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/53412\/revisions"}],"predecessor-version":[{"id":53416,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/53412\/revisions\/53416"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=53412"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=53412"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=53412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}