{"id":5341,"date":"2020-01-09T20:04:20","date_gmt":"2020-01-09T23:04:20","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=5341"},"modified":"2020-01-09T20:04:20","modified_gmt":"2020-01-09T23:04:20","slug":"toffoli-derruba-censura-a-especial-de-natal-do-porta-dos-fundos","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2020\/01\/09\/toffoli-derruba-censura-a-especial-de-natal-do-porta-dos-fundos\/","title":{"rendered":"Toffoli derruba censura a especial de Natal do Porta dos Fundos"},"content":{"rendered":"\n<p>O presidente do<strong>\u00a0Supremo Tribunal Federal<\/strong>\u00a0(STF), ministro\u00a0<strong>Dias Toffoli<\/strong>, derrubou na tarde desta quinta-feira a censura imposta pelo desembargador Benedicto Abicair ao\u00a0<em>Especial de Natal Porta dos Fundos: A Primeira Tenta\u00e7\u00e3o de Cristo<\/em>, veiculado pela plataforma de streaming\u00a0<strong>Netflix<\/strong>. Toffoli atendeu a um pedido da pr\u00f3pria Netflix, que havia recorrido \u00e0 Corte sob a alega\u00e7\u00e3o de que n\u00e3o cabe ao Estado brasileiro impor censura pol\u00edtica, ideol\u00f3gica ou art\u00edstica e tampouco definir novas regras ou restri\u00e7\u00f5es \u00e0 liberdade de express\u00e3o.<\/p>\n\n\n\n<p>Para a empresa, a inger\u00eancia judicial sobre o filme tinha \u201co cond\u00e3o de causar um efeito silenciador no espectro da liberdade de express\u00e3o sobre outros conte\u00fados audiovisuais de car\u00e1ter cr\u00edtico ou sat\u00edrico, atuais ou futuros\u201d. \u201cFica evidente o efeito devastador produzido por tais decis\u00f5es [de censura]. A decis\u00e3o [que determinou a suspens\u00e3o da exibi\u00e7\u00e3o da s\u00e1tira] tem efeito equivalente ao da bomba utilizada no atentado terrorista \u00e0 sede do Porta dos Fundos: silencia por meio do medo e da intimida\u00e7\u00e3o\u201d, alegou a Netflix. Na v\u00e9spera de Natal, a fachada da produtora Porta dos Fundos, no Rio de Janeiro, foi alvo de bombas incendi\u00e1rias de fabrica\u00e7\u00e3o caseira. Um dos autores do ataque foi identificado como Eduardo Fauzi. Ele est\u00e1 na R\u00fassia e tem contra si um mandado de captura internacional emitido pela Interpol.<\/p>\n\n\n\n<p>O recurso havia sido distribu\u00eddo originalmente ao ministro Gilmar Mendes, mas por conta do recesso do Poder Judici\u00e1rio, o caso foi encaminhado ao presidente do STF, respons\u00e1vel, no plant\u00e3o do tribunal, por analisar casos urgentes. No processo encaminhado ao Supremo, a plataforma de streaming destaca que o Chile foi condenado, em 2001, pela Corte Interamericana de Direitos Humanos ap\u00f3s ter censurado judicialmente a exibi\u00e7\u00e3o do filme \u201cA \u00daltima Tenta\u00e7\u00e3o de Cristo\u201d, de Martin Scorsese. A Corte chilena alegara na \u00e9poca que a suspens\u00e3o da exibi\u00e7\u00e3o do longa estava baseada, entre outros pontos, no direito \u00e0 honra e \u00e0 reputa\u00e7\u00e3o de Jesus Cristo.<\/p><div class=\"lxliu6a56fe90a0503\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.lxliu6a56fe90a0503 {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.lxliu6a56fe90a0503 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.lxliu6a56fe90a0503 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.lxliu6a56fe90a0503 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.lxliu6a56fe90a0503 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.lxliu6a56fe90a0503 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"vurbr6a56fe90a04ef\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.vurbr6a56fe90a04ef {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.vurbr6a56fe90a04ef {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.vurbr6a56fe90a04ef {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.vurbr6a56fe90a04ef {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.vurbr6a56fe90a04ef {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.vurbr6a56fe90a04ef {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>\u201cN\u00e3o \u00e9 dado ao Estado proteger maiorias sempre que manifesta\u00e7\u00f5es art\u00edsticas as incomode, ainda mais se o direito contraposto \u00e9 fundamentado em cren\u00e7as religiosas, considerando o modelo de Estado laico adotado no Brasil desde a Proclama\u00e7\u00e3o da Rep\u00fablica. Trata-se de medida que viola o cerne do regime democr\u00e1tico brasileiro\u201d, alegou a Netflix no processo. \u201cImp\u00f4s-se um controle sobre conte\u00fados art\u00edsticos que, a pretexto de conferir preval\u00eancia \u00e0s liberdades religiosas, importou em verdadeira retirada de conte\u00fado audiovisual disponibilizada a p\u00fablico espec\u00edfico. Isso constitui patente censura pr\u00e9via emanada do Poder Judici\u00e1rio a ve\u00edculo de comunica\u00e7\u00e3o social que dissemina (\u2026) conte\u00fado art\u00edstico \u2013 expressamente vedada pela Constitui\u00e7\u00e3o\u201d, completa a empresa.<\/p>\n\n\n\n<p>Veja<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Toffoli atendeu a um pedido da pr\u00f3pria Netflix, que havia recorrido \u00e0 Corte sob a alega\u00e7\u00e3o de que n\u00e3o cabe ao Estado brasileiro impor censura <br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2020\/01\/09\/toffoli-derruba-censura-a-especial-de-natal-do-porta-dos-fundos\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":5,"featured_media":5342,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5341"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=5341"}],"version-history":[{"count":1,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5341\/revisions"}],"predecessor-version":[{"id":5343,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5341\/revisions\/5343"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media\/5342"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=5341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=5341"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=5341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}