{"id":53330,"date":"2026-04-15T21:57:55","date_gmt":"2026-04-16T00:57:55","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=53330"},"modified":"2026-04-15T22:02:41","modified_gmt":"2026-04-16T01:02:41","slug":"tcu-aponta-descontrole-em-gastos-de-r-285-milhoes-com-voos-da-fab","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2026\/04\/15\/tcu-aponta-descontrole-em-gastos-de-r-285-milhoes-com-voos-da-fab\/","title":{"rendered":"TCU aponta descontrole em gastos de R$ 285 milh\u00f5es com voos da FAB"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"900\" height=\"596\" src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/04\/FAB.jpg\" alt=\"\" class=\"wp-image-53332\" srcset=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/04\/FAB.jpg 900w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/04\/FAB-300x199.jpg 300w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/04\/FAB-768x509.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><figcaption>Foto: FAB<\/figcaption><\/figure>\n\n\n\n<p>O Tribunal de Contas da Uni\u00e3o (TCU) realizou uma auditoria em voos da For\u00e7a A\u00e9rea Brasileira (FAB) ocorridos entre janeiro de 2020 e julho de 2025, os quais custaram R$ 285 milh\u00f5es aos cofres p\u00fablicos. O \u00f3rg\u00e3o apontou irregularidades e sinalizou que o governo poderia ter economizado pelo menos R$ 36,1 milh\u00f5es se, em determinados casos, as autoridades tivessem priorizado voos comerciais.<\/p>\n\n\n\n<p>A fiscaliza\u00e7\u00e3o revelou que, em uma amostra de 266 processos de pedidos de voos, 25% n\u00e3o foram localizados. Nos registros encontrados, aponta o TCU, n\u00e3o h\u00e1 justificativa exata para o uso de avi\u00f5es da FAB em detrimento de voos comerciais. A Corte tamb\u00e9m afirmou que, em 70% dos voos analisados, os passageiros embarcados n\u00e3o foram devidamente identificados.<\/p>\n\n\n\n<p>Segundo o TCU, a FAB n\u00e3o possui um controle interno para impedir que pessoas n\u00e3o autorizadas pelo decreto que regulamenta o transporte oficial utilizem os voos. \u201cO Comando da Aeron\u00e1utica n\u00e3o emite qualquer ju\u00edzo de valor acerca da motiva\u00e7\u00e3o do requerimento de transporte e do atendimento aos requisitos normativos\u201d, diz o documento da auditoria.<\/p>\n\n\n\n<p>O plen\u00e1rio do TCU determinou, nesta ter\u00e7a-feira (15\/4), que a Casa Civil apresente, em at\u00e9 30 dias, um plano de a\u00e7\u00e3o conjunta com medidas para reformular as regras de uso dos voos da FAB. As novas diretrizes, conforme a decis\u00e3o do tribunal, devem ser implementadas pelo Comando da Aeron\u00e1utica em um prazo de at\u00e9 180 dias.<\/p><div class=\"gnxad6a9803ada6bc8\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.gnxad6a9803ada6bc8 {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.gnxad6a9803ada6bc8 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.gnxad6a9803ada6bc8 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.gnxad6a9803ada6bc8 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.gnxad6a9803ada6bc8 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.gnxad6a9803ada6bc8 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"yihvj6a9803ada6bae\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.yihvj6a9803ada6bae {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.yihvj6a9803ada6bae {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.yihvj6a9803ada6bae {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.yihvj6a9803ada6bae {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.yihvj6a9803ada6bae {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.yihvj6a9803ada6bae {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>\u201cA auditoria destacou, ainda, a inefici\u00eancia em decorr\u00eancia da baixa taxa de ocupa\u00e7\u00e3o de assentos: verificou-se que, no per\u00edodo de 2020 a julho de 2024, foram realizados 111 voos para o transporte de apenas 1 passageiro e 1.585 voos (21%) para transportar at\u00e9 5 passageiros, sendo que a aeronave utilizada pela FAB com menor capacidade de transporte carrega 8 passageiros\u201d, diz o documento.<\/p>\n\n\n\n<p>Os voos da FAB s\u00e3o usados por autoridades dos Tr\u00eas Poderes (Executivo, Legislativo e Judici\u00e1rio).<\/p>\n\n\n\n<p><em>Fonte: Metr\u00f3poles<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Segundo o TCU, a FAB n\u00e3o possui um controle interno para impedir que pessoas n\u00e3o autorizadas pelo decreto que regulamenta o transporte oficial utilizem os voos. <br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2026\/04\/15\/tcu-aponta-descontrole-em-gastos-de-r-285-milhoes-com-voos-da-fab\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/53330"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=53330"}],"version-history":[{"count":3,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/53330\/revisions"}],"predecessor-version":[{"id":53334,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/53330\/revisions\/53334"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=53330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=53330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=53330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}