{"id":53295,"date":"2026-04-15T09:43:23","date_gmt":"2026-04-15T12:43:23","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=53295"},"modified":"2026-04-15T09:46:22","modified_gmt":"2026-04-15T12:46:22","slug":"cnj-proibe-exposicao-da-vida-privada-de-vitima-em-processo-disciplinar","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2026\/04\/15\/cnj-proibe-exposicao-da-vida-privada-de-vitima-em-processo-disciplinar\/","title":{"rendered":"CNJ pro\u00edbe exposi\u00e7\u00e3o da vida privada de v\u00edtimas e testemunhas em processo disciplinar"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"799\" height=\"533\" src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/04\/55208032183_fe89d7dc77_c.jpg\" alt=\"\" class=\"wp-image-53299\" srcset=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/04\/55208032183_fe89d7dc77_c.jpg 799w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/04\/55208032183_fe89d7dc77_c-300x200.jpg 300w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/04\/55208032183_fe89d7dc77_c-768x512.jpg 768w\" sizes=\"(max-width: 799px) 100vw, 799px\" \/><figcaption>Foto: Ana Ara\u00fajo\/CNJ<\/figcaption><\/figure>\n\n\n\n<p>O plen\u00e1rio do CNJ refor\u00e7ou a proibi\u00e7\u00e3o de exposi\u00e7\u00e3o indevida da vida privada de v\u00edtimas e testemunhas em processos disciplinares, ao atualizar normas para evitar revitimiza\u00e7\u00e3o em casos de infra\u00e7\u00f5es contra a dignidade sexual e viol\u00eancia contra a mulher.<\/p>\n\n\n\n<p>A decis\u00e3o foi tomada nesta ter\u00e7a-feira, 14, durante a 5\u00aa sess\u00e3o Ordin\u00e1ria de 2026 do colegiado, com base na necessidade de prote\u00e7\u00e3o e de alinhamento a diretrizes constitucionais.<\/p>\n\n\n\n<p>A medida altera a resolu\u00e7\u00e3o 135\/11, que trata do procedimento administrativo disciplinar aplic\u00e1vel a magistrados, e estabelece regras mais claras sobre a conduta de advogados e demais participantes.<\/p>\n\n\n\n<p>A atualiza\u00e7\u00e3o decorre do pedido de provid\u00eancia apresentado pela servidora p\u00fablica Federal Jussara de Carvalho Perea, que solicitou a aplica\u00e7\u00e3o expressa, em processo disciplinar contra magistrado Federal investigado por suposto ass\u00e9dio sexual, das regras previstas na lei 14.245\/21, conhecida como lei Mariana Ferrer.<\/p>\n\n\n\n<p>No voto, o relator, conselheiro Fabio Esteves, vedou men\u00e7\u00f5es a aspectos da vida privada sem rela\u00e7\u00e3o com os fatos investigados, o uso de linguagem ofensiva e a apresenta\u00e7\u00e3o de materiais que atentem contra a dignidade da v\u00edtima. Ele destacou que, embora o ordenamento jur\u00eddico j\u00e1 permita a aplica\u00e7\u00e3o do art. 400-A do CPP, \u00e9 necess\u00e1rio refor\u00e7o normativo expl\u00edcito.<\/p>\n\n\n\n<p>\u201cO refor\u00e7o normativo se revela recomend\u00e1vel, especialmente diante do papel pedag\u00f3gico que uma norma expressa pode exercer no enfrentamento da viol\u00eancia institucional contra mulheres v\u00edtimas de infra\u00e7\u00f5es sexuais. O ordenamento jur\u00eddico brasileiro (\u2026) \u00e9 inequ\u00edvoco ao estabelecer a igualdade de g\u00eanero como valor fundamental e ao impor aos Estados o dever de adotar todas as medidas necess\u00e1rias para erradicar a viol\u00eancia contra a mulher.&#8221;<\/p>\n\n\n\n<p>O relator tamb\u00e9m fundamentou a proposta em entendimento do STF, que pro\u00edbe o uso de elementos relacionados \u00e0 vida sexual pregressa da v\u00edtima em processos dessa natureza, al\u00e9m de destacar a pol\u00edtica institucional do CNJ de incorpora\u00e7\u00e3o da perspectiva de g\u00eanero.<\/p>\n\n\n\n<p>\u201cA persist\u00eancia de estere\u00f3tipos de g\u00eanero e a cultura jur\u00eddica ainda segue marcada por vieses hist\u00f3ricos que t\u00eam permitido que v\u00edtimas sejam submetidas a questionamentos sobre sua vida privada, em desconformidade com os princ\u00edpios constitucionais da dignidade da pessoa humana e da igualdade.&#8221;<\/p><div class=\"bnjxa6a98042aa2be1\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.bnjxa6a98042aa2be1 {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.bnjxa6a98042aa2be1 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.bnjxa6a98042aa2be1 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.bnjxa6a98042aa2be1 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.bnjxa6a98042aa2be1 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.bnjxa6a98042aa2be1 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"ffmec6a98042aa2bc2\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.ffmec6a98042aa2bc2 {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.ffmec6a98042aa2bc2 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.ffmec6a98042aa2bc2 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.ffmec6a98042aa2bc2 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.ffmec6a98042aa2bc2 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.ffmec6a98042aa2bc2 {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>O conselheiro apontou que a viol\u00eancia institucional ocorre quando \u00f3rg\u00e3os do sistema de Justi\u00e7a exp\u00f5em v\u00edtimas a constrangimentos e julgamentos morais irrelevantes, transferindo indevidamente a responsabilidade pelos fatos.<\/p>\n\n\n\n<p>\u201cAspectos da vida privada da mulher, sua vida sexual pregressa, escolhas afetivas, modo de vestir ou h\u00e1bitos de lazer n\u00e3o podem ser utilizados para desqualificar sua palavra ou legitimar, ainda que implicitamente, a conduta do agressor.\u201d<\/p>\n\n\n\n<p>A conselheira Jaceguara Dantas da Silva destacou que as medidas representam avan\u00e7o na garantia de direitos, ao evitar pr\u00e1ticas discriminat\u00f3rias e interrogat\u00f3rios invasivos que possam influenciar decis\u00f5es.<\/p>\n\n\n\n<p>\u201c[As medidas] evitam barreiras institucionais que perpetuam desigualdades, sobretudo an\u00e1lises e estere\u00f3tipos discriminat\u00f3rios que exp\u00f5em v\u00edtimas a julgamentos morais e interrogat\u00f3rios invasivos sobre sua vida privada, refletindo em decis\u00f5es parciais e marcadas por comportamento mis\u00f3gino.\u201d<\/p>\n\n\n\n<p>No mesmo sentido, o conselheiro Marcello Terto afirmou que o protocolo de julgamento com perspectiva de g\u00eanero, embora abrangente, ainda n\u00e3o tem sido suficiente para impedir estrat\u00e9gias que deslocam o foco dos fatos.<\/p>\n\n\n\n<p>\u201cEm diversos processos dessa natureza sob nossa an\u00e1lise, temos observado que, n\u00e3o raramente, a defesa desloca o foco dos fatos para a intimidade, a vida privada e o modo de viver da v\u00edtima, como se ela pr\u00f3pria estivesse sendo julgada. Essa pr\u00e1tica, se tolerada, configura verdadeira viol\u00eancia.&#8221;<\/p>\n\n\n\n<p><strong>Processo:&nbsp;0002075-02.2024.2.00.0000<\/strong><\/p>\n\n\n\n<p><em>Fonte: Migalhas<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A decis\u00e3o foi tomada nesta ter\u00e7a-feira, 14, durante a 5\u00aa sess\u00e3o Ordin\u00e1ria de 2026 do colegiado, com base na necessidade de prote\u00e7\u00e3o e de alinhamento a diretrizes constitucionais.<br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2026\/04\/15\/cnj-proibe-exposicao-da-vida-privada-de-vitima-em-processo-disciplinar\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/53295"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=53295"}],"version-history":[{"count":3,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/53295\/revisions"}],"predecessor-version":[{"id":53300,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/53295\/revisions\/53300"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=53295"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=53295"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=53295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}