{"id":53230,"date":"2026-04-13T20:03:06","date_gmt":"2026-04-13T23:03:06","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=53230"},"modified":"2026-04-13T20:07:35","modified_gmt":"2026-04-13T23:07:35","slug":"eua-dizem-que-ramagem-esta-sujeito-a-deportacao-apos-ter-o-visto-vencido","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2026\/04\/13\/eua-dizem-que-ramagem-esta-sujeito-a-deportacao-apos-ter-o-visto-vencido\/","title":{"rendered":"Estados Unidos dizem que Ramagem est\u00e1 sujeito \u00e0 deporta\u00e7\u00e3o ap\u00f3s ter o visto vencido"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/04\/Ramagem-1024x683.jpg\" alt=\"\" class=\"wp-image-53233\" srcset=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/04\/Ramagem-1024x683.jpg 1024w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/04\/Ramagem-300x200.jpg 300w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/04\/Ramagem-768x512.jpg 768w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/04\/Ramagem-1536x1024.jpg 1536w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/04\/Ramagem.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>Foto: Fernando Faz\u00e3o\/Ag\u00eancia Brasil<\/figcaption><\/figure>\n\n\n\n<p>O Departamento de Seguran\u00e7a Interna dos Estados Unidos (DHS, na sigla em ingl\u00eas) afirmou que o deputado federal cassado Alexandre Ramagem, preso em Orlando nesta segunda-feira (13\/4), est\u00e1 sujeito a deporta\u00e7\u00e3o. A informa\u00e7\u00e3o consta em documento exclusivo obtido pelo Metr\u00f3poles.<\/p>\n\n\n\n<p>De acordo com o documento, Ramagem foi admitido nos EUA no dia 11 de setembro de 2025, com um visto B-2, no formato visitante n\u00e3o imigrante para turismo. O prazo de perman\u00eancia no pa\u00eds era at\u00e9 10 de mar\u00e7o de 2026.<\/p>\n\n\n\n<p>O DHS afirma que o brasileiro continuou no pa\u00eds ap\u00f3s o vencimento da permiss\u00e3o. \u201cFica determinado que voc\u00ea est\u00e1 sujeito \u00e0 remo\u00e7\u00e3o (deporta\u00e7\u00e3o) dos Estados Unidos, nos termos da Lei de Imigra\u00e7\u00e3o e Nacionalidade\u201d, diz trecho.<\/p>\n\n\n\n<p>Ramagem foi preso pelo Servi\u00e7o de Imigra\u00e7\u00e3o e Controle de Aduanas dos EUA (ICE) e levado para um centro de deten\u00e7\u00e3o devido a quest\u00f5es migrat\u00f3ria. Ele perdeu o passaporte diplom\u00e1tico ap\u00f3s ter o mandato de deputado federal cassado pelo Congresso Nacional, em dezembro de 2025.<\/p><div class=\"nxtgl6a9812107f8f9\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.nxtgl6a9812107f8f9 {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.nxtgl6a9812107f8f9 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.nxtgl6a9812107f8f9 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.nxtgl6a9812107f8f9 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.nxtgl6a9812107f8f9 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.nxtgl6a9812107f8f9 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"cckby6a9812107f8e6\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.cckby6a9812107f8e6 {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.cckby6a9812107f8e6 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.cckby6a9812107f8e6 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.cckby6a9812107f8e6 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.cckby6a9812107f8e6 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.cckby6a9812107f8e6 {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>Em comunicado, a Pol\u00edcia Federal (PF) afirmou que a pris\u00e3o de Alexandre Ramagem ocorreu \u201cem coopera\u00e7\u00e3o internacional entre Brasil e EUA.<\/p>\n\n\n\n<p>\u201cA pris\u00e3o decorreu de coopera\u00e7\u00e3o policial internacional entre a Pol\u00edcia Federal e autoridades policiais dos EUA. O preso \u00e9 considerado foragido da Justi\u00e7a brasileira ap\u00f3s condena\u00e7\u00e3o pelos crimes de organiza\u00e7\u00e3o criminosa armada, golpe de Estado e tentativa de aboli\u00e7\u00e3o violenta do Estado de Direito\u201d, diz a PF.<\/p>\n\n\n\n<p><em>Fonte: Metr\u00f3poles<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ramagem foi preso nesta segunda-feira (13) pelo Servi\u00e7o de Imigra\u00e7\u00e3o e Controle de Aduanas dos EUA (ICE) e levado para um centro de deten\u00e7\u00e3o devido a quest\u00f5es migrat\u00f3ria. <br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2026\/04\/13\/eua-dizem-que-ramagem-esta-sujeito-a-deportacao-apos-ter-o-visto-vencido\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/53230"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=53230"}],"version-history":[{"count":4,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/53230\/revisions"}],"predecessor-version":[{"id":53236,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/53230\/revisions\/53236"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=53230"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=53230"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=53230"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}