{"id":52860,"date":"2026-04-02T06:54:35","date_gmt":"2026-04-02T09:54:35","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=52860"},"modified":"2026-04-02T07:01:50","modified_gmt":"2026-04-02T10:01:50","slug":"justica-reconhece-falha-de-banco-em-golpe-do-boleto-e-proibe-negativacao-de-cliente","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2026\/04\/02\/justica-reconhece-falha-de-banco-em-golpe-do-boleto-e-proibe-negativacao-de-cliente\/","title":{"rendered":"Golpe do boleto: TJRN responsabiliza banco e protege cliente de negativa\u00e7\u00e3o"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"678\" height=\"471\" src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/04\/boletos.jpg\" alt=\"\" class=\"wp-image-52865\" srcset=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/04\/boletos.jpg 678w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/04\/boletos-300x208.jpg 300w\" sizes=\"(max-width: 678px) 100vw, 678px\" \/><\/figure>\n\n\n\n<p>A 3\u00aa C\u00e2mara C\u00edvel do TJRN determinou que um banco abstenha-se de incluir o nome de uma usu\u00e1ria dos servi\u00e7os, autora de um recurso, em cadastros de inadimplentes (SPC, Serasa), bem como de realizar protestos ou qualquer outro ato de cobran\u00e7a, sob pena de multa di\u00e1ria. A demanda se relaciona ao chamado \u201cGolpe do Boleto\u201d, em que foi v\u00edtima a autora e, desta forma, reformou a senten\u00e7a inicial, dada pela 1\u00aa Vara C\u00edvel da Comarca de Natal, que havia, inicialmente, indeferido o pedido.<\/p>\n\n\n\n<p>\u201cA an\u00e1lise preliminar dos documentos constantes nos autos indica a exist\u00eancia de fortes ind\u00edcios de que os dados utilizados na fraude foram obtidos a partir de vazamento no sistema da pr\u00f3pria institui\u00e7\u00e3o financeira, dada a precis\u00e3o e o detalhamento das informa\u00e7\u00f5es inseridas no boleto falso, como o n\u00famero da parcela (59\/64), dados do im\u00f3vel e hist\u00f3rico de pagamento\u201d, destaca o desembargador Jo\u00e3o Rebou\u00e7as, relator do recurso.<\/p>\n\n\n\n<p>Segundo o julgamento, a presen\u00e7a de informa\u00e7\u00f5es sigilosas no boleto fraudulento, n\u00e3o dispon\u00edveis publicamente, caracteriza falha na presta\u00e7\u00e3o do servi\u00e7o e viola\u00e7\u00e3o do dever de prote\u00e7\u00e3o de dados, atraindo a responsabilidade objetiva da institui\u00e7\u00e3o financeira, com base na teoria do risco do empreendimento e conforme disp\u00f5e a S\u00famula 479 do STJ e o artigo 44 da LGPD (Lei Geral de Prote\u00e7\u00e3o de Dados).<\/p><div class=\"odtic6a98343c9e514\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.odtic6a98343c9e514 {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.odtic6a98343c9e514 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.odtic6a98343c9e514 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.odtic6a98343c9e514 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.odtic6a98343c9e514 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.odtic6a98343c9e514 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"vqfza6a98343c9e4f9\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.vqfza6a98343c9e4f9 {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.vqfza6a98343c9e4f9 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.vqfza6a98343c9e4f9 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.vqfza6a98343c9e4f9 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.vqfza6a98343c9e4f9 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.vqfza6a98343c9e4f9 {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>Conforme o desembargador Jo\u00e3o Rebou\u00e7as, a pr\u00f3pria jurisprud\u00eancia do STJ reconhece que, comprovado o vazamento de dados banc\u00e1rios utilizados em golpe, configura-se defeito na presta\u00e7\u00e3o do servi\u00e7o, sendo devida a responsabiliza\u00e7\u00e3o da institui\u00e7\u00e3o financeira pelo evento danoso.<\/p>\n\n\n\n<p>\u201cA imin\u00eancia de protesto e negativa\u00e7\u00e3o indevida, evidenciada por notifica\u00e7\u00e3o extrajudicial j\u00e1 expedida, demonstra risco de dano de dif\u00edcil repara\u00e7\u00e3o, justificando a concess\u00e3o da tutela de urg\u00eancia para impedir a pr\u00e1tica de atos que agravem a situa\u00e7\u00e3o da parte autora antes da conclus\u00e3o do m\u00e9rito\u201d, esclarece o relator.<\/p>\n\n\n\n<p>A decis\u00e3o ainda acrescenta que a presen\u00e7a de terceiro como benefici\u00e1rio do pagamento, longe de afastar a tese da agravante, refor\u00e7a a narrativa de que ela foi v\u00edtima de golpe arquitetado com base em informa\u00e7\u00f5es indevidamente acessadas, sendo esse o n\u00facleo da fraude denunciada.<br><br><em>Fonte: TJRN<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jurisprud\u00eancia do STJ entende que o vazamento de dados banc\u00e1rios em golpes caracteriza falha no servi\u00e7o e gera responsabilidade da institui\u00e7\u00e3o financeira.<br \/>\n<br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2026\/04\/02\/justica-reconhece-falha-de-banco-em-golpe-do-boleto-e-proibe-negativacao-de-cliente\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/52860"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=52860"}],"version-history":[{"count":5,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/52860\/revisions"}],"predecessor-version":[{"id":52870,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/52860\/revisions\/52870"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=52860"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=52860"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=52860"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}