{"id":52795,"date":"2026-03-31T13:22:15","date_gmt":"2026-03-31T16:22:15","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=52795"},"modified":"2026-03-31T13:25:00","modified_gmt":"2026-03-31T16:25:00","slug":"caseiro-recebera-multa-de-40-do-fgts-por-rompimento-antecipado-de-contrato-de-experiencia","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2026\/03\/31\/caseiro-recebera-multa-de-40-do-fgts-por-rompimento-antecipado-de-contrato-de-experiencia\/","title":{"rendered":"Caseiro receber\u00e1 multa de 40% do FGTS por rompimento antecipado de contrato de experi\u00eancia"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"770\" height=\"513\" src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/03\/carteira_digital.jpg\" alt=\"\" class=\"wp-image-52797\" srcset=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/03\/carteira_digital.jpg 770w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/03\/carteira_digital-300x200.jpg 300w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/03\/carteira_digital-768x512.jpg 768w\" sizes=\"(max-width: 770px) 100vw, 770px\" \/><figcaption>Foto: Marcelo Camargo\/Ag\u00eancia Brasil<\/figcaption><\/figure>\n\n\n\n<p>A S\u00e9tima Turma do Tribunal Superior do Trabalho (TST) condenou uma empregadora dom\u00e9stica de Nazar\u00e9 da Mata (PE) a pagar a multa de 40% do Fundo de Garantia do Tempo de Servi\u00e7o (FGTS) a um caseiro por rescis\u00e3o antecipada do contrato de experi\u00eancia. Segundo o colegiado, a parcela visa proteger o trabalhador de dispensa arbitr\u00e1ria, e o contrato de experi\u00eancia n\u00e3o afasta essa prote\u00e7\u00e3o constitucional.<\/p>\n\n\n\n<p>O caseiro foi contratado em 1\u00ba\/10\/2021 para um per\u00edodo de experi\u00eancia de 45 dias, prorrog\u00e1vel pelo mesmo per\u00edodo, mas foi dispensado quando faltavam apenas dois dias para o fim do prazo.<\/p>\n\n\n\n<p>Na contesta\u00e7\u00e3o \u00e0 a\u00e7\u00e3o trabalhista, a empregadora disse que o caseiro teria abandonado o emprego e defendeu que a multa de 40% do FGTS seria devida apenas na rescis\u00e3o contratual sem justa causa. Outra interpreta\u00e7\u00e3o, segundo ela, desvirtuaria a ess\u00eancia do contrato de experi\u00eancia, impondo-lhe uma penalidade incompat\u00edvel com a sua natureza.<\/p><div class=\"sacqj6a983e7b59841\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.sacqj6a983e7b59841 {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.sacqj6a983e7b59841 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.sacqj6a983e7b59841 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.sacqj6a983e7b59841 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.sacqj6a983e7b59841 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.sacqj6a983e7b59841 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"dkdrz6a983e7b59829\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.dkdrz6a983e7b59829 {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.dkdrz6a983e7b59829 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.dkdrz6a983e7b59829 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.dkdrz6a983e7b59829 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.dkdrz6a983e7b59829 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.dkdrz6a983e7b59829 {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>Sem conseguir comprovar o abandono de emprego, a empregadora foi condenada em primeira e segunda inst\u00e2ncia e recorreu ao TST.<br>Rescis\u00e3o antecipada equivale a dispensa imotivada<\/p>\n\n\n\n<p>O relator, ministro Agra Belmonte, ressaltou que o TST tem entendimento consolidado de que, no caso de rescis\u00e3o antecipada de contrato por tempo determinado, \u00e9 devida a indeniza\u00e7\u00e3o de 40% sobre o FGTS. Segundo ele, a medida, prevista na Constitui\u00e7\u00e3o Federal, visa proteger o trabalhador contra despedidas arbitr\u00e1rias ou sem justa causa. Por sua vez, o regulamento do FGTS (Decreto 99.684\/1990) estabelece que a rescis\u00e3o antecipada nesses casos equivale \u00e0 despedida imotivada.<br><br><em>Fonte: TST<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O caseiro foi contratado em 1\u00ba\/10\/2021 para um per\u00edodo de experi\u00eancia de 45 dias, prorrog\u00e1vel pelo mesmo per\u00edodo, mas foi dispensado quando faltavam apenas dois dias para o fim do prazo.<br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2026\/03\/31\/caseiro-recebera-multa-de-40-do-fgts-por-rompimento-antecipado-de-contrato-de-experiencia\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/52795"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=52795"}],"version-history":[{"count":3,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/52795\/revisions"}],"predecessor-version":[{"id":52800,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/52795\/revisions\/52800"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=52795"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=52795"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=52795"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}