{"id":52194,"date":"2026-03-16T09:03:52","date_gmt":"2026-03-16T12:03:52","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=52194"},"modified":"2026-03-16T09:07:31","modified_gmt":"2026-03-16T12:07:31","slug":"cunhada-do-ministro-alexandre-de-moraes-e-autora-do-codigo-de-etica-do-banco-master","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2026\/03\/16\/cunhada-do-ministro-alexandre-de-moraes-e-autora-do-codigo-de-etica-do-banco-master\/","title":{"rendered":"Cunhada do ministro Alexandre de Moraes \u00e9 autora do C\u00f3digo de \u00c9tica do Banco Master"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1024\" height=\"1024\" src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/03\/Ana-Claudia-Consani-de-Moraes-1024x1024.jpg\" alt=\"\" class=\"wp-image-52196\" srcset=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/03\/Ana-Claudia-Consani-de-Moraes-1024x1024.jpg 1024w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/03\/Ana-Claudia-Consani-de-Moraes-300x300.jpg 300w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/03\/Ana-Claudia-Consani-de-Moraes-150x150.jpg 150w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/03\/Ana-Claudia-Consani-de-Moraes-768x768.jpg 768w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/03\/Ana-Claudia-Consani-de-Moraes.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>Foto: Reprodu\u00e7\u00e3o<\/figcaption><\/figure>\n\n\n\n<p>A advogada Ana Claudia Consani de Moraes, cunhada do ministro do Supremo Tribunal Federal, Alexandre de Moraes, \u00e9 a autora do C\u00f3digo de \u00c9tica do Banco Master. Casada com Leonardo de Moraes, irm\u00e3o do juiz, ela atua como consultora no escrit\u00f3rio de Viviane Barci de Moraes, mulher do ministro \u2013que recebeu R$ 80 milh\u00f5es por um contrato de 22 meses de servi\u00e7os prestados \u00e0 institui\u00e7\u00e3o.<\/p>\n\n\n\n<p>Segundo os metadados consultados pelo Poder360 em PDF dispon\u00edvel no site do Banco Master, a advogada aparece classificada como \u201cautora\u201d do documento, criado em 8 de abril de 2025.<\/p>\n\n\n\n<p>O escrit\u00f3rio Barci de Moraes confirmou em nota divulgada em 9 de mar\u00e7o de 2026 que a elabora\u00e7\u00e3o do documento estava entre os produtos entregues ao banco de Daniel Vorcaro.<\/p>\n\n\n\n<p>Al\u00e9m de ser consultora no escrit\u00f3rio Barci de Moraes, Consani faz parte de comiss\u00f5es de integridade, \u00e9tica e compliance da Petrobras, OAB\/SP (Ordem dos Advogados do Brasil), IBDEE (Instituto Brasileiro de Direito e \u00c9tica Empresarial) e Idasan (Instituto de Direito Administrativo Sancionador Brasileiro).<\/p><div class=\"xhnst6a986cfb7561f\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.xhnst6a986cfb7561f {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.xhnst6a986cfb7561f {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.xhnst6a986cfb7561f {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.xhnst6a986cfb7561f {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.xhnst6a986cfb7561f {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.xhnst6a986cfb7561f {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"intgi6a986cfb7560c\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.intgi6a986cfb7560c {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.intgi6a986cfb7560c {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.intgi6a986cfb7560c {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.intgi6a986cfb7560c {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.intgi6a986cfb7560c {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.intgi6a986cfb7560c {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>O escrit\u00f3rio Barci de Moraes recebeu R$ 80.223.654,94 do Banco Master por servi\u00e7os prestados ao banco entre fevereiro de 2024 e novembro de 2025. O contrato de presta\u00e7\u00e3o de servi\u00e7os durou 22 meses. Os servi\u00e7os foram interrompidos quando Daniel Vorcaro foi preso pela 1\u00aa vez na opera\u00e7\u00e3o Compliance Zero.<\/p>\n\n\n\n<p>O escrit\u00f3rio cobrava honor\u00e1rios mensais de R$ 3.646.529,77. O contrato original previa dura\u00e7\u00e3o de 36 meses. Detalhes do acordo circulam desde dezembro de 2025.<\/p>\n\n\n\n<p><em>Fonte: Poder360<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O escrit\u00f3rio Barci de Moraes recebeu R$ 80.223.654,94 do Banco Master por servi\u00e7os prestados ao banco entre fevereiro de 2024 e novembro de 2025.  <br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2026\/03\/16\/cunhada-do-ministro-alexandre-de-moraes-e-autora-do-codigo-de-etica-do-banco-master\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/52194"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=52194"}],"version-history":[{"count":3,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/52194\/revisions"}],"predecessor-version":[{"id":52198,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/52194\/revisions\/52198"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=52194"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=52194"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=52194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}