{"id":5203,"date":"2020-01-03T09:13:21","date_gmt":"2020-01-03T12:13:21","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=5203"},"modified":"2020-01-03T08:54:39","modified_gmt":"2020-01-03T11:54:39","slug":"regras-rigidas-sobre-roupas-impedem-o-acesso-de-mulheres-aos-tribunais","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2020\/01\/03\/regras-rigidas-sobre-roupas-impedem-o-acesso-de-mulheres-aos-tribunais\/","title":{"rendered":"Regras r\u00edgidas sobre roupas impedem o acesso de mulheres aos tribunais"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img loading=\"lazy\" width=\"680\" height=\"408\" src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2019\/12\/EFE6A002A568A701C1F36C55EDA94694D1FC_saias.jpg\" alt=\"\" class=\"wp-image-4617\" srcset=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2019\/12\/EFE6A002A568A701C1F36C55EDA94694D1FC_saias.jpg 680w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2019\/12\/EFE6A002A568A701C1F36C55EDA94694D1FC_saias-300x180.jpg 300w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/><figcaption>Reprodu\u00e7\u00e3o<\/figcaption><\/figure>\n\n\n\n<p>No Supremo Tribunal Federal (STF) os julgamentos come\u00e7am antes da sess\u00e3o. Quase sempre do lado de fora, na porta de acesso ao plen\u00e1rio, em frente \u00e0 Pra\u00e7a dos Tr\u00eas Poderes.S\u00e3o feitos por seguran\u00e7as que analisam detalhadamente a roupa dos que pretendem acompanhar os julgamentos, principalmente das mulheres. N\u00e3o raro, educadamente, um deles informa: \u201cA senhora n\u00e3o pode entrar vestida assim.\u201d<\/p>\n\n\n\n<p>Estudantes e jovens advogadas s\u00e3o maioria. Uma delas, flagrada pela reportagem, assistiria aos ministros pela primeira vez. Usava vestido de renda branco, pouco acima do joelho, e blusa com gola do tipo canoa e manga curta, que deixava parte dos ombros \u00e0 mostra.<\/p>\n\n\n\n<p>\u201cPor qu\u00ea?\u201d, reagiu. O seguran\u00e7a apontou para os bra\u00e7os dela. \u201cSe a senhora tiver um casaco\u201d, disse baixinho. Ela n\u00e3o tinha. Saiu da fila visivelmente constrangida, fez uma foto da fachada do pr\u00e9dio e foi embora.<\/p>\n\n\n\n<p>A cena \u00e9 corriqueira e, segundo o Conselho Federal da Ordem dos Advogados do Brasil (OAB), n\u00e3o se trata de uma exclusividade do STF.<\/p>\n\n\n\n<p>\u201cTemos problemas grav\u00edssimos no Brasil todo\u201d, afirma Daniela Lima de Andrade Borges, presidente das Comiss\u00f5es Nacionais da Mulher Advogada. \u201cNo Rio de Janeiro, h\u00e1 pouco tempo, uma ju\u00edza estava medindo a saia das mulheres com r\u00e9gua\u201d, conta ela, acrescentando que a comiss\u00e3o est\u00e1 levantando quais tribunais t\u00eam esse tipo de regra para que seja tomada uma medida conjunta pela entidade.<\/p>\n\n\n\n<p>O caso a que a advogada se refere ocorreu no F\u00f3rum de Iguaba Grande, interior do Rio de Janeiro, no m\u00eas de outubro. A ju\u00edza e diretora, Ma\u00edra Val\u00e9ria Veiga de Oliveira, colocou um aviso com a foto de uma mulher usando vestido, comprimento at\u00e9 o joelho, na entrada do pr\u00e9dio e determinou aos seguran\u00e7as que proibissem o ingresso de mulheres que estivessem com saia ou vestido acima daquele limite.<\/p>\n\n\n\n<p>A OAB denunciou o caso \u00e0 Corregedoria do Tribunal de Justi\u00e7a do Estado (TJ-RJ). Na \u00e9poca, a Associa\u00e7\u00e3o dos Magistrados do Estado do Rio de Janeiro (Amaerj) divulgou nota afirmando que a medida havia sido tomada pela ju\u00edza \u201cem raz\u00e3o do uso recorrente de vestimentas impr\u00f3prias no local\u201d. Negou, no entanto, que ela tivesse autorizado os seguran\u00e7as a medir as saias e vestidos das mulheres com r\u00e9gua.<\/p>\n\n\n\n<p>Outro epis\u00f3dio recente, cita Daniela, foi registrado no Estado de Rond\u00f4nia. Seguran\u00e7as do Tribunal de Justi\u00e7a (TJ-RO) teriam impedido a entrada de uma advogada com o argumento de que ela estava \u201ccom tudo para fora\u201d. A mulher vestia blusa preta, justa ao corpo, com manga tr\u00eas quartos e cal\u00e7a preta comprida.<\/p>\n\n\n\n<p>Nesse caso tamb\u00e9m houve rea\u00e7\u00e3o da OAB. A entidade publicou nota de rep\u00fadio e afirmou que estava atuando \u201cno enfrentamento das vistorias pelas quais as mulheres t\u00eam passado diariamente nas unidades judici\u00e1rias estaduais, que as exp\u00f5e ao constrangimento, a situa\u00e7\u00f5es vexat\u00f3rias e abusivas\u201d.<\/p>\n\n\n\n<p>No STF, quando questionados, os seguran\u00e7as informam que h\u00e1 uma norma da Presid\u00eancia sobre o traje adequado para acesso ao plen\u00e1rio. Em nota, a assessoria do presidente, ministro Dias Toffoli, informa que a \u00faltima altera\u00e7\u00e3o nas regras sobre as vestimentas foi feita em 2000, na gest\u00e3o do ministro Sep\u00falveda Pertence.<\/p>\n\n\n\n<p>Naquela ocasi\u00e3o, os ministros decidiram, por meio de medida administrativa, liberar \u00e0s mulheres o uso de cal\u00e7a. At\u00e9 ent\u00e3o, s\u00f3 podiam vestir saia ou vestido. Funcion\u00e1rios mais antigos do STF contam que a antiga norma gerou \u201cmuitos constrangimentos\u201d ao longo dos anos.<\/p>\n\n\n\n<p>Um dos epis\u00f3dios, muito falado, teria ocorrido nos anos 70. Uma advogada do Rio de Janeiro teria ido ao Supremo exclusivamente para fazer a defesa em um dos casos que seria julgado. Ela usava cal\u00e7a comprida e blazer. Proibida de entrar, teria tirado a cal\u00e7a e entrado s\u00f3 de calcinha e blazer. Os funcion\u00e1rios, por\u00e9m, j\u00e1 n\u00e3o sabem mais dizer se realmente aconteceu ou se a hist\u00f3ria foi se transformando com o passar dos anos. Mas ainda d\u00e1 muito o que falar.<\/p><div class=\"nxnve6a57a8863b6a4\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.nxnve6a57a8863b6a4 {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.nxnve6a57a8863b6a4 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.nxnve6a57a8863b6a4 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.nxnve6a57a8863b6a4 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.nxnve6a57a8863b6a4 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.nxnve6a57a8863b6a4 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"blnlm6a57a8863b686\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.blnlm6a57a8863b686 {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.blnlm6a57a8863b686 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.blnlm6a57a8863b686 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.blnlm6a57a8863b686 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.blnlm6a57a8863b686 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.blnlm6a57a8863b686 {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>A regra dos anos 2000 libera o uso de cal\u00e7a, saia ou vestido sociais, mas exige que as mulheres usem blazer. Na \u00e9poca em que foi feita a mudan\u00e7a no regimento, s\u00f3 o ministro Marco Aur\u00e9lio foi contra a maioria. Ele pretendia mais. Queria acabar tamb\u00e9m com a obrigatoriedade do casaco. Mas ficou vencido.<\/p>\n\n\n\n<p>Levou tempo at\u00e9 que uma ministra inaugurasse a nova regra. C\u00e1rmen L\u00facia, a primeira a usar cal\u00e7a no plen\u00e1rio, s\u00f3 o fez sete anos depois. Ela escolheu um terninho preto e uma blusa da mesma cor, com detalhes em renda, e colar de p\u00e9rolas. Virou not\u00edcia.<\/p>\n\n\n\n<p>Se levar em conta o que consta na regra, propriamente dita, pode-se dizer que houve uma evolu\u00e7\u00e3o. Os seguran\u00e7as do Supremo costumam vetar o uso de blusa com manga curta ou cavada, mas liberam a entrada se a manga for comprida \u2013 mesmo sem o blazer.<\/p>\n\n\n\n<p>\u201cMas isso faz pouco tempo\u201c, diz uma advogada que prefere n\u00e3o se identificar. \u201cNem na gest\u00e3o da ministra C\u00e1rmen era permitido. Os seguran\u00e7as costumavam emprestar blazer para quem estivessem sem. Eu mesma j\u00e1 passei por isso no come\u00e7o da carreira. Emprestaram um que cabia quase duas de mim\u201d, lembra.<\/p>\n\n\n\n<p>Na nota enviada, a assessoria do presidente n\u00e3o menciona se h\u00e1 a inten\u00e7\u00e3o de novas altera\u00e7\u00f5es no regimento do STF. Diz apenas que existem exce\u00e7\u00f5es para as vestimentas culturais \u2013 \u201ctrajes ind\u00edgenas e quilombolas, por exemplo\u201d \u2013 e destaca que as regras valem somente para aqueles que acompanharem as sess\u00f5es. \u201cPara entrar nas demais depend\u00eancias do tribunal, h\u00e1 uma flexibilidade maior.\u201d<\/p>\n\n\n\n<p>\u201c\u00c9 uma quest\u00e3o dif\u00edcil\u201d, avalia a advogada Cristiane Romano, s\u00f3cia do escrit\u00f3rio Machado Meyer, que atua constantemente nos tribunais superiores. \u201cPor um lado h\u00e1 a liberdade no vestir, mas por outro lado h\u00e1 trajes adequados para ir a um tribunal, \u00e0 festa ou \u00e0 praia. Deveria imperar a regra do bom senso.\u201d<\/p>\n\n\n\n<p>A presidente das Comiss\u00f5es Nacionais da Mulher Advogada do Conselho Federal da OAB, Daniela Lima de Andrade Borges, entende que n\u00e3o cabe aos tribunais fixar regras para as vestimentas de advogadas ou advogados \u2013 com exce\u00e7\u00e3o para audi\u00eancias e sustenta\u00e7\u00f5es orais, em que h\u00e1 exig\u00eancia de traje t\u00edpico.<\/p>\n\n\n\n<p>\u201cA OAB entende que \u00e9 compet\u00eancia dela regulamentar as vestimentas da advocacia. Existe inclusive decis\u00e3o do CNJ [Conselho Nacional de Justi\u00e7a] nesse sentido\u201d, diz.<\/p>\n\n\n\n<p>Para a advogada, as regulamenta\u00e7\u00f5es \u201cv\u00eam com julgamento moral\u201d e, muitas vezes, \u201cdentro de um recorte de discrimina\u00e7\u00e3o de g\u00eanero\u201d. \u201cS\u00e3o sempre nessa linha do tamanho da saia ou do decote\u201d, enfatiza.<\/p>\n\n\n\n<p>\u201cIsso restringe o direito da mulher de acessar os tribunais. O exerc\u00edcio da profiss\u00e3o fica comprometido e ainda h\u00e1 o constrangimento, principalmente, se estiver acompanhada do cliente.\u201d<\/p>\n\n\n\n<p>Valor<\/p>\n","protected":false},"excerpt":{"rendered":"<p>N\u00e3o raro, educadamente, um deles informa: \u201cA senhora n\u00e3o pode entrar vestida assim.\u201d<br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2020\/01\/03\/regras-rigidas-sobre-roupas-impedem-o-acesso-de-mulheres-aos-tribunais\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":5,"featured_media":4617,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5203"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=5203"}],"version-history":[{"count":1,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5203\/revisions"}],"predecessor-version":[{"id":5204,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5203\/revisions\/5204"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media\/4617"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=5203"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=5203"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=5203"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}