{"id":52027,"date":"2026-03-11T08:45:52","date_gmt":"2026-03-11T11:45:52","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=52027"},"modified":"2026-03-11T08:48:11","modified_gmt":"2026-03-11T11:48:11","slug":"mantida-legalidade-de-nomeacoes-de-aprovados-em-concurso-publico-em-parnamirim","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2026\/03\/11\/mantida-legalidade-de-nomeacoes-de-aprovados-em-concurso-publico-em-parnamirim\/","title":{"rendered":"Mantida legalidade de nomea\u00e7\u00f5es de aprovados em concurso p\u00fablico em Parnamirim"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"825\" height=\"470\" src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/03\/concurso.jpg\" alt=\"\" class=\"wp-image-52029\" srcset=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/03\/concurso.jpg 825w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/03\/concurso-300x171.jpg 300w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/03\/concurso-768x438.jpg 768w\" sizes=\"(max-width: 825px) 100vw, 825px\" \/><figcaption>Foto: Reprodu\u00e7\u00e3o<\/figcaption><\/figure>\n\n\n\n<p>A legalidade das nomea\u00e7\u00f5es de 32 candidatos aprovados no concurso p\u00fablico para o cargo de agente de combate \u00e0s endemias do Munic\u00edpio de Parnamirim foi mantida pelo Tribunal de Justi\u00e7a do Rio Grande do Norte (TJRN). A decis\u00e3o confirmou senten\u00e7a de primeiro grau que havia julgado improcedente A\u00e7\u00e3o Popular que questionava os atos administrativos.<\/p>\n\n\n\n<p>A senten\u00e7a judicial havia sido proferida pelo juiz Airton Pinheiro, da 2\u00aa Vara da Fazenda P\u00fablica da Comarca de Parnamirim, que concluiu pela regularidade das nomea\u00e7\u00f5es, realizadas dentro do prazo de validade do concurso e em conformidade com os princ\u00edpios da Administra\u00e7\u00e3o P\u00fablica.<\/p>\n\n\n\n<p>Na a\u00e7\u00e3o, os autores alegavam que o edital previa apenas uma vaga para o cargo e que a convoca\u00e7\u00e3o de candidatos al\u00e9m desse n\u00famero seria ilegal. Ao analisar o caso, o magistrado destacou que a Administra\u00e7\u00e3o P\u00fablica pode nomear candidatos aprovados conforme a necessidade do servi\u00e7o, desde que o certame esteja vigente, o que ocorreu no caso concreto.<\/p>\n\n\n\n<p>O juiz tamb\u00e9m ressaltou que n\u00e3o foi demonstrado qualquer dano ao er\u00e1rio ou \u00e0 moralidade administrativa, requisitos essenciais para o acolhimento de a\u00e7\u00e3o popular. Segundo a senten\u00e7a, a substitui\u00e7\u00e3o de v\u00ednculos tempor\u00e1rios por servidores efetivos aprovados em concurso p\u00fablico n\u00e3o configura ilegalidade, mas refor\u00e7a o princ\u00edpio constitucional do concurso como forma regular de ingresso no servi\u00e7o p\u00fablico.<\/p><div class=\"tntdm6a98885e95c06\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.tntdm6a98885e95c06 {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.tntdm6a98885e95c06 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.tntdm6a98885e95c06 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.tntdm6a98885e95c06 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.tntdm6a98885e95c06 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.tntdm6a98885e95c06 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"drxiq6a98885e95bf4\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.drxiq6a98885e95bf4 {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.drxiq6a98885e95bf4 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.drxiq6a98885e95bf4 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.drxiq6a98885e95bf4 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.drxiq6a98885e95bf4 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.drxiq6a98885e95bf4 {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>Em grau de recurso, a desembargadora Martha Danyelle Santanna Costa Barbosa, relatora do processo na 2\u00aa C\u00e2mara C\u00edvel do TJRN, confirmou integralmente a senten\u00e7a proferida pelo juiz Airton Pinheiro, mantendo o entendimento de que as nomea\u00e7\u00f5es foram legais. No ac\u00f3rd\u00e3o, a relatora destacou que a nomea\u00e7\u00e3o de candidatos aprovados al\u00e9m do n\u00famero inicial de vagas, quando realizada dentro do prazo de validade do concurso, n\u00e3o configura ilegalidade, especialmente na aus\u00eancia de prova de preju\u00edzo ao patrim\u00f4nio p\u00fablico.<\/p>\n\n\n\n<p>Tamb\u00e9m foi considerado o per\u00edodo de suspens\u00e3o dos prazos de validade dos concursos p\u00fablicos durante a pandemia da Covid-19, o que manteve o certame vigente \u00e0 \u00e9poca das nomea\u00e7\u00f5es. Com isso, o Tribunal reafirmou a regularidade dos atos administrativos praticados pelo Munic\u00edpio de Parnamirim, consolidando o entendimento de que a Administra\u00e7\u00e3o P\u00fablica pode convocar candidatos aprovados conforme a necessidade do servi\u00e7o, desde que observados os limites legais.<\/p>\n\n\n\n<p><em>Fonte: TJRN<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ao analisar o caso, o magistrado destacou que a Administra\u00e7\u00e3o P\u00fablica pode nomear candidatos aprovados conforme a necessidade do servi\u00e7o, desde que o certame esteja vigente,<br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2026\/03\/11\/mantida-legalidade-de-nomeacoes-de-aprovados-em-concurso-publico-em-parnamirim\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/52027"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=52027"}],"version-history":[{"count":3,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/52027\/revisions"}],"predecessor-version":[{"id":52031,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/52027\/revisions\/52031"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=52027"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=52027"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=52027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}