{"id":5196,"date":"2020-01-02T16:39:05","date_gmt":"2020-01-02T19:39:05","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=5196"},"modified":"2020-01-02T16:39:05","modified_gmt":"2020-01-02T19:39:05","slug":"juiza-em-minas-manda-advogado-calar-a-boca-e-o-chama-de-pessimo-profissional","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2020\/01\/02\/juiza-em-minas-manda-advogado-calar-a-boca-e-o-chama-de-pessimo-profissional\/","title":{"rendered":"Ju\u00edza em Minas manda advogado calar a boca e o chama de p\u00e9ssimo profissional"},"content":{"rendered":"\n<p>Um v\u00eddeo de uma audi\u00eancia conturbada em Minas Gerais viralizou e deixou muitos advogados indignados. A situa\u00e7\u00e3o envolveu a ju\u00edza Andr\u00e9a Cristina de Miranda Costa, da 2\u00aa Vara de T\u00f3xicos da Comarca de Belo Horizonte, e os advogados\u00a0<strong>Dario Dias dos Santos<\/strong>,\u00a0<strong>Jaqueline Tavares da Silva Rocha<\/strong>\u00a0e\u00a0<strong>Francieles Angelis Sales<\/strong>.\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" width=\"640\" height=\"427\" src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2019\/08\/justica-1.jpg\" alt=\"\" class=\"wp-image-1055\" srcset=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2019\/08\/justica-1.jpg 640w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2019\/08\/justica-1-300x200.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><figcaption>Reprodu\u00e7\u00e3o<\/figcaption><\/figure>\n\n\n\n<p>As imagens foram enviadas para o advogado&nbsp;<strong>M\u00e1rio De Oliveira Filho<\/strong>, presidente da comiss\u00e3o de direitos e prerrogativas da Associa\u00e7\u00e3o Brasileira de Advogados Criminalistas (Abracrim), que denunciou o caso em suas redes sociais.<\/p>\n\n\n\n<p>No&nbsp;<a href=\"https:\/\/www.instagram.com\/tv\/B6OCTnLDGTI\/?igshid=4wnk6gwu4eh9\" target=\"_blank\" rel=\"noreferrer noopener\">v\u00eddeo<\/a>, a magistrada chama o advogado de mal educado ap\u00f3s ele pedir a palavra pela ordem. A ju\u00edza grita com o advogado e diz que ele \u00e9 um p\u00e9ssimo profissional.&nbsp;<\/p>\n\n\n\n<p>Em entrevista \u00e0&nbsp;<strong>ConJur<\/strong>, o advogado Dario Dias dos Santos afirmou que j\u00e1 havia tido problemas anteriormente com a magistrada em quest\u00e3o. \u201cEssa ju\u00edza agride verbalmente os r\u00e9us, grita com advogados (&#8230;) bate na mesa. \u00c9 o terceiro embate que eu j\u00e1 tive com ela\u201d, explica.<\/p><div class=\"waehk6a57ccfc38b1e\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.waehk6a57ccfc38b1e {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.waehk6a57ccfc38b1e {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.waehk6a57ccfc38b1e {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.waehk6a57ccfc38b1e {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.waehk6a57ccfc38b1e {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.waehk6a57ccfc38b1e {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"vhjou6a57ccfc38afe\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.vhjou6a57ccfc38afe {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.vhjou6a57ccfc38afe {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.vhjou6a57ccfc38afe {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.vhjou6a57ccfc38afe {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.vhjou6a57ccfc38afe {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.vhjou6a57ccfc38afe {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>\u201cEu achei importante divulgar o caso, pois estamos no limiar do come\u00e7o da vig\u00eancia da Lei de Abuso de Autoridade, e isso tem que mudar\u201d, diz.<\/p>\n\n\n\n<p>Dario relatou os fatos do v\u00eddeo para o delegado de prerrogativas da OAB-MG, Jos\u00e9 Ant\u00f4nio Guimar\u00e3es Fraga, que assinou um auto de constata\u00e7\u00e3o. O documento diz que a \u201cmagistrada se dirigiu ao Solicitante de maneira descort\u00eas, ofensiva, inapropriada, deselegante e inoportuna\u201d, e recomenda a representa\u00e7\u00e3o da ju\u00edza perante \u00e0&nbsp;Corregedoria do Conselho Nacional de Justi\u00e7a.<\/p>\n\n\n\n<p>A Associa\u00e7\u00e3o dos Magistrados Mineiros se pronunciou sobre o caso e emitiu uma nota de apoio a ju\u00edza.<\/p>\n\n\n\n<p>Conjur<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Associa\u00e7\u00e3o dos Magistrados Mineiros se pronunciou sobre o caso e emitiu uma nota de apoio a ju\u00edza.<br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2020\/01\/02\/juiza-em-minas-manda-advogado-calar-a-boca-e-o-chama-de-pessimo-profissional\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":5,"featured_media":1055,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5196"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=5196"}],"version-history":[{"count":1,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5196\/revisions"}],"predecessor-version":[{"id":5197,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5196\/revisions\/5197"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media\/1055"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=5196"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=5196"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=5196"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}