{"id":51852,"date":"2026-03-06T18:54:53","date_gmt":"2026-03-06T21:54:53","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=51852"},"modified":"2026-03-06T19:02:51","modified_gmt":"2026-03-06T22:02:51","slug":"alexandre-de-moraes-diz-que-mensagens-no-celular-de-vorcaro-nao-sao-do-numero-dele","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2026\/03\/06\/alexandre-de-moraes-diz-que-mensagens-no-celular-de-vorcaro-nao-sao-do-numero-dele\/","title":{"rendered":"Alexandre de Moraes diz que mensagens no celular de Vorcaro n\u00e3o s\u00e3o do n\u00famero dele"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"799\" height=\"584\" src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/03\/moraes.jpg\" alt=\"\" class=\"wp-image-51857\" srcset=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/03\/moraes.jpg 799w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/03\/moraes-300x219.jpg 300w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2026\/03\/moraes-768x561.jpg 768w\" sizes=\"(max-width: 799px) 100vw, 799px\" \/><figcaption>Foto: Rosinei Coutinho\/STF<\/figcaption><\/figure>\n\n\n\n<p>O ministro Alexandre de Moraes, do Supremo Tribunal Federal (STF), afirmou por meio de nota que \u201can\u00e1lise t\u00e9cnica realizada nos dados telem\u00e1ticos de Daniel Vorcaro, tornados p\u00fablicos pela CPMI do INSS, constatou que as mensagens de visualiza\u00e7\u00e3o \u00fanica enviadas por ele no dia 17 de novembro de 2025 n\u00e3o conferem com os contatos do ministro Alexandre de Moraes nos arquivos apreendidos\u201d.<\/p>\n\n\n\n<p>Segundo a nota do ministro do STF, no conte\u00fado extra\u00eddo do celular do banqueiro pelos investigadores, os prints dessas mensagens enviadas por Vorcaro est\u00e3o vinculadas a pastas de outras pessoas da sua lista de contatos e n\u00e3o constam como direcionadas a Moraes.<\/p><div class=\"kmisb6a989684ae998\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.kmisb6a989684ae998 {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.kmisb6a989684ae998 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.kmisb6a989684ae998 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.kmisb6a989684ae998 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.kmisb6a989684ae998 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.kmisb6a989684ae998 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"msbnz6a989684ae97c\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.msbnz6a989684ae97c {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.msbnz6a989684ae97c {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.msbnz6a989684ae97c {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.msbnz6a989684ae97c {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.msbnz6a989684ae97c {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.msbnz6a989684ae97c {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>\u201cA mensagem e o respectivo contato est\u00e3o na mesma pasta do computador de quem fez os prints (Vorcaro). Ou seja, fica demonstrado que as mensagens (prints) est\u00e3o vinculadas a outros contatos telef\u00f4nicos no computador de Daniel Vorcaro, jamais ao ministro Alexandre de Moraes\u201d, diz a nota.<br><br><em>Fonte: Metr\u00f3poles<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Segundo nota do ministro do STF, prints encontrados no celular do banqueiro mostram que as mensagens de Vorcaro estavam vinculadas a pastas de outros contatos e n\u00e3o direcionadas a Moraes.<br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2026\/03\/06\/alexandre-de-moraes-diz-que-mensagens-no-celular-de-vorcaro-nao-sao-do-numero-dele\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/51852"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=51852"}],"version-history":[{"count":3,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/51852\/revisions"}],"predecessor-version":[{"id":51858,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/51852\/revisions\/51858"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=51852"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=51852"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=51852"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}