{"id":51680,"date":"2026-03-02T20:08:32","date_gmt":"2026-03-02T23:08:32","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=51680"},"modified":"2026-03-02T20:09:56","modified_gmt":"2026-03-02T23:09:56","slug":"datena-e-pablo-marcal-fazem-acordo-na-justica-para-engavetar-acoes-da-cadeirada","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2026\/03\/02\/datena-e-pablo-marcal-fazem-acordo-na-justica-para-engavetar-acoes-da-cadeirada\/","title":{"rendered":"Datena e Pablo Mar\u00e7al fazem acordo na Justi\u00e7a para engavetar a\u00e7\u00f5es da \u2018cadeirada\u2019"},"content":{"rendered":"\n<p>Um dos momentos mais pol\u00eamicos da campanha \u00e0 prefeitura de S\u00e3o Paulo em 2024 chegou ao fim. O apresentador Jos\u00e9 Luiz Datena e o coach Pablo Mar\u00e7al fizeram um acordo na Justi\u00e7a para encerrar as a\u00e7\u00f5es judiciais que movem um contra o outro por causa do epis\u00f3dio da cadeirada. A homologa\u00e7\u00e3o do acordo foi publicada no Di\u00e1rio de Justi\u00e7a nesta segunda-feira, 2.<\/p>\n\n\n\n<p>Ao longo de toda a campanha, Mar\u00e7al se notabilizou pelas sucessivas provoca\u00e7\u00f5es aos advers\u00e1rios. Em um debate na TV Cultura no dia 15 de setembro de 2024, ele chamou Datena de \u201cjack\u201d, uma g\u00edria usada para se referir a estupradores. A organiza\u00e7\u00e3o havia pedido ao <em>coach<\/em> sucessivas vezes para que ele seguisse as regras do debate, mas Datena se irritou e bateu em Mar\u00e7al com a cadeira em que estava sentado.<\/p>\n\n\n\n<p>Depois disso, os dois moveram a\u00e7\u00f5es um contra o outro nas esferas c\u00edvel, criminal e eleitoral. O pacto entre os dois advers\u00e1rios engaveta todos esses processos, mas n\u00e3o menciona se alguma das partes pagou valores \u00e0 outra. Os dois foram \u00e0 audi\u00eancia de concilia\u00e7\u00e3o no dia 8 de outubro e sinalizaram a inten\u00e7\u00e3o de chegar a um acordo. O caso ficou suspenso por alguns dias, enquanto as defesas dos dois lados combinaram os termos dessa negocia\u00e7\u00e3o.<\/p><div class=\"kddoz6a98a1c869841\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.kddoz6a98a1c869841 {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.kddoz6a98a1c869841 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.kddoz6a98a1c869841 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.kddoz6a98a1c869841 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.kddoz6a98a1c869841 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.kddoz6a98a1c869841 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"fwpdi6a98a1c869823\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.fwpdi6a98a1c869823 {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.fwpdi6a98a1c869823 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.fwpdi6a98a1c869823 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.fwpdi6a98a1c869823 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.fwpdi6a98a1c869823 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.fwpdi6a98a1c869823 {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>A ju\u00edza da 30\u00aa Vara C\u00edvel da capital paulista, Priscilla Bittar Neves Netto, homologou o acordo na \u00faltima sexta, 27. Os dois lados renunciaram ao direito de discutir o assunto de novo na Justi\u00e7a e de apresentarem recursos judiciais sobre o tema.<\/p>\n\n\n\n<p>No come\u00e7o deste ano, Datena saiu da RedeTV! e foi para a EBC, emissora p\u00fablica ligada ao governo federal. Em 2024, ele fez menos de 2% dos votos na disputa eleitoral. Mar\u00e7al, por outro lado, quase chegou ao segundo turno, mas saiu derrotado e com v\u00e1rios problemas com a Justi\u00e7a. Ele j\u00e1 foi declarado ineleg\u00edvel tr\u00eas vezes e, no caso do laudo falso divulgado contra Guilherme Boulos (PSOL), fez um acordo com o Minist\u00e9rio P\u00fablico para ter a a\u00e7\u00e3o penal arquivada.<br><br><em>Fonte: Veja<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img alt=\"\"\/><\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os dois foram \u00e0 audi\u00eancia de concilia\u00e7\u00e3o no dia 8 de outubro e sinalizaram a inten\u00e7\u00e3o de chegar a um acordo.<br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2026\/03\/02\/datena-e-pablo-marcal-fazem-acordo-na-justica-para-engavetar-acoes-da-cadeirada\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/51680"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=51680"}],"version-history":[{"count":3,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/51680\/revisions"}],"predecessor-version":[{"id":51684,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/51680\/revisions\/51684"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=51680"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=51680"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=51680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}