{"id":47364,"date":"2025-10-06T09:44:22","date_gmt":"2025-10-06T12:44:22","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=47364"},"modified":"2025-10-06T13:06:15","modified_gmt":"2025-10-06T16:06:15","slug":"operadora-nao-pode-cancelar-unilateralmente-plano-de-paciente-com-cancer-2","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2025\/10\/06\/operadora-nao-pode-cancelar-unilateralmente-plano-de-paciente-com-cancer-2\/","title":{"rendered":"Operadora de sa\u00fade n\u00e3o pode cancelar unilateralmente plano de paciente com c\u00e2ncer"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/10\/esposa-visitando-seu-marido-doente-1024x683.jpg\" alt=\"\" class=\"wp-image-47365\" srcset=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/10\/esposa-visitando-seu-marido-doente-1024x683.jpg 1024w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/10\/esposa-visitando-seu-marido-doente-300x200.jpg 300w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/10\/esposa-visitando-seu-marido-doente-768x512.jpg 768w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/10\/esposa-visitando-seu-marido-doente-1536x1024.jpg 1536w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/10\/esposa-visitando-seu-marido-doente-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>Foto: Freepik<\/figcaption><\/figure>\n\n\n\n<p>A 4\u00aa C\u00e2mara de Direito Privado do Tribunal de Justi\u00e7a de S\u00e3o Paulo manteve uma decis\u00e3o da 5\u00aa Vara C\u00edvel do Foro Regional de Santo Amaro, na capital paulista, que determinou que uma operadora mantenha ativo o plano de sa\u00fade de um paciente em tratamento de c\u00e2ncer, nos termos da senten\u00e7a proferida pelo juiz Eurico Leonel Peixoto Filho.<\/p>\n\n\n\n<p>A empresa deve seguir as condi\u00e7\u00f5es contratadas at\u00e9 a alta m\u00e9dica, data em que o autor dever\u00e1 ser cientificado para o exerc\u00edcio do direito de requerer a portabilidade de car\u00eancia. Al\u00e9m disso, a requerida dever\u00e1 disponibilizar plano de mesma cobertura e valor, sem cumprimento de nova car\u00eancia.<\/p>\n\n\n\n<p>Segundo os autos, o autor foi diagnosticado com leucemia e fazia acompanhamento quando o plano cancelou unilateralmente o contrato.<\/p>\n\n\n\n<p>O relator do recurso, juiz substituto em segundo grau Vitor Frederico K\u00fcmpel, destacou que a rescis\u00e3o somente poderia ocorrer em caso de inadimpl\u00eancia superior a 60 dias, com pr\u00e9via comunica\u00e7\u00e3o, o que n\u00e3o ocorreu no caso em an\u00e1lise.<\/p><div class=\"ojdwg6a0447a9f40f4\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.ojdwg6a0447a9f40f4 {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.ojdwg6a0447a9f40f4 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.ojdwg6a0447a9f40f4 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.ojdwg6a0447a9f40f4 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.ojdwg6a0447a9f40f4 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.ojdwg6a0447a9f40f4 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"agygn6a0447a9f40df\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.agygn6a0447a9f40df {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.agygn6a0447a9f40df {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.agygn6a0447a9f40df {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.agygn6a0447a9f40df {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.agygn6a0447a9f40df {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.agygn6a0447a9f40df {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>O magistrado ainda afirmou que o cancelamento \u201cn\u00e3o pode resultar na interrup\u00e7\u00e3o de cuidados imprescind\u00edveis para a sobreviv\u00eancia e incolumidade f\u00edsica do benefici\u00e1rio\u201d e ressaltou que n\u00e3o haver\u00e1 preju\u00edzos \u00e0 operadora de sa\u00fade, uma vez que o autor continuar\u00e1 pagando as mensalidades.<\/p>\n\n\n\n<p>\u201cDiante dessas considera\u00e7\u00f5es, deve mesmo ser mantido o contrato at\u00e9 efetiva alta, sobretudo quando o bem protegido nesse caso \u00e9 a sa\u00fade e a vida do benefici\u00e1rio, que obrigatoriamente se sobrep\u00f5e a qualquer outro interesse de natureza contratual ou negocial\u201d, escreveu.<\/p>\n\n\n\n<p>Os desembargadores Enio Zuliani e Alcides Leopoldo completaram a turma de julgamento. A vota\u00e7\u00e3o foi un\u00e2nime. Com informa\u00e7\u00f5es da assessoria de imprensa do TJ-SP.<\/p>\n\n\n\n<p class=\"has-text-align-left\">Processo: 1043775-08.2024.8.26.0002<br><br><em>Fonte: Conjur<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Segundo os autos, o autor foi diagnosticado com leucemia e fazia acompanhamento quando o plano cancelou unilateralmente o contrato.<br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2025\/10\/06\/operadora-nao-pode-cancelar-unilateralmente-plano-de-paciente-com-cancer-2\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/47364"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=47364"}],"version-history":[{"count":4,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/47364\/revisions"}],"predecessor-version":[{"id":47376,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/47364\/revisions\/47376"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=47364"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=47364"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=47364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}