{"id":47343,"date":"2025-10-05T13:42:00","date_gmt":"2025-10-05T16:42:00","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=47343"},"modified":"2025-10-05T13:43:11","modified_gmt":"2025-10-05T16:43:11","slug":"custas-processuais-ja-podem-ser-pagas-via-pix-ou-cartao-na-justica-federal-da-5a-regiao","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2025\/10\/05\/custas-processuais-ja-podem-ser-pagas-via-pix-ou-cartao-na-justica-federal-da-5a-regiao\/","title":{"rendered":"Custas processuais j\u00e1 podem ser pagas via Pix ou cart\u00e3o na Justi\u00e7a Federal da 5\u00aa Regi\u00e3o"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1024\" height=\"1024\" src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/10\/pagamentos-moveis-pagamentos-de-varredura-movel-pagamentos-face-face-1024x1024.jpg\" alt=\"\" class=\"wp-image-47345\" srcset=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/10\/pagamentos-moveis-pagamentos-de-varredura-movel-pagamentos-face-face-1024x1024.jpg 1024w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/10\/pagamentos-moveis-pagamentos-de-varredura-movel-pagamentos-face-face-300x300.jpg 300w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/10\/pagamentos-moveis-pagamentos-de-varredura-movel-pagamentos-face-face-150x150.jpg 150w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/10\/pagamentos-moveis-pagamentos-de-varredura-movel-pagamentos-face-face-768x768.jpg 768w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/10\/pagamentos-moveis-pagamentos-de-varredura-movel-pagamentos-face-face-1536x1536.jpg 1536w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/10\/pagamentos-moveis-pagamentos-de-varredura-movel-pagamentos-face-face-2048x2048.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>Foto: Freepik<\/figcaption><\/figure>\n\n\n\n<p>A partir de agora, as custas processuais j\u00e1 podem ser pagas atrav\u00e9s de Pix ou cart\u00e3o de cr\u00e9dito na Justi\u00e7a Federal da 5\u00aa Regi\u00e3o (JF5). As novas modalidades de pagamento est\u00e3o dispon\u00edveis no Sistema de Custas, atrav\u00e9s do PagTesouro.<\/p>\n\n\n\n<p>O novo sistema de pagamentos \u00e9 uma plataforma digital do Tesouro Nacional que moderniza o recolhimento de receitas federais e substitui a Guia de Recolhimento da Uni\u00e3o (GRU). Ele permite que cidad\u00e3os(\u00e3s) e empresas paguem taxas, tarifas e outras receitas ao Governo Federal de forma totalmente eletr\u00f4nica, o que torna o processo mais r\u00e1pido, seguro, transparente e inclusivo.<\/p><div class=\"fpsyh6a04267a29898\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.fpsyh6a04267a29898 {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.fpsyh6a04267a29898 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.fpsyh6a04267a29898 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.fpsyh6a04267a29898 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.fpsyh6a04267a29898 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.fpsyh6a04267a29898 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"vmpgt6a04267a29885\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.vmpgt6a04267a29885 {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.vmpgt6a04267a29885 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.vmpgt6a04267a29885 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.vmpgt6a04267a29885 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.vmpgt6a04267a29885 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.vmpgt6a04267a29885 {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>A ado\u00e7\u00e3o do PagTesouro pela JF5 atende \u00e0 Recomenda\u00e7\u00e3o n\u00ba 164\/2025 do Conselho Nacional de Justi\u00e7a (CNJ), que determina aos tribunais e demais \u00f3rg\u00e3os do Poder Judici\u00e1rio a ado\u00e7\u00e3o do Pix como meio de pagamento de custas e de despesas processuais, de cumprimento de mandados de levantamento de valores vinculados a processos judiciais, em especial nas a\u00e7\u00f5es de execu\u00e7\u00e3o ou pedidos de cumprimento de senten\u00e7a, ou de remunera\u00e7\u00e3o dos demais protagonistas e auxiliares da Justi\u00e7a.<\/p>\n\n\n\n<p><em>Fonte: TRF5<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O novo sistema de pagamentos \u00e9 uma plataforma digital do Tesouro Nacional que moderniza o recolhimento de receitas federais e substitui a Guia de Recolhimento da Uni\u00e3o (GRU).<br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2025\/10\/05\/custas-processuais-ja-podem-ser-pagas-via-pix-ou-cartao-na-justica-federal-da-5a-regiao\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/47343"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=47343"}],"version-history":[{"count":4,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/47343\/revisions"}],"predecessor-version":[{"id":47348,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/47343\/revisions\/47348"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=47343"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=47343"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=47343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}