{"id":47333,"date":"2025-10-05T09:29:51","date_gmt":"2025-10-05T12:29:51","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=47333"},"modified":"2025-10-05T09:34:02","modified_gmt":"2025-10-05T12:34:02","slug":"falta-de-assistencia-gol-pagara-r-24-mil-por-cancelamento-de-voo","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2025\/10\/05\/falta-de-assistencia-gol-pagara-r-24-mil-por-cancelamento-de-voo\/","title":{"rendered":"Gol \u00e9 condenada por falhas em voo internacional e falta de assist\u00eancia aos passageiros"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"888\" height=\"592\" src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/10\/gol-.jpg\" alt=\"\" class=\"wp-image-47334\" srcset=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/10\/gol-.jpg 888w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/10\/gol--300x200.jpg 300w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/10\/gol--768x512.jpg 768w\" sizes=\"(max-width: 888px) 100vw, 888px\" \/><figcaption>Foto: Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n\n\n\n<p>O juiz de Direito Guilherme Pedrosa Lopes, da 50\u00aa vara C\u00edvel do RJ, condenou a Gol Linhas A\u00e9reas ao pagamento de indeniza\u00e7\u00e3o por falha na presta\u00e7\u00e3o de servi\u00e7o durante viagem internacional.<\/p>\n\n\n\n<p>O magistrado reconheceu a falha da companhia e afastou os argumentos de caso fortuito.<\/p>\n\n\n\n<p>Os passageiros adquiriram bilhetes na categoria Gol+ Conforto para voo de Curitiba\/PR a Canc\u00fan\/M\u00e9xico. A escolha pela categoria foi motivada por condi\u00e7\u00f5es m\u00e9dicas de dois dos viajantes, que demandavam maior conforto.<\/p>\n\n\n\n<p>Ap\u00f3s cerca de 20 minutos de voo, a aeronave apresentou alarme de despressuriza\u00e7\u00e3o e precisou retornar a Curitiba. Segundo os autores, n\u00e3o houve assist\u00eancia m\u00e9dica ou suporte adequado.<\/p>\n\n\n\n<p>O cancelamento do voo provocou a perda da conex\u00e3o e obrigou a fam\u00edlia a aceitar rota alternativa, com custos adicionais de hospedagem e transporte.<\/p><div class=\"ecqph6a040e4f4b194\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.ecqph6a040e4f4b194 {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.ecqph6a040e4f4b194 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.ecqph6a040e4f4b194 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.ecqph6a040e4f4b194 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.ecqph6a040e4f4b194 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.ecqph6a040e4f4b194 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"mjweo6a040e4f4b176\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.mjweo6a040e4f4b176 {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.mjweo6a040e4f4b176 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.mjweo6a040e4f4b176 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.mjweo6a040e4f4b176 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.mjweo6a040e4f4b176 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.mjweo6a040e4f4b176 {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>Relataram ainda que sofreram <em>downgrade<\/em> no trecho seguinte, um dos passageiros menor de idade viajou separado dos pais e a chegada ocorreu com 18 horas de atraso. No retorno, tiveram bagagem danificada, sendo ofertadas apenas milhas como compensa\u00e7\u00e3o.<\/p>\n\n\n\n<p>O juiz reconheceu a falha da companhia e afastou os argumentos de caso fortuito. Para ele, houve frustra\u00e7\u00e3o da leg\u00edtima expectativa do consumidor e aus\u00eancia de assist\u00eancia adequada.<\/p>\n\n\n\n<p>Assim, a empresa foi condenada a indenizar R$ 971,96 por danos materiais, referentes a despesas com transporte e bagagem danificada e R$ 24 mil por danos morais, sendo R$ 8 mil para cada passageiro.<\/p>\n\n\n\n<p>O magistrado destacou que o dano moral ultrapassou o mero aborrecimento, diante do cen\u00e1rio de inseguran\u00e7a, atraso expressivo e falta de suporte aos passageiros.<br><br><em>Fonte: Migalhas <\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O cancelamento do voo provocou a perda da conex\u00e3o e obrigou a fam\u00edlia a aceitar rota alternativa, com custos adicionais de hospedagem e transporte.<br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2025\/10\/05\/falta-de-assistencia-gol-pagara-r-24-mil-por-cancelamento-de-voo\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/47333"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=47333"}],"version-history":[{"count":4,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/47333\/revisions"}],"predecessor-version":[{"id":47338,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/47333\/revisions\/47338"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=47333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=47333"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=47333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}