{"id":47320,"date":"2025-10-04T18:16:12","date_gmt":"2025-10-04T21:16:12","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=47320"},"modified":"2025-10-04T18:16:12","modified_gmt":"2025-10-04T21:16:12","slug":"pm-ce-nega-recurso-e-manda-prender-soldado-que-gravou-video-lavando-viatura","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2025\/10\/04\/pm-ce-nega-recurso-e-manda-prender-soldado-que-gravou-video-lavando-viatura\/","title":{"rendered":"PM-CE nega recurso e manda prender soldado que gravou v\u00eddeo lavando viatura"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"974\" height=\"550\" src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/10\/policial-militar.jpg\" alt=\"\" class=\"wp-image-47321\" srcset=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/10\/policial-militar.jpg 974w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/10\/policial-militar-300x169.jpg 300w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/10\/policial-militar-768x434.jpg 768w\" sizes=\"(max-width: 974px) 100vw, 974px\" \/><figcaption>Foto: Reprodu\u00e7\u00e3o\/Instagram<\/figcaption><\/figure>\n\n\n\n<p>A policial militar Mayara Kelly Mota, advertida ap\u00f3s ter publicado em 2023 dois v\u00eddeos em sua conta em que aparecia lavando uma viatura e ensinando a fazer um torniquete, foi punida com dois dias de pris\u00e3o administrativa. A Pol\u00edcia Militar negou o recurso que ela havia apresentado, e Mayara dever\u00e1 cumprir a pena.<\/p>\n\n\n\n<p>&#8220;A Pol\u00edcia Militar do Cear\u00e1 (PMCE) informa que, ap\u00f3s an\u00e1lise de recursos apresentados pela defesa da policial, manteve a san\u00e7\u00e3o disciplinar aplicada anteriormente&#8221;, respondeu a PM.<\/p>\n\n\n\n<p>Mayara explicou em seu Instagram que vai ficar dois dias no quartel sem poder ir para casa. &#8220;\u00c9 uma san\u00e7\u00e3o grave a qual eu nunca pensei em ter na minha ficha, pois para mim nunca cometeria algo que pudesse manchar meu assentamento disciplinar durante minha caminhada aqui&#8221;, lamentou.<\/p>\n\n\n\n<p>A agente disse que gravou os v\u00eddeos porque estava orgulhosa de seu servi\u00e7o e que n\u00e3o imaginava que o conte\u00fado pudesse lhe prejudicar.<\/p>\n\n\n\n<p>&#8220;Irei cumprir minha puni\u00e7\u00e3o de cabe\u00e7a erguida, mas a partir desse momento eu nunca mais postarei nada sobre minha profiss\u00e3o, n\u00e3o haver\u00e1 mais foto alguma no meu perfil, vou deixar para quem pode e quem ainda se orgulha da farda que usa&#8221;, escreveu a policial.<\/p>\n\n\n\n<p>Ela ainda disse que vai voltar a estudar para conseguir outro trabalho: &#8220;Em que eu me sinta valorizada e onde eu possa compartilhar com orgulho aonde eu consegui chegar com esfor\u00e7o e dedica\u00e7\u00e3o&#8221;.<\/p><div class=\"oyalc6a03e7b92b1d4\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.oyalc6a03e7b92b1d4 {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.oyalc6a03e7b92b1d4 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.oyalc6a03e7b92b1d4 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.oyalc6a03e7b92b1d4 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.oyalc6a03e7b92b1d4 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.oyalc6a03e7b92b1d4 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"nobgs6a03e7b92b1bd\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.nobgs6a03e7b92b1bd {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.nobgs6a03e7b92b1bd {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.nobgs6a03e7b92b1bd {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.nobgs6a03e7b92b1bd {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.nobgs6a03e7b92b1bd {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.nobgs6a03e7b92b1bd {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>A policial militar Mayara Kelly Mota recebeu uma san\u00e7\u00e3o disciplinar ap\u00f3s publicar v\u00eddeos nas redes sociais em que aparece lavando uma viatura e ensinando a fazer um torniquete. Segundo a corpora\u00e7\u00e3o, a agente violou o C\u00f3digo Disciplinar Militar ao se promover com a farda militar. A decis\u00e3o determinava dois dias de perman\u00eancia no quartel, mas cabia recurso. No entanto, o recurso foi negado.<\/p>\n\n\n\n<p>A policial acumula mais de 46 mil seguidores no Instagram, onde ela costuma compartilhar v\u00eddeos sobre sua rotina como m\u00e3e. No passado, ela tamb\u00e9m publicava conte\u00fados relacionados \u00e0 sua profiss\u00e3o, sendo que a maioria desses v\u00eddeos foi feita em 2023.<\/p>\n\n\n\n<p>Em um dos v\u00eddeos citados na decis\u00e3o da Pol\u00edcia Militar, publicado no dia 22 de abril de 2023, Mayara aparece lavando uma viatura em um quartel. Na grava\u00e7\u00e3o, ela comenta sobre as fun\u00e7\u00f5es exercidas por mulheres na corpora\u00e7\u00e3o, como patrulheira e motorista.<\/p>\n\n\n\n<p>&#8220;Algumas pessoas acham que a mulher na pol\u00edcia s\u00f3 trabalha no administrativo. Mal sabe eles que exercemos in\u00fameras fun\u00e7\u00f5es que at\u00e9 uns anos atr\u00e1s poderiam ser consideradas apenas coisas para homem&#8221;, declara no v\u00eddeo.<\/p>\n\n\n\n<p>Em outra filmagem, Mayara aparece, fardada, ensinando como usar um torniquete. A publica\u00e7\u00e3o foi feita no dia 18 de julho de 2023.<\/p>\n\n\n\n<p>A Pol\u00edcia Militar afirmou que a sindic\u00e2ncia realizada com a policial militar seguiu todos os procedimentos legais previstos no C\u00f3digo Disciplinar, garantindo ampla defesa e o direito ao contradit\u00f3rio. A corpora\u00e7\u00e3o refor\u00e7ou que a decis\u00e3o est\u00e1 sujeita a recurso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A agente disse que gravou os v\u00eddeos porque estava orgulhosa de seu servi\u00e7o e que n\u00e3o imaginava que o conte\u00fado pudesse lhe prejudicar.<br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2025\/10\/04\/pm-ce-nega-recurso-e-manda-prender-soldado-que-gravou-video-lavando-viatura\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/47320"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=47320"}],"version-history":[{"count":1,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/47320\/revisions"}],"predecessor-version":[{"id":47322,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/47320\/revisions\/47322"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=47320"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=47320"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=47320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}