{"id":45665,"date":"2025-08-13T07:42:43","date_gmt":"2025-08-13T10:42:43","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=45665"},"modified":"2025-08-13T07:48:55","modified_gmt":"2025-08-13T10:48:55","slug":"empresa-de-viagens-deve-indenizar-passageiros-em-r-13-mil-apos-cancelamento-de-voo-a-gramado","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2025\/08\/13\/empresa-de-viagens-deve-indenizar-passageiros-em-r-13-mil-apos-cancelamento-de-voo-a-gramado\/","title":{"rendered":"Empresa de viagens deve indenizar passageiros ap\u00f3s cancelamento de voo a Gramado"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1024\" height=\"681\" src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/08\/viagem-lateral-viajante-com-mala-1024x681.jpg\" alt=\"\" class=\"wp-image-45668\" srcset=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/08\/viagem-lateral-viajante-com-mala-1024x681.jpg 1024w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/08\/viagem-lateral-viajante-com-mala-300x200.jpg 300w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/08\/viagem-lateral-viajante-com-mala-768x511.jpg 768w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/08\/viagem-lateral-viajante-com-mala-1536x1022.jpg 1536w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/08\/viagem-lateral-viajante-com-mala-2048x1363.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>Imagem: Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n\n\n\n<p>O Poder Judici\u00e1rio do Rio Grande do Norte determinou que uma ag\u00eancia de viagens indenizasse um casal de passageiros ap\u00f3s o cancelamento de uma viagem para Gramado e a n\u00e3o restitui\u00e7\u00e3o dos valores pagos. A decis\u00e3o foi tomada pelo juiz Fl\u00e1vio Ricardo Pires, do 2\u00ba Juizado Especial C\u00edvel, Criminal e da Fazenda P\u00fablica de Parnamirim. A empresa foi condenada a devolver R$ 7.773,24 aos autores, al\u00e9m de pagar R$ 3 mil em danos morais para cada um dos clientes.<\/p>\n\n\n\n<p>O casal, juntamente com amigos, adquiriu um pacote de viagem para Gramado com a ag\u00eancia, que oferecia voos de Natal para Porto Alegre, com partida prevista para 4 de outubro de 2023. O custo total do pacote foi de R$ 4.633,86. No entanto, antes da data da viagem, os passageiros foram surpreendidos por not\u00edcias na m\u00eddia informando o cancelamento de pacotes e passagens promocionais da empresa entre setembro e dezembro de 2023. A ag\u00eancia ofereceu a devolu\u00e7\u00e3o do valor atrav\u00e9s de vouchers.<\/p>\n\n\n\n<p>Quando tentaram utilizar os vouchers para hospedar-se em Porto de Galinhas, os passageiros descobriram que o resgate estava temporariamente suspenso. Pesquisas na internet revelaram que a empresa enfrentava dificuldades para emitir novos vouchers e processar os antigos, sem qualquer previs\u00e3o de normaliza\u00e7\u00e3o da situa\u00e7\u00e3o. A empresa n\u00e3o forneceu solu\u00e7\u00f5es ou estimativas para os clientes lesados.<\/p><div class=\"upcoa6a581a30bde77\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.upcoa6a581a30bde77 {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.upcoa6a581a30bde77 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.upcoa6a581a30bde77 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.upcoa6a581a30bde77 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.upcoa6a581a30bde77 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.upcoa6a581a30bde77 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"qsqao6a581a30bde5f\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.qsqao6a581a30bde5f {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.qsqao6a581a30bde5f {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.qsqao6a581a30bde5f {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.qsqao6a581a30bde5f {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.qsqao6a581a30bde5f {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.qsqao6a581a30bde5f {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>Na defesa, a ag\u00eancia alegou que o atraso na presta\u00e7\u00e3o dos servi\u00e7os ocorreu devido a dificuldades econ\u00f4micas, mas negou a exist\u00eancia de danos materiais ou morais. No entanto, o juiz considerou que a justificativa n\u00e3o foi suficiente para justificar o descumprimento do contrato e que n\u00e3o havia provas que respaldassem a defesa da empresa.<\/p>\n\n\n\n<p>O juiz concluiu que a ag\u00eancia falhou na presta\u00e7\u00e3o dos servi\u00e7os e que o ocorrido configurou um ato il\u00edcito, resultando em danos para os consumidores. A decis\u00e3o reafirma a responsabilidade da empresa pela falha contratual e a necessidade de repara\u00e7\u00e3o financeira aos clientes afetados.<br><br><em>Fonte: TJRN<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O juiz concluiu que a ag\u00eancia falhou na presta\u00e7\u00e3o dos servi\u00e7os e que o ocorrido configurou um ato il\u00edcito, resultando em danos para os consumidores. <br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2025\/08\/13\/empresa-de-viagens-deve-indenizar-passageiros-em-r-13-mil-apos-cancelamento-de-voo-a-gramado\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/45665"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=45665"}],"version-history":[{"count":3,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/45665\/revisions"}],"predecessor-version":[{"id":45670,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/45665\/revisions\/45670"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=45665"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=45665"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=45665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}