{"id":45629,"date":"2025-08-12T15:56:57","date_gmt":"2025-08-12T18:56:57","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=45629"},"modified":"2025-08-12T16:20:21","modified_gmt":"2025-08-12T19:20:21","slug":"tjpe-atualiza-pje-para-combater-golpe-do-falso-advogado-apos-apos-pedido-da-oab-pe","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2025\/08\/12\/tjpe-atualiza-pje-para-combater-golpe-do-falso-advogado-apos-apos-pedido-da-oab-pe\/","title":{"rendered":"TJPE atualiza PJe para combater golpe do falso advogado ap\u00f3s pedido da OAB-PE"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2023-03-28-at-11.40.03-1024x683.jpeg\" alt=\"\" class=\"wp-image-45632\" srcset=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2023-03-28-at-11.40.03-1024x683.jpeg 1024w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2023-03-28-at-11.40.03-300x200.jpeg 300w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2023-03-28-at-11.40.03-768x512.jpeg 768w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2023-03-28-at-11.40.03-1536x1024.jpeg 1536w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2023-03-28-at-11.40.03.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>Foto: Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n\n\n\n<p>A Ordem dos Advogados do Brasil \u2013 Seccional Pernambuco (OAB-PE) comemora uma conquista importante na luta contra o golpe do falso advogado. Fruto de um di\u00e1logo institucional permanente com o Tribunal de Justi\u00e7a de Pernambuco (TJPE), foi poss\u00edvel identificar a necessidade de refor\u00e7ar a prote\u00e7\u00e3o dos processos eletr\u00f4nicos, que, por serem p\u00fablicos, exigem um controle mais rigoroso de acesso.<\/p>\n\n\n\n<p>Como resultado dessa atua\u00e7\u00e3o conjunta, o TJPE lan\u00e7ou uma nova vers\u00e3o do sistema de Processo Judicial Eletr\u00f4nico (PJe), que traz uma inova\u00e7\u00e3o fundamental: a partir de agora, apenas advogadas e advogados devidamente logados no sistema ter\u00e3o acesso a processos de terceiros. A medida amplia a seguran\u00e7a e previne o uso indevido de informa\u00e7\u00f5es por pessoas n\u00e3o habilitadas.<\/p>\n\n\n\n<p>\u201c\u00c9 atrav\u00e9s desse di\u00e1logo e dessa constru\u00e7\u00e3o que a OAB de Pernambuco vai sempre pugnar pela seguran\u00e7a do Judici\u00e1rio e, principalmente, pela valoriza\u00e7\u00e3o da nossa profiss\u00e3o. Todos juntos no combate ao golpe do falso advogado\u201d, destacou a presidente da OAB-PE, Ingrid Zanella.<\/p><div class=\"eugdt6a581a6d33a31\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.eugdt6a581a6d33a31 {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.eugdt6a581a6d33a31 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.eugdt6a581a6d33a31 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.eugdt6a581a6d33a31 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.eugdt6a581a6d33a31 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.eugdt6a581a6d33a31 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"uwctj6a581a6d33a11\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.uwctj6a581a6d33a11 {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.uwctj6a581a6d33a11 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.uwctj6a581a6d33a11 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.uwctj6a581a6d33a11 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.uwctj6a581a6d33a11 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.uwctj6a581a6d33a11 {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>Essa iniciativa representa um avan\u00e7o na prote\u00e7\u00e3o dos processos eletr\u00f4nicos, garantindo mais seguran\u00e7a \u00e0 sociedade e \u00e0 advocacia pernambucana, al\u00e9m de refor\u00e7ar a integridade do exerc\u00edcio profissional no ambiente digital.<\/p>\n\n\n\n<p><em>Fonte: OAB-PE<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O TJPE lan\u00e7ou uma nova vers\u00e3o do sistema de Processo Judicial Eletr\u00f4nico (PJe), que traz uma inova\u00e7\u00e3o fundamental: a partir de agora, apenas advogadas e advogados devidamente logados no sistema ter\u00e3o acesso a processos de terceiros. <br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2025\/08\/12\/tjpe-atualiza-pje-para-combater-golpe-do-falso-advogado-apos-apos-pedido-da-oab-pe\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/45629"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=45629"}],"version-history":[{"count":8,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/45629\/revisions"}],"predecessor-version":[{"id":45639,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/45629\/revisions\/45639"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=45629"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=45629"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=45629"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}