{"id":45621,"date":"2025-08-12T09:41:39","date_gmt":"2025-08-12T12:41:39","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=45621"},"modified":"2025-08-12T09:41:39","modified_gmt":"2025-08-12T12:41:39","slug":"empresarios-e-auditor-fiscal-sao-presos-em-operacao-do-ministerio-publico-de-sp","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2025\/08\/12\/empresarios-e-auditor-fiscal-sao-presos-em-operacao-do-ministerio-publico-de-sp\/","title":{"rendered":"Empres\u00e1rios e auditor fiscal s\u00e3o presos em opera\u00e7\u00e3o do Minist\u00e9rio P\u00fablico de SP"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"878\" height=\"498\" src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/08\/https__img.migalhas.com_.br__SL__gf_base__SL__empresas__SL__MIGA__SL__imagens__SL__2025__SL__08__SL__12__SL__cropped_1qamszf1.4zh.png._PROC_CP65.png\" alt=\"\" class=\"wp-image-45622\" srcset=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/08\/https__img.migalhas.com_.br__SL__gf_base__SL__empresas__SL__MIGA__SL__imagens__SL__2025__SL__08__SL__12__SL__cropped_1qamszf1.4zh.png._PROC_CP65.png 878w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/08\/https__img.migalhas.com_.br__SL__gf_base__SL__empresas__SL__MIGA__SL__imagens__SL__2025__SL__08__SL__12__SL__cropped_1qamszf1.4zh.png._PROC_CP65-300x170.png 300w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/08\/https__img.migalhas.com_.br__SL__gf_base__SL__empresas__SL__MIGA__SL__imagens__SL__2025__SL__08__SL__12__SL__cropped_1qamszf1.4zh.png._PROC_CP65-768x436.png 768w\" sizes=\"(max-width: 878px) 100vw, 878px\" \/><figcaption>Imagem: Reprodu\u00e7\u00e3o\/Ultrafarma <\/figcaption><\/figure>\n\n\n\n<p>Uma opera\u00e7\u00e3o do Minist\u00e9rio P\u00fablico de S\u00e3o Paulo (MPSP) para desarticular um esquema de corrup\u00e7\u00e3o envolvendo auditores fiscais tribut\u00e1rios da Secretaria de Estado da Fazenda prendeu nesta ter\u00e7a-feira (12) os empres\u00e1rios Sidney OIiveira, dono da rede Ultrafarma, e Mario Ot\u00e1vio Gomes, diretor estatut\u00e1rio da Fast Shop.<\/p>\n\n\n\n<p>O auditor, Artur Gomes da Silva Neto, que \u00e9 supervisor da Diretoria de Fiscaliza\u00e7\u00e3o (DIFIS) da Fazenda estadual paulista, tamb\u00e9m foi preso na opera\u00e7\u00e3o.<\/p>\n\n\n\n<p>Al\u00e9m das pris\u00f5es, os agentes d\u00e3o cumprimento a diversos mandados de busca e apreens\u00e3o em endere\u00e7os residenciais dos alvos e nas sedes das empresas investigadas.<\/p>\n\n\n\n<p>Segundo o MPSP, a investiga\u00e7\u00e3o identificou que um auditor fiscal estadual de alto escal\u00e3o estaria comandando um esquema de fraudes em cr\u00e9ditos tribut\u00e1rios que teria arrecadado em propinas cerca de R$ 1 bilh\u00e3o desde 2021.<\/p><div class=\"ykhej6a581716d9eaa\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.ykhej6a581716d9eaa {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.ykhej6a581716d9eaa {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.ykhej6a581716d9eaa {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.ykhej6a581716d9eaa {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.ykhej6a581716d9eaa {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.ykhej6a581716d9eaa {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"kchuz6a581716d9e93\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.kchuz6a581716d9e93 {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.kchuz6a581716d9e93 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.kchuz6a581716d9e93 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.kchuz6a581716d9e93 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.kchuz6a581716d9e93 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.kchuz6a581716d9e93 {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>De acordo com a apura\u00e7\u00e3o, o fiscal utilizava manipulava processos administrativos para facilitar a quita\u00e7\u00e3o de cr\u00e9ditos tribut\u00e1rios \u00e0s empresas. Em contrapartida, recebia pagamentos mensais de propina por meio de uma empresa registrada em nome de sua m\u00e3e.<\/p>\n\n\n\n<p>A investiga\u00e7\u00e3o conduzida pelo Grupo de Atua\u00e7\u00e3o Especial de Repress\u00e3o aos Delitos Econ\u00f4micos (GEDEC). Os investigados poder\u00e3o responder pelos crimes de corrup\u00e7\u00e3o ativa e passiva, organiza\u00e7\u00e3o criminosa e lavagem de dinheiro.<\/p>\n\n\n\n<p>Durante a Opera\u00e7\u00e3o \u00cdcaro, a pol\u00edcia encontrou na casa do auditor fiscal pedras preciosas e grande quantidade de dinheiro em esp\u00e9cie. O material foi apreendido.<br><br><em>Fonte: Band.com.br<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O dono da rede Ultrafarma, Sidney Oliveira, foi preso na manh\u00e3 desta ter\u00e7a-feira, 12, acusado de participar de um esquema de corrup\u00e7\u00e3o que teria movimentado mais de R$ 1 bilh\u00e3o em propina.<br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2025\/08\/12\/empresarios-e-auditor-fiscal-sao-presos-em-operacao-do-ministerio-publico-de-sp\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/45621"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=45621"}],"version-history":[{"count":2,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/45621\/revisions"}],"predecessor-version":[{"id":45624,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/45621\/revisions\/45624"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=45621"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=45621"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=45621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}