{"id":45514,"date":"2025-08-09T10:14:20","date_gmt":"2025-08-09T13:14:20","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=45514"},"modified":"2025-08-09T10:15:08","modified_gmt":"2025-08-09T13:15:08","slug":"tst-autoriza-penhora-de-pensao-por-morte-para-debitos-trabalhistas","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2025\/08\/09\/tst-autoriza-penhora-de-pensao-por-morte-para-debitos-trabalhistas\/","title":{"rendered":"TST autoriza penhora de pens\u00e3o por morte para quitar d\u00e9bitos trabalhistas"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1024\" height=\"544\" src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/08\/dinheiro-esquecido-1024x544.jpg\" alt=\"\" class=\"wp-image-45515\" srcset=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/08\/dinheiro-esquecido-1024x544.jpg 1024w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/08\/dinheiro-esquecido-300x159.jpg 300w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/08\/dinheiro-esquecido-768x408.jpg 768w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/08\/dinheiro-esquecido.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>Imagem: Getty Images<\/figcaption><\/figure>\n\n\n\n<p>A 5\u00aa turma do TST decidiu, por unanimidade, autorizar a penhora de parte da pens\u00e3o por morte recebida por uma s\u00f3cia de empresa para quitar d\u00e9bitos trabalhistas. O colegiado fixou que a reten\u00e7\u00e3o poder\u00e1 ser de at\u00e9 15% do valor l\u00edquido mensal, desde que seja preservado, no m\u00ednimo, o equivalente a um sal\u00e1rio m\u00ednimo para a benefici\u00e1ria.<\/p>\n\n\n\n<p>O processo teve in\u00edcio com pedido de penhora sobre a pens\u00e3o por morte recebida pela s\u00f3cia executada, no valor bruto de R$ 2.821,36, que, ap\u00f3s descontos de empr\u00e9stimos consignados, resultava em R$ 1.726 l\u00edquidos. O objetivo era destinar parte dessa renda ao pagamento de cr\u00e9ditos trabalhistas reconhecidos judicialmente.<\/p>\n\n\n\n<p>O TRT da 2\u00aa regi\u00e3o negou a medida, argumentando que a constri\u00e7\u00e3o poderia comprometer a subsist\u00eancia da benefici\u00e1ria, sobretudo por n\u00e3o haver provas de outras fontes de renda.<\/p>\n\n\n\n<p>A parte credora recorreu ao TST, sustentando que o cr\u00e9dito trabalhista tem natureza aliment\u00edcia, o que permite a penhora de rendimentos como sal\u00e1rios e pens\u00f5es, dentro de limites legais.<\/p><div class=\"wfidz6a580696bc477\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.wfidz6a580696bc477 {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.wfidz6a580696bc477 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.wfidz6a580696bc477 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.wfidz6a580696bc477 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.wfidz6a580696bc477 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.wfidz6a580696bc477 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"nypts6a580696bc459\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.nypts6a580696bc459 {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.nypts6a580696bc459 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.nypts6a580696bc459 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.nypts6a580696bc459 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.nypts6a580696bc459 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.nypts6a580696bc459 {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>Ao analisar o recurso, a relatora, ministra Morgana de Almeida Richa, destacou que a jurisprud\u00eancia do TST admite a penhora de sal\u00e1rios, proventos de aposentadoria e pens\u00f5es para a satisfa\u00e7\u00e3o de cr\u00e9ditos trabalhistas, em raz\u00e3o de seu car\u00e1ter alimentar. Esse entendimento tem fundamento no art. 100, \u00a71\u00ba, da CF, e no art. 833, inciso IV e \u00a72\u00ba, do CPC.<\/p>\n\n\n\n<p>Para a 5\u00aa turma, o TRT n\u00e3o considerou a exce\u00e7\u00e3o prevista no \u00a72\u00ba do art. 833 do CPC, que autoriza a penhora nesses casos. No entendimento do colegiado, a constri\u00e7\u00e3o de at\u00e9 15% sobre a pens\u00e3o por morte, desde que reste ao menos um sal\u00e1rio m\u00ednimo dispon\u00edvel \u00e0 executada, n\u00e3o viola o direito \u00e0 subsist\u00eancia.<\/p>\n\n\n\n<p>Com base nesse racioc\u00ednio, a 5\u00aa turma deu provimento ao recurso da parte credora e autorizou a penhora parcial da pens\u00e3o por morte. A decis\u00e3o foi un\u00e2nime.<\/p>\n\n\n\n<p><em>Fonte: Migalhas<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A relatora, ministra Morgana de Almeida Richa, destacou que a jurisprud\u00eancia do TST admite a penhora de sal\u00e1rios, proventos de aposentadoria e pens\u00f5es para a satisfa\u00e7\u00e3o de cr\u00e9ditos trabalhistas, em raz\u00e3o de seu car\u00e1ter alimentar. <br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2025\/08\/09\/tst-autoriza-penhora-de-pensao-por-morte-para-debitos-trabalhistas\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/45514"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=45514"}],"version-history":[{"count":2,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/45514\/revisions"}],"predecessor-version":[{"id":45517,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/45514\/revisions\/45517"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=45514"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=45514"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=45514"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}