{"id":45391,"date":"2025-08-06T06:40:42","date_gmt":"2025-08-06T09:40:42","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=45391"},"modified":"2025-08-06T06:41:02","modified_gmt":"2025-08-06T09:41:02","slug":"ministro-luiz-fux-suspende-decisao-do-trt-2-que-reconheceu-vinculo-de-pj","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2025\/08\/06\/ministro-luiz-fux-suspende-decisao-do-trt-2-que-reconheceu-vinculo-de-pj\/","title":{"rendered":"Ministro Luiz Fux suspende decis\u00e3o do TRT-2 que reconheceu v\u00ednculo de PJ"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"597\" height=\"482\" src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/08\/carteira-de-trabalho-digital-640w2.jpg\" alt=\"\" class=\"wp-image-45392\" srcset=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/08\/carteira-de-trabalho-digital-640w2.jpg 597w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/08\/carteira-de-trabalho-digital-640w2-300x242.jpg 300w\" sizes=\"(max-width: 597px) 100vw, 597px\" \/><\/figure>\n\n\n\n<p>O ministro Luiz Fux, do Supremo Tribunal Federal, determinou a suspens\u00e3o de um processo que versa sobre fraude trabalhista em contrato de presta\u00e7\u00e3o de servi\u00e7os.<\/p>\n\n\n\n<p>Nos autos, consta que o Tribunal Regional do Trabalho da 2\u00aa Regi\u00e3o (Grande S\u00e3o Paulo e litoral paulista) reconheceu o v\u00ednculo de emprego entre um homem e uma empresa de transportes, a despeito da exist\u00eancia de um contrato firmado por uma pessoa jur\u00eddica de titularidade do autor.<\/p>\n\n\n\n<p>A empresa contestou o julgado no Supremo. A firma alegou que a decis\u00e3o do TRT-2 afrontou os entendimentos estabelecidos pelo STF no julgamento do ADPF 324 e no RE 958.252, Tema 725 da repercuss\u00e3o geral (terceiriza\u00e7\u00e3o da atividade-fim).<\/p>\n\n\n\n<p>O ministro, contudo, explicou que a controv\u00e9rsia sobre a compet\u00eancia da Justi\u00e7a do Trabalho para julgar casos de fraude em contratos de presta\u00e7\u00e3o de servi\u00e7os por pessoas jur\u00eddicas fez com que o Plen\u00e1rio do STF admitisse novo tema de repercuss\u00e3o geral para esclarecer a mat\u00e9ria, o Tema 1.389.<\/p><div class=\"xnopz6a57f4bbcbe82\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.xnopz6a57f4bbcbe82 {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.xnopz6a57f4bbcbe82 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.xnopz6a57f4bbcbe82 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.xnopz6a57f4bbcbe82 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.xnopz6a57f4bbcbe82 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.xnopz6a57f4bbcbe82 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"iqmxd6a57f4bbcbe6c\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.iqmxd6a57f4bbcbe6c {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.iqmxd6a57f4bbcbe6c {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.iqmxd6a57f4bbcbe6c {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.iqmxd6a57f4bbcbe6c {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.iqmxd6a57f4bbcbe6c {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.iqmxd6a57f4bbcbe6c {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>O relator da discuss\u00e3o, ministro Gilmar Mendes, determinou, em abril, a suspens\u00e3o de todos os processos que tratem das quest\u00f5es relativas \u00e0 mat\u00e9ria at\u00e9 o julgamento definitivo do m\u00e9rito pelo Supremo.<\/p>\n\n\n\n<p>\u201cConstada, pois, a similitude de quest\u00f5es debatidas no caso de origem e aquelas que ensejaram instaura\u00e7\u00e3o do Tema 1.389 da repercuss\u00e3o geral, tendo o decisum reclamado versado sobre as quest\u00f5es constitucionais reconhecidas por este STF em recurso extraordin\u00e1rio submetido \u00e0 sistem\u00e1tica da repercuss\u00e3o geral, imp\u00f5e-se a proced\u00eancia em parte da presente a\u00e7\u00e3o, com vistas \u00e0 suspens\u00e3o do processo de origem, nos termos do artigo 1.035, \u00a7 5\u00ba, do CPC, at\u00e9 o julgamento do recurso paradigma do Tema 1.389 no \u00e2mbito deste Supremo Tribunal\u201d, resumiu Fux.<\/p>\n\n\n\n<p><em>Fonte: Conjur<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A firma alegou que a decis\u00e3o do TRT-2 afrontou os entendimentos estabelecidos pelo STF no julgamento do ADPF 324 e no RE 958.252, Tema 725 da repercuss\u00e3o geral (terceiriza\u00e7\u00e3o da atividade-fim).<br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2025\/08\/06\/ministro-luiz-fux-suspende-decisao-do-trt-2-que-reconheceu-vinculo-de-pj\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/45391"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=45391"}],"version-history":[{"count":1,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/45391\/revisions"}],"predecessor-version":[{"id":45393,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/45391\/revisions\/45393"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=45391"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=45391"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=45391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}