{"id":45147,"date":"2025-07-30T12:47:45","date_gmt":"2025-07-30T15:47:45","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=45147"},"modified":"2025-07-30T12:47:45","modified_gmt":"2025-07-30T15:47:45","slug":"apos-atuacao-da-oab-rn-justica-rejeita-denuncia-contra-advogada-criminalista","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2025\/07\/30\/apos-atuacao-da-oab-rn-justica-rejeita-denuncia-contra-advogada-criminalista\/","title":{"rendered":"Ap\u00f3s atua\u00e7\u00e3o da OAB\/RN, Justi\u00e7a rejeita den\u00fancia contra advogada criminalista"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-30-at-12.34.50-1024x690.jpg\" alt=\"\" class=\"wp-image-45148\" width=\"839\" height=\"565\" srcset=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-30-at-12.34.50-1024x690.jpg 1024w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-30-at-12.34.50-300x202.jpg 300w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-30-at-12.34.50-768x518.jpg 768w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-30-at-12.34.50.jpg 1159w\" sizes=\"(max-width: 839px) 100vw, 839px\" \/><figcaption>Foto: Divulga\u00e7\u00e3o OAB\/RN<\/figcaption><\/figure>\n\n\n\n<p>A Justi\u00e7a potiguar rejeitou a den\u00fancia oferecida pelo Minist\u00e9rio P\u00fablico contra a advogada Francisca Iara Renata Fernandes, que havia sido acusada de cal\u00fania por questionar, no exerc\u00edcio de sua fun\u00e7\u00e3o, a destina\u00e7\u00e3o de valores supostamente apreendidos durante uma dilig\u00eancia policial em Ass\u00fa\/RN, em setembro de 2024.<\/p>\n\n\n\n<p>A decis\u00e3o do juiz Cl\u00e1udio Mendes J\u00fanior reconheceu que a conduta da advogada se deu no exerc\u00edcio leg\u00edtimo da advocacia e dentro dos limites legais e constitucionais da profiss\u00e3o. Segundo a senten\u00e7a, n\u00e3o houve qualquer evid\u00eancia de dolo ou inten\u00e7\u00e3o de ofensa por parte da profissional, que apenas apresentou questionamentos em defesa da sua cliente, como assegurado pelo artigo 133 da Constitui\u00e7\u00e3o Federal e pelo Estatuto da Advocacia (Lei n\u00ba 8.906\/94).<\/p>\n\n\n\n<p>A Ordem dos Advogados do Brasil no Rio Grande do Norte (OAB\/RN) atuou de forma firme em defesa das prerrogativas da profissional. A entidade acompanhou de perto o caso e reiterou que manifesta\u00e7\u00f5es feitas por advogados no exerc\u00edcio da profiss\u00e3o s\u00e3o protegidas por imunidade funcional (inj\u00faria e difama\u00e7\u00e3o), n\u00e3o configurando crime, e em casos de cal\u00fania, \u00e9 indispens\u00e1vel a vontade de ofender, pois sem a vontade de atingir a honra do ofendido, n\u00e3o h\u00e1 como tipificar o crime.<\/p><div class=\"zbrzs6a57d4fc14240\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.zbrzs6a57d4fc14240 {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.zbrzs6a57d4fc14240 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.zbrzs6a57d4fc14240 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.zbrzs6a57d4fc14240 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.zbrzs6a57d4fc14240 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.zbrzs6a57d4fc14240 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"bgnlj6a57d4fc14223\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.bgnlj6a57d4fc14223 {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.bgnlj6a57d4fc14223 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.bgnlj6a57d4fc14223 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.bgnlj6a57d4fc14223 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.bgnlj6a57d4fc14223 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.bgnlj6a57d4fc14223 {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>\u201cEssa decis\u00e3o \u00e9 uma vit\u00f3ria da advocacia e uma reafirma\u00e7\u00e3o do que est\u00e1 garantido pela Constitui\u00e7\u00e3o. A OAB\/RN seguir\u00e1 vigilante e combativa na defesa intransigente das prerrogativas profissionais, que s\u00e3o, na pr\u00e1tica, garantias de toda a sociedade\u201d, afirmou o presidente da OAB\/RN, Carlos Kelsen.<\/p>\n\n\n\n<p>A vice-presidente da Comiss\u00e3o de Prerrogativas que acompanhou o caso, Aylla Benigno, refor\u00e7ou a atua\u00e7\u00e3o da OAB\/RN junto ao judici\u00e1rio. \u201cRefor\u00e7amos junto ao Judici\u00e1rio que a atua\u00e7\u00e3o da advocacia, quando exercida nos limites legais, n\u00e3o pode ser criminalizada. A decis\u00e3o \u00e9 uma conquista e reafirma o compromisso da OAB com as prerrogativas\u201d, disse.<br><br><em>Fonte: OAB\/RN<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A decis\u00e3o do juiz Cl\u00e1udio Mendes J\u00fanior reconheceu que a conduta da advogada se deu no exerc\u00edcio leg\u00edtimo da advocacia e dentro dos limites legais e constitucionais da profiss\u00e3o.  <br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2025\/07\/30\/apos-atuacao-da-oab-rn-justica-rejeita-denuncia-contra-advogada-criminalista\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/45147"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=45147"}],"version-history":[{"count":1,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/45147\/revisions"}],"predecessor-version":[{"id":45149,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/45147\/revisions\/45149"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=45147"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=45147"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=45147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}