{"id":4496,"date":"2019-12-04T11:26:51","date_gmt":"2019-12-04T14:26:51","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=4496"},"modified":"2019-12-04T10:19:24","modified_gmt":"2019-12-04T13:19:24","slug":"pec-da-prisao-em-2a-instancia-pode-incluir-tambem-justica-civel-e-tributaria","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2019\/12\/04\/pec-da-prisao-em-2a-instancia-pode-incluir-tambem-justica-civel-e-tributaria\/","title":{"rendered":"PEC da pris\u00e3o em 2\u00aa inst\u00e2ncia pode incluir tamb\u00e9m Justi\u00e7a C\u00edvel e Tribut\u00e1ria"},"content":{"rendered":"\n<p>L\u00edderes partid\u00e1rios articulam construir uma maioria na\u00a0<strong>C\u00e2mara\u00a0<\/strong>capaz de garantir que a Proposta de Emenda \u00e0 Constitui\u00e7\u00e3o (PEC) da\u00a0<strong>pris\u00e3o<\/strong>\u00a0imediata em\u00a0<strong>segunda inst\u00e2ncia<\/strong>\u00a0atinja outras as esferas da Justi\u00e7a. A previs\u00e3o do presidente da Casa, Rodrigo Maia (DEM-RJ), \u00e9 que a comiss\u00e3o especial para debat\u00ea-la seja instalada hoje. O texto estabelece a execu\u00e7\u00e3o da pena depois da senten\u00e7a em segunda inst\u00e2ncia n\u00e3o apenas na \u00e1rea criminal, mas nas outras esferas, como c\u00edvel e tribut\u00e1ria.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" width=\"640\" height=\"480\" src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2019\/12\/74693.jpg\" alt=\"\" class=\"wp-image-4497\" srcset=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2019\/12\/74693.jpg 640w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2019\/12\/74693-300x225.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><figcaption>Ag\u00eancia C\u00e2mara<\/figcaption><\/figure>\n\n\n\n<p>Assim, uma d\u00edvida fiscal de uma empresa poderia ser executada antes dos recursos aos tribunais superiores, ou uma a\u00e7\u00e3o c\u00edvel sobre um div\u00f3rcio, por exemplo, poderia ter defini\u00e7\u00e3o antecipada.<\/p><div class=\"adbxb6a0466f3ba58d\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.adbxb6a0466f3ba58d {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.adbxb6a0466f3ba58d {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.adbxb6a0466f3ba58d {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.adbxb6a0466f3ba58d {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.adbxb6a0466f3ba58d {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.adbxb6a0466f3ba58d {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"ebswq6a0466f3ba577\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.ebswq6a0466f3ba577 {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.ebswq6a0466f3ba577 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.ebswq6a0466f3ba577 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.ebswq6a0466f3ba577 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.ebswq6a0466f3ba577 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.ebswq6a0466f3ba577 {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>Como a PEC prop\u00f5e extinguir os recursos apresentados ao Superior Tribunal de Justi\u00e7a (STJ) e ao Supremo Tribunal Federal (STF) como forma de abreviar o tr\u00e2nsito em julgado das a\u00e7\u00f5es penas, ramos do Direito que t\u00eam tribunais superiores pr\u00f3prios, como o trabalhista (TST) e o eleitoral (TSE), est\u00e3o fora do alcance da PEC.<\/p>\n\n\n\n<p>Acordo fechado na semana passada entre senadores e deputados previu prioridade a essa PEC da C\u00e2mara, em detrimento de um projeto de lei sobre o mesmo assunto que tramita no Senado. A despeito do combinado entre l\u00edderes, um grupo de senadores ainda insiste na vota\u00e7\u00e3o da proposta que tramita na Comiss\u00e3o de Constitui\u00e7\u00e3o e Justi\u00e7a do Senado, e que modifica o C\u00f3digo Penal e teria tramita\u00e7\u00e3o mais r\u00e1pida que a PEC. Ontem, sem cit\u00e1-los, Maia criticou quem quer \u201cjogar para a galera\u201d. Ele avalia que a mudan\u00e7a na Constitui\u00e7\u00e3o teria menos chance de ser contestada no futuro:<br><br><br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Assim, uma d\u00edvida fiscal de uma empresa poderia ser executada antes dos recursos aos tribunais superiores, ou uma a\u00e7\u00e3o c\u00edvel sobre um div\u00f3rcio, por exemplo, poderia ter defini\u00e7\u00e3o antecipada.<br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2019\/12\/04\/pec-da-prisao-em-2a-instancia-pode-incluir-tambem-justica-civel-e-tributaria\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":5,"featured_media":4497,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4496"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=4496"}],"version-history":[{"count":1,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4496\/revisions"}],"predecessor-version":[{"id":4498,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4496\/revisions\/4498"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media\/4497"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=4496"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=4496"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=4496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}