{"id":44956,"date":"2025-07-22T13:07:42","date_gmt":"2025-07-22T16:07:42","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=44956"},"modified":"2025-07-22T13:08:53","modified_gmt":"2025-07-22T16:08:53","slug":"precatorios-prazo-final-para-acordo-direto-com-o-municipio-de-natal-e-ate-12-de-agosto","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2025\/07\/22\/precatorios-prazo-final-para-acordo-direto-com-o-municipio-de-natal-e-ate-12-de-agosto\/","title":{"rendered":"Precat\u00f3rios: Prazo final para Acordo Direto com o munic\u00edpio de Natal \u00e9 at\u00e9 12 de agosto"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1024\" height=\"544\" src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/07\/poupanca-ensino-medio-petroleo-1024x544.jpg\" alt=\"\" class=\"wp-image-44957\" srcset=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/07\/poupanca-ensino-medio-petroleo-1024x544.jpg 1024w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/07\/poupanca-ensino-medio-petroleo-300x159.jpg 300w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/07\/poupanca-ensino-medio-petroleo-768x408.jpg 768w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/07\/poupanca-ensino-medio-petroleo.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>(Imagem: iStock)<\/figcaption><\/figure>\n\n\n\n<p>O Tribunal Regional do Trabalho da 21\u00aa Regi\u00e3o (RN) informa que o prazo para as inscri\u00e7\u00f5es no Programa Acordo Direto, para quem tem precat\u00f3rio com o munic\u00edpio de Natal, \u00e9 at\u00e9 o dia 12 de agosto de 2025. O valor disponibilizado pela prefeitura subiu para R$6,5 milh\u00f5es.<\/p>\n\n\n\n<p>Segundo o Edital assinado pela Coordenadoria de Precat\u00f3rios e Requisit\u00f3rios do TRT-RN, representada pelo juiz Higor Sanches, somente ser\u00e3o considerados v\u00e1lidos os pedidos de acordo direto enviados \u00e0 Coordenadoria no prazo e nas condi\u00e7\u00f5es estabelecidas na publica\u00e7\u00e3o. O programa permite o pagamento imediato de precat\u00f3rios trabalhistas, com um des\u00e1gio de 40% do valor atualizado do cr\u00e9dito.<\/p>\n\n\n\n<p>Mais de 300 pessoas j\u00e1 est\u00e3o aptas a se inscrever, incluindo servidores, pensionistas ou seus sucessores habilitados no processo que possuam cr\u00e9ditos a receber.<\/p>\n\n\n\n<p>A manifesta\u00e7\u00e3o de interesse deve ser feita exclusivamente por meio de procurador habilitado no PJe 1\u00ba grau e no precat\u00f3rio 2\u00ba grau e \u00e9 fundamental que haja a concord\u00e2ncia expressa do credor \u00e0s condi\u00e7\u00f5es do acordo. O peticionamento deve ser feito no Precat\u00f3rio Requisit\u00f3rio autuado ou migrado ao PJe 2\u00ba grau, nominando o tipo de documento como \u201cAcordo\u201d e a descri\u00e7\u00e3o \u201cManifesta\u00e7\u00e3o ao Acordo Direto\u201d.<\/p><div class=\"pwuql6a57ad2ec7808\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.pwuql6a57ad2ec7808 {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.pwuql6a57ad2ec7808 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.pwuql6a57ad2ec7808 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.pwuql6a57ad2ec7808 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.pwuql6a57ad2ec7808 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.pwuql6a57ad2ec7808 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"wwnau6a57ad2ec77ef\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.wwnau6a57ad2ec77ef {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.wwnau6a57ad2ec77ef {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.wwnau6a57ad2ec77ef {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.wwnau6a57ad2ec77ef {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.wwnau6a57ad2ec77ef {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.wwnau6a57ad2ec77ef {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>Apesar disso, o Edital informa que a manifesta\u00e7\u00e3o de interesse, por si s\u00f3, n\u00e3o garante \u00e0 parte credora o direito de receber o seu cr\u00e9dito, n\u00e3o gerando qualquer direito subjetivo ao pagamento, pois constitui mera expectativa, bem como \u00e0 disponibilidade de recursos financeiros dispon\u00edveis na conta judicial reservada aos acordos diretos.<\/p>\n\n\n\n<p>Em caso de d\u00favidas, fale diretamente com a Coordenadoria de Precat\u00f3rios do Tribunal pelo e-mail cprec@trt21.jus.br ou pelo telefone (84) 4006-3249.<\/p>\n\n\n\n<p>O Programa Acordo Direto \u00e9 uma iniciativa do TRT-RN que permite o pagamento imediato de precat\u00f3rios trabalhistas, com um des\u00e1gio de 40% do valor atualizado do cr\u00e9dito. No ano passado, o programa resultou de um termo de coopera\u00e7\u00e3o entre o TRT-RN e a Procuradoria-Geral do Estado e , em 2025, com o Munic\u00edpio de Natal.<br><br><em>Fonte: TRT21<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A manifesta\u00e7\u00e3o de interesse deve ser feita exclusivamente por meio de procurador habilitado no PJe 1\u00ba grau e no precat\u00f3rio 2\u00ba grau e \u00e9 fundamental que haja a concord\u00e2ncia expressa do credor \u00e0s condi\u00e7\u00f5es do acordo. <br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2025\/07\/22\/precatorios-prazo-final-para-acordo-direto-com-o-municipio-de-natal-e-ate-12-de-agosto\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/44956"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=44956"}],"version-history":[{"count":3,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/44956\/revisions"}],"predecessor-version":[{"id":44960,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/44956\/revisions\/44960"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=44956"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=44956"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=44956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}