{"id":43338,"date":"2025-06-10T13:00:50","date_gmt":"2025-06-10T16:00:50","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=43338"},"modified":"2025-06-10T13:00:50","modified_gmt":"2025-06-10T16:00:50","slug":"mp-de-mossoro-vai-investigar-possivel-propaganda-eleitoral-para-o-prefeito-allyson-bezerra","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2025\/06\/10\/mp-de-mossoro-vai-investigar-possivel-propaganda-eleitoral-para-o-prefeito-allyson-bezerra\/","title":{"rendered":"MP de Mossor\u00f3 vai investigar poss\u00edvel propaganda eleitoral para o prefeito Allyson Bezerra"},"content":{"rendered":"\n<p>O Minist\u00e9rio P\u00fablico do Rio Grande do Norte (MPRN) instaurou uma Not\u00edcia de Fato para apurar a fala do cantor Xand Avi\u00e3o em apoio ao prefeito de Mossor\u00f3, Allyson Bezerra (Uni\u00e3o Brasil), durante o Pingo da Mei Dia, evento que abriu os festejos do Mossor\u00f3 Cidade Junina 2025, no \u00faltimo s\u00e1bado. A manifesta\u00e7\u00e3o do artista, em cima de um trio el\u00e9trico, fez men\u00e7\u00f5es diretas \u00e0 poss\u00edvel candidatura de Allyson ao governo do Estado e gerou questionamentos sobre o uso de recursos p\u00fablicos em evento com vi\u00e9s pol\u00edtico.<\/p>\n\n\n\n<p>A promotora de Justi\u00e7a Ana Ximenes, da segunda Promotoria de Justi\u00e7a da Comarca de Mossor\u00f3, confirmou ao Di\u00e1rio do RN que o caso est\u00e1 sob an\u00e1lise. \u201c\u00c9 cedo para fazer um enquadramento jur\u00eddico preciso. Contudo, determinei a abertura de Not\u00edcia de Fato para apurar\u201d, afirmou \u00e0 reportagem.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1024\" height=\"725\" src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/06\/allyson-1024x725.jpg\" alt=\"\" class=\"wp-image-43339\" srcset=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/06\/allyson-1024x725.jpg 1024w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/06\/allyson-300x212.jpg 300w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/06\/allyson-768x544.jpg 768w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/06\/allyson.jpg 1436w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>Imagem: Reprodu\u00e7\u00e3o\/Facebook Allyson Bezerra<\/figcaption><\/figure>\n\n\n\n<p>A Not\u00edcia de Fato 02.23.2022.0000025\/2025-37, instaurado nesta segunda-feira (09), tem como objeto a apura\u00e7\u00e3o de suposta pr\u00e1tica de propaganda eleitoral antecipada patrocinada com recursos p\u00fablicos. S\u00e3o citados o cantor Jos\u00e9 Alexandre da Silva Filho, o Xand Avi\u00e3o, o prefeito Allyson Bezerra e a secret\u00e1ria Municipal de Cultura de Mossor\u00f3, Jana\u00edna Holanda. Da autua\u00e7\u00e3o da not\u00edcia, foram anexadas mat\u00e9rias jornal\u00edsticas e not\u00edcias do Instagram.<\/p>\n\n\n\n<p>A Not\u00edcia de Fato \u00e9 o registro preliminar de uma poss\u00edvel irregularidade ou ilegalidade. \u00c9 a fase inicial de apura\u00e7\u00e3o, anterior \u00e0 abertura de inqu\u00e9rito civil ou procedimento investigat\u00f3rio, para verificar se h\u00e1 elementos m\u00ednimos que justifiquem a instaura\u00e7\u00e3o de uma investiga\u00e7\u00e3o mais aprofundada.<\/p>\n\n\n\n<p>Durante passagem pelo camarote da Prefeitura de Mossor\u00f3, pr\u00f3ximo aos camarotes da imprensa, Xand Avi\u00e3o dirigiu-se diretamente ao prefeito: \u201cMeu prefeito Allyson, um beijo do comandante.<\/p><div class=\"vvxxa6a03c5304f96f\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.vvxxa6a03c5304f96f {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.vvxxa6a03c5304f96f {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.vvxxa6a03c5304f96f {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.vvxxa6a03c5304f96f {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.vvxxa6a03c5304f96f {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.vvxxa6a03c5304f96f {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"yoaut6a03c5304f94c\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.yoaut6a03c5304f94c {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.yoaut6a03c5304f94c {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.yoaut6a03c5304f94c {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.yoaut6a03c5304f94c {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.yoaut6a03c5304f94c {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.yoaut6a03c5304f94c {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>Parab\u00e9ns por essa festa maravilhosa. Quem \u00e9 f\u00e3 do Allyson d\u00e1 um grit\u00e3o bem grande a\u00ed! 99,9% de aprova\u00e7\u00e3o. Quem n\u00e3o \u00e9, \u00e9 porque n\u00e3o vota aqui. Quem quer Allyson para governador, grita eu! Por mim ele era presidente logo, macho\u201d, completou o forrozeiro.<\/p>\n\n\n\n<p>Para o advogado Felipe Cortez, especialista em Direito Eleitoral, a fala configura propaganda eleitoral antecipada. \u201cA leitura que eu fa\u00e7o disso \u00e9 de propaganda antecipada. N\u00f3s temos uma elei\u00e7\u00e3o que ser\u00e1 no pr\u00f3ximo ano e o prefeito se coloca como pr\u00e9-candidato. E, pelo que eu vi, ele gostou do que Xand Avi\u00e3o disse. Ent\u00e3o, voc\u00ea coloca um cantor de renome nacional lan\u00e7ando a candidatura dele para governador num evento com 200 mil pessoas, pago com dinheiro p\u00fablico.<\/p>\n\n\n\n<p>Na minha concep\u00e7\u00e3o, temos a\u00ed um cen\u00e1rio de propaganda antecipada que \u00e9 sancionado com multa\u201d, avalia Cortez.<\/p>\n\n\n\n<p>O jurista se refere ao artigo 36 da Lei das Elei\u00e7\u00f5es (Lei n\u00ba 9.504\/97), que pro\u00edbe manifesta\u00e7\u00f5es que caracterizem campanha eleitoral fora do per\u00edodo permitido. O par\u00e1grafo 3\u00ba do artigo prev\u00ea multa de R$ 5 mil a R$ 25 mil para quem divulgar a propaganda e, se comprovado pr\u00e9vio conhecimento, para o benefici\u00e1rio.<\/p>\n\n\n\n<p><em>Fonte: Di\u00e1rio do RN<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Not\u00edcia de Fato tem como objeto a apura\u00e7\u00e3o de suposta pr\u00e1tica de propaganda eleitoral antecipada patrocinada com recursos p\u00fablicos. <br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2025\/06\/10\/mp-de-mossoro-vai-investigar-possivel-propaganda-eleitoral-para-o-prefeito-allyson-bezerra\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/43338"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=43338"}],"version-history":[{"count":3,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/43338\/revisions"}],"predecessor-version":[{"id":43342,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/43338\/revisions\/43342"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=43338"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=43338"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=43338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}