{"id":43277,"date":"2025-06-09T15:41:58","date_gmt":"2025-06-09T18:41:58","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=43277"},"modified":"2025-06-09T15:41:58","modified_gmt":"2025-06-09T18:41:58","slug":"justica-mantem-decisao-que-permite-ampla-concessao-de-alvaras-para-mototaxis-em-ceara-mirim","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2025\/06\/09\/justica-mantem-decisao-que-permite-ampla-concessao-de-alvaras-para-mototaxis-em-ceara-mirim\/","title":{"rendered":"Justi\u00e7a mant\u00e9m decis\u00e3o que permite ampla concess\u00e3o de alvar\u00e1s para motot\u00e1xis em Cear\u00e1-Mirim"},"content":{"rendered":"\n<p>Ap\u00f3s uma atua\u00e7\u00e3o do Minist\u00e9rio P\u00fablico do Rio Grande do Norte (MPRN), o Tribunal de Justi\u00e7a do RN (TJRN) manteve uma decis\u00e3o sobre a regulamenta\u00e7\u00e3o do servi\u00e7o de motot\u00e1xi em Cear\u00e1-Mirim. O MPRN, na qualidade de fiscal da lei, intercedeu em um processo judicial que discutia a forma de concess\u00e3o de alvar\u00e1s para o transporte individual de passageiros, inicialmente buscando a obrigatoriedade de licita\u00e7\u00e3o.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"748\" height=\"408\" src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/06\/mototaxistas.jpg\" alt=\"\" class=\"wp-image-43278\" srcset=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/06\/mototaxistas.jpg 748w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/06\/mototaxistas-300x164.jpg 300w\" sizes=\"(max-width: 748px) 100vw, 748px\" \/><figcaption>Paulo Pinto\/Ag\u00eancia Brasil<\/figcaption><\/figure>\n\n\n\n<p>A discuss\u00e3o teve origem em uma A\u00e7\u00e3o Ordin\u00e1ria Coletiva ajuizada por 25 pessoas contra o Munic\u00edpio de Cear\u00e1-Mirim, com o objetivo de evitar a necessidade de licita\u00e7\u00e3o para os servi\u00e7os de t\u00e1xi. A 3\u00aa Vara de Cear\u00e1-Mirim havia julgado parcialmente procedente a a\u00e7\u00e3o, declarando a desnecessidade de licita\u00e7\u00e3o e determinando a emiss\u00e3o de alvar\u00e1s para aqueles que preenchessem os requisitos legais.<\/p>\n\n\n\n<p>A interven\u00e7\u00e3o do MPRN no caso remonta a um Termo de Ajustamento de Conduta (TAC) celebrado em novembro de 2013, entre o Munic\u00edpio de Cear\u00e1-Mirim e o Minist\u00e9rio P\u00fablico. O acordo visava solucionar irregularidades no servi\u00e7o de t\u00e1xi e motot\u00e1xi, estabelecendo que um projeto de lei seria apresentado \u00e0 C\u00e2mara Municipal para exigir licita\u00e7\u00e3o pr\u00e9via \u00e0 outorga de permiss\u00f5es.<\/p>\n\n\n\n<p>Os requerentes da a\u00e7\u00e3o argumentaram que a exig\u00eancia de licita\u00e7\u00e3o resultaria em desemprego, pobreza e desigualdade social no munic\u00edpio. A quest\u00e3o central do processo judicial passou a ser a legalidade da outorga de autoriza\u00e7\u00f5es para o servi\u00e7o de t\u00e1xi sem licita\u00e7\u00e3o e a manuten\u00e7\u00e3o das vagas para os motoristas j\u00e1 atuantes.<\/p><div class=\"kjrkg6a03c5509cbf2\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.kjrkg6a03c5509cbf2 {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.kjrkg6a03c5509cbf2 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.kjrkg6a03c5509cbf2 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.kjrkg6a03c5509cbf2 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.kjrkg6a03c5509cbf2 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.kjrkg6a03c5509cbf2 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"adfpp6a03c5509cbdf\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.adfpp6a03c5509cbdf {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.adfpp6a03c5509cbdf {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.adfpp6a03c5509cbdf {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.adfpp6a03c5509cbdf {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.adfpp6a03c5509cbdf {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.adfpp6a03c5509cbdf {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>No decorrer do processo, o Supremo Tribunal Federal (STF) firmou o entendimento de que o servi\u00e7o de motot\u00e1xi n\u00e3o se configura como servi\u00e7o p\u00fablico, mas sim como uma atividade econ\u00f4mica de interesse p\u00fablico sujeita a regime de autoriza\u00e7\u00e3o, o que afasta a necessidade de licita\u00e7\u00e3o para sua concess\u00e3o.<\/p>\n\n\n\n<p>Com base nesse entendimento do STF, o TJRN manteve a senten\u00e7a de primeira inst\u00e2ncia, proferida em 27 de fevereiro de 2025. A decis\u00e3o garante que os mototaxistas que j\u00e1 possuem alvar\u00e1 possam mant\u00ea-lo, desde que continuem a preencher os requisitos legais. Al\u00e9m disso, a decis\u00e3o estabelece que novos interessados em atuar como mototaxistas podem obter o alvar\u00e1, desde que tamb\u00e9m preencham os requisitos, sem que haja limita\u00e7\u00e3o no n\u00famero de vagas.<\/p>\n\n\n\n<p>Embora o MPRN tenha recorrido inicialmente pela exig\u00eancia de licita\u00e7\u00e3o, a decis\u00e3o final alinha-se com o entendimento de que o servi\u00e7o de t\u00e1xi \u00e9 uma atividade econ\u00f4mica regulada, n\u00e3o uma concess\u00e3o p\u00fablica limitada por vagas. A atua\u00e7\u00e3o do MPRN foi fundamental para assegurar que a outorga das autoriza\u00e7\u00f5es ocorra de forma transparente, com crit\u00e9rios imparciais para todos os mototaxistas que cumprirem os requisitos previstos em lei.<\/p>\n\n\n\n<p>A decis\u00e3o final do TJRN refor\u00e7a a seguran\u00e7a jur\u00eddica para os atuais permission\u00e1rios e abre caminho para que mais profissionais possam atuar no transporte de passageiros em Cear\u00e1-Mirim, desde que cumpram as exig\u00eancias legais, promovendo a livre concorr\u00eancia e o atendimento \u00e0 popula\u00e7\u00e3o.<br><br><em>Fonte: MPRN<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A decis\u00e3o final do TJRN refor\u00e7a a seguran\u00e7a jur\u00eddica para os atuais permission\u00e1rios e abre caminho para que mais profissionais possam atuar no transporte de passageiros na cidade. <br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2025\/06\/09\/justica-mantem-decisao-que-permite-ampla-concessao-de-alvaras-para-mototaxis-em-ceara-mirim\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/43277"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=43277"}],"version-history":[{"count":4,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/43277\/revisions"}],"predecessor-version":[{"id":43282,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/43277\/revisions\/43282"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=43277"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=43277"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=43277"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}