{"id":42068,"date":"2025-05-12T16:04:56","date_gmt":"2025-05-12T19:04:56","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=42068"},"modified":"2025-05-12T18:42:23","modified_gmt":"2025-05-12T21:42:23","slug":"cnj-analisara-caso-de-juiz-que-reconheceu-ilegalidade-de-descontos-mas-negou-pedido-de-aposentado-por-valor-ser-baixo","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2025\/05\/12\/cnj-analisara-caso-de-juiz-que-reconheceu-ilegalidade-de-descontos-mas-negou-pedido-de-aposentado-por-valor-ser-baixo\/","title":{"rendered":"CNJ analisar\u00e1 caso de juiz que reconheceu ilegalidade de descontos, mas negou pedido de aposentado"},"content":{"rendered":"\n<p>O Conselho Nacional de Justi\u00e7a (CNJ) vai analisar o caso de um juiz da comarca de S\u00e3o Miguel (RN) que negou o pedido liminar de um idoso de 84 anos para suspender descontos n\u00e3o autorizados na sua aposentadoria do Instituto Nacional do Seguro Social (INSS).<\/p>\n\n\n\n<p>O magistrado reconheceu a ilegalidade dos descontos, mas n\u00e3o viu a urg\u00eancia necess\u00e1ria para acolher o pedido do aposentado sob o argumento de que os valores debitados eram baixos, os abatimentos aconteciam h\u00e1 &#8220;tempo consider\u00e1vel&#8221; e n\u00e3o havia &#8220;perigo de dano concreto&#8221;.<\/p>\n\n\n\n<p>O idoso de 84 anos v\u00edtima dos descontos sem autoriza\u00e7\u00e3o se chama In\u00e1cio Martins de Carvalho e \u00e9 analfabeto.<\/p>\n\n\n\n<p>Ele recebe uma aposentadoria no valor de um sal\u00e1rio m\u00ednimo, R$ 1.412, e todos os meses era descontado em R$ 28,24 a t\u00edtulo de uma contribui\u00e7\u00e3o para a Associa\u00e7\u00e3o dos Aposentados e Pensionistas Nacional (AAPEN).<\/p>\n\n\n\n<p>A AAPEN est\u00e1 entre as associa\u00e7\u00f5es investigadas pela Pol\u00edcia Federal (PF) e pela Controladoria Geral da Uni\u00e3o (CGU) por fazer parte do \u201cn\u00facleo\u201d do esquema de fraudes no INSS. Os desvios, que come\u00e7aram em 2019, podem chegar a R$ 6,3 bilh\u00f5es.<\/p>\n\n\n\n<p>Os descontos na conta do aposentado come\u00e7aram em abril de 2024 e s\u00f3 foram descobertos, porque o idoso come\u00e7ou a ser assistido pela filha em raz\u00e3o de problemas de sa\u00fade. A contribui\u00e7\u00e3o equivalia a 2% sobre o valor que o aposentado recebia todos os meses.<\/p><div class=\"kpcrx6a03f85d9a8c8\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.kpcrx6a03f85d9a8c8 {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.kpcrx6a03f85d9a8c8 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.kpcrx6a03f85d9a8c8 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.kpcrx6a03f85d9a8c8 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.kpcrx6a03f85d9a8c8 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.kpcrx6a03f85d9a8c8 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"ocdvc6a03f85d9a8ac\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.ocdvc6a03f85d9a8ac {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.ocdvc6a03f85d9a8ac {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.ocdvc6a03f85d9a8ac {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.ocdvc6a03f85d9a8ac {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.ocdvc6a03f85d9a8ac {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.ocdvc6a03f85d9a8ac {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>O juiz da vara \u00fanica da Comarca de S\u00e3o Miguel, Marco Ant\u00f4nio Mendes Ribeiro, negou o pedido de suspens\u00e3o liminar dos descontos.<\/p>\n\n\n\n<p>O magistrado entendeu que, apesar de il\u00edcito, a contribui\u00e7\u00e3o n\u00e3o autorizada tinha um valor pequeno, o que n\u00e3o justificava a urg\u00eancia de uma decis\u00e3o de suspens\u00e3o.<\/p>\n\n\n\n<p>Depois de a liminar ser negada, a defesa recorreu ao Tribunal de Justi\u00e7a do Rio Grande do Norte. Nesse intervalo, os descontos continuaram por mais sete meses.<\/p>\n\n\n\n<p>Somente em mar\u00e7o de 2025 a contribui\u00e7\u00e3o n\u00e3o autorizada foi suspensa pela segunda inst\u00e2ncia. O desembargador Luiz Alberto Dantas Filho concedeu a liminar e intimou a AAPEN.<\/p>\n\n\n\n<p><em>Fonte: G1<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os descontos na conta do aposentado come\u00e7aram em abril de 2024 e s\u00f3 foram descobertos, porque o idoso come\u00e7ou a ser assistido pela filha em raz\u00e3o de problemas de sa\u00fade.<br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2025\/05\/12\/cnj-analisara-caso-de-juiz-que-reconheceu-ilegalidade-de-descontos-mas-negou-pedido-de-aposentado-por-valor-ser-baixo\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/42068"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=42068"}],"version-history":[{"count":2,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/42068\/revisions"}],"predecessor-version":[{"id":42072,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/42068\/revisions\/42072"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=42068"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=42068"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=42068"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}