{"id":42005,"date":"2025-05-10T13:53:10","date_gmt":"2025-05-10T16:53:10","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=42005"},"modified":"2025-05-10T13:53:10","modified_gmt":"2025-05-10T16:53:10","slug":"presidente-lula-nao-da-prazo-de-devolucao-do-dinheiro-do-inss","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2025\/05\/10\/presidente-lula-nao-da-prazo-de-devolucao-do-dinheiro-do-inss\/","title":{"rendered":"Presidente Lula n\u00e3o d\u00e1 prazo de devolu\u00e7\u00e3o do dinheiro do INSS"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"405\" height=\"270\" src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/05\/lula01.jpg\" alt=\"\" class=\"wp-image-42006\" srcset=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/05\/lula01.jpg 405w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/05\/lula01-300x200.jpg 300w\" sizes=\"(max-width: 405px) 100vw, 405px\" \/><figcaption>Foto: Ricardo Stuckert \/ PR<\/figcaption><\/figure>\n\n\n\n<p>O presidente Luiz In\u00e1cio Lula da Silva (PT) n\u00e3o deu prazo para a devolu\u00e7\u00e3o do dinheiro desviado de aposentados do INSS (Instituto Nacional do Seguro Social) por entidades sindicais.<\/p>\n\n\n\n<p>Em conversa com jornalistas em Moscou, na R\u00fassia, o presidente comentou sobre a opera\u00e7\u00e3o da PF (Pol\u00edcia federal) em sua declara\u00e7\u00e3o inicial. Disse que foi o seu governo que conseguiu identificar as irregularidades no \u00f3rg\u00e3o, iniciadas no governo do ex-presidente Jair Bolsonaro (PL).<\/p>\n\n\n\n<p>\u201cGra\u00e7as a Deus, a CGU [Controladoria Geral da Uni\u00e3o] e a nossa Pol\u00edcia Federal, no processo de investiga\u00e7\u00e3o, com muita intelig\u00eancia, sem nenhum alarde, conseguiram desmontar uma quadrilha que estava montada desde 2019 neste pa\u00eds\u201d, declarou.<\/p>\n\n\n\n<p>Lula disse que seu governo poderia ter feito um \u201cshow de pirotecnia\u201d depois de apurar os desvios do dinheiro de aposentados, mas que sua gest\u00e3o est\u00e1 mais atenta a devolver os recursos de quem foi prejudicado. N\u00e3o deu mais detalhes de quando o dinheiro ser\u00e1 devolvido.<\/p><div class=\"oyeva6a03f81c4ad2c\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.oyeva6a03f81c4ad2c {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.oyeva6a03f81c4ad2c {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.oyeva6a03f81c4ad2c {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.oyeva6a03f81c4ad2c {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.oyeva6a03f81c4ad2c {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.oyeva6a03f81c4ad2c {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"jkybp6a03f81c4ad15\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.jkybp6a03f81c4ad15 {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.jkybp6a03f81c4ad15 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.jkybp6a03f81c4ad15 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.jkybp6a03f81c4ad15 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.jkybp6a03f81c4ad15 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.jkybp6a03f81c4ad15 {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>\u201cVoc\u00eas sabem quem governava o Brasil em 2019. Voc\u00eas sabem quem era ministro da Previd\u00eancia em 2019. Voc\u00eas sabem quem era chefe da Casa Civil em 2019\u201d, disse. \u201cA gente poderia ter feito um show de pirotecnia, mas a gente n\u00e3o quer uma manchete criminal, a gente quer apurar\u201d.<\/p>\n\n\n\n<p>A opera\u00e7\u00e3o Sem Desconto identificou que entidades sindicais descontaram indevidamente cerca de R$ 6,5 bilh\u00f5es de aposentadorias e pens\u00f5es de 2019 a 2024.<\/p>\n\n\n\n<p><em>Fonte: Poder 360<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img alt=\"\"\/><\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A opera\u00e7\u00e3o Sem Desconto identificou que entidades sindicais descontaram indevidamente cerca de R$ 6,5 bilh\u00f5es de aposentadorias e pens\u00f5es de 2019 a 2024.<br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2025\/05\/10\/presidente-lula-nao-da-prazo-de-devolucao-do-dinheiro-do-inss\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/42005"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=42005"}],"version-history":[{"count":2,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/42005\/revisions"}],"predecessor-version":[{"id":42008,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/42005\/revisions\/42008"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=42005"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=42005"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=42005"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}