{"id":41947,"date":"2025-05-08T16:50:01","date_gmt":"2025-05-08T19:50:01","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=41947"},"modified":"2025-05-08T16:50:01","modified_gmt":"2025-05-08T19:50:01","slug":"barroso-deixa-com-1a-turma-do-stf-decisao-da-camara-sobre-ramagem","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2025\/05\/08\/barroso-deixa-com-1a-turma-do-stf-decisao-da-camara-sobre-ramagem\/","title":{"rendered":"Barroso deixa com 1\u00aa Turma do STF decis\u00e3o da C\u00e2mara sobre Ramagem"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2019\/08\/195054359-luis-roberto-barroso-e-demais-ministros-do-stf-estao-sendo-pressionados-para-se-posicionarem-respeit-1024x683-1024x683.jpg\" alt=\"\" class=\"wp-image-1461\" srcset=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2019\/08\/195054359-luis-roberto-barroso-e-demais-ministros-do-stf-estao-sendo-pressionados-para-se-posicionarem-respeit-1024x683.jpg 1024w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2019\/08\/195054359-luis-roberto-barroso-e-demais-ministros-do-stf-estao-sendo-pressionados-para-se-posicionarem-respeit-1024x683-300x200.jpg 300w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2019\/08\/195054359-luis-roberto-barroso-e-demais-ministros-do-stf-estao-sendo-pressionados-para-se-posicionarem-respeit-1024x683-768x512.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>Foto: Reprodu\u00e7\u00e3o <\/figcaption><\/figure>\n\n\n\n<p>O presidente do STF (Supremo Tribunal Federal), Lu\u00eds Roberto Barroso, enviou nesta quinta-feira (8) \u00e0 presid\u00eancia da Primeira Turma do tribunal a an\u00e1lise da decis\u00e3o da C\u00e2mara que tenta suspender o processo contra o deputado federal Alexandre Ramagem (PL-RJ).<\/p>\n\n\n\n<p>Caber\u00e1 ao ministro Cristiano Zanin, presidente do colegiado, decidir uma data para o julgamento do caso.<\/p>\n\n\n\n<p>A C\u00e2mara aprovou na quarta-feira (7) uma proposta que tenta suspender por completo a a\u00e7\u00e3o penal contra Ramagem.<\/p>\n\n\n\n<p>Ministros do Supremo afirmaram \u00e0 Folha de S. Paulo, sob reserva, que a tentativa da C\u00e2mara \u00e9 inconstitucional e deve ser derrubada.<\/p><div class=\"meoay6a04067f8c4b7\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.meoay6a04067f8c4b7 {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.meoay6a04067f8c4b7 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.meoay6a04067f8c4b7 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.meoay6a04067f8c4b7 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.meoay6a04067f8c4b7 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.meoay6a04067f8c4b7 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"qgmod6a04067f8c497\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.qgmod6a04067f8c497 {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.qgmod6a04067f8c497 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.qgmod6a04067f8c497 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.qgmod6a04067f8c497 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.qgmod6a04067f8c497 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.qgmod6a04067f8c497 {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>No entendimento do tribunal, a Constitui\u00e7\u00e3o somente permite a suspens\u00e3o do processo em rela\u00e7\u00e3o aos crimes cometidos por Ramagem ap\u00f3s sua diploma\u00e7\u00e3o como deputado federal.<\/p>\n\n\n\n<p>Zanin informou \u00e0 C\u00e2mara que a den\u00fancia da PGR (Procuradoria-Geral da Rep\u00fablica) revela que o deputado possivelmente cometeu os crimes de dano qualificado ao patrim\u00f4nio p\u00fablico e deteriora\u00e7\u00e3o do patrim\u00f4nio tombado ap\u00f3s a diploma\u00e7\u00e3o.<\/p>\n\n\n\n<p>Outros tr\u00eas delitos \u2014associa\u00e7\u00e3o criminosa armada, golpe de Estado e aboli\u00e7\u00e3o do Estado democr\u00e1tico de direito\u2014 pelos quais Ramagem \u00e9 r\u00e9u teriam sido cometidos antes da diploma\u00e7\u00e3o e, portanto, n\u00e3o estariam no guarda-chuva de an\u00e1lise da C\u00e2mara, j\u00e1 que ele n\u00e3o era ainda parlamentar quando praticados.<\/p>\n\n\n\n<p><em>Fonte: Folha de S. Paulo<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Caber\u00e1 ao ministro Cristiano Zanin, presidente do colegiado, decidir uma data para o julgamento do caso.<br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2025\/05\/08\/barroso-deixa-com-1a-turma-do-stf-decisao-da-camara-sobre-ramagem\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/41947"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=41947"}],"version-history":[{"count":2,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/41947\/revisions"}],"predecessor-version":[{"id":41949,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/41947\/revisions\/41949"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=41947"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=41947"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=41947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}