{"id":41818,"date":"2025-05-06T08:05:00","date_gmt":"2025-05-06T11:05:00","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=41818"},"modified":"2025-05-05T21:25:48","modified_gmt":"2025-05-06T00:25:48","slug":"advocacia-potiguar-tera-50-vagas-para-uso-no-estacionamento-interno-do-tribunal-de-justica-do-rn","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2025\/05\/06\/advocacia-potiguar-tera-50-vagas-para-uso-no-estacionamento-interno-do-tribunal-de-justica-do-rn\/","title":{"rendered":"Advocacia potiguar ter\u00e1 50 vagas para uso no estacionamento interno do Tribunal de Justi\u00e7a do RN"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"768\" height=\"1024\" src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/05\/IMG-20250505-WA0232-768x1024.jpg\" alt=\"\" class=\"wp-image-41822\" srcset=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/05\/IMG-20250505-WA0232-768x1024.jpg 768w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/05\/IMG-20250505-WA0232-225x300.jpg 225w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/05\/IMG-20250505-WA0232-1152x1536.jpg 1152w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/05\/IMG-20250505-WA0232-1536x2048.jpg 1536w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/05\/IMG-20250505-WA0232-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><figcaption>Foto: Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n\n\n\n<p>Ap\u00f3s reuni\u00e3o institucional com o Tribunal de Justi\u00e7a do Rio Grande do Norte (TJ\/RN), a Ordem dos Advogados do Brasil no Rio Grande do Norte (OAB\/RN) conquistou a amplia\u00e7\u00e3o das vagas para uso da advocacia na sede do Tribunal.<\/p>\n\n\n\n<p>O processo de amplia\u00e7\u00e3o das vagas j\u00e1 est\u00e1 em andamento e todas as vagas devem estar dispon\u00edveis para uso da advocacia potiguar e de membros do sistema de justi\u00e7a at\u00e9 o dia 30 de maio, segundo informa\u00e7\u00f5es do TJ\/RN. Inicialmente ser\u00e3o disponibilizadas 50 vagas para uso da advocacia no estacionamento interno do Tribunal.<\/p>\n\n\n\n<p>\u201cEssa pauta \u00e9 de extrema import\u00e2ncia para a advocacia e vem de um debate que est\u00e1 sendo travado h\u00e1 muito tempo com o Tribunal, mas que a atual gest\u00e3o trabalhou, desde o primeiro dia de janeiro, para solucionar as pend\u00eancias e afastar os obst\u00e1culos. Enfim recebemos a not\u00edcia: ainda no m\u00eas de maio ser\u00e1 iniciada a fase de teste da amplia\u00e7\u00e3o de vagas e a advocacia poder\u00e1 fazer uso do estacionamento do TJ\/RN\u201d, celebra o presidente da OAB\/RN, Carlos Kelsen.<\/p><div class=\"fdpzm6a0413148280b\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.fdpzm6a0413148280b {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.fdpzm6a0413148280b {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.fdpzm6a0413148280b {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.fdpzm6a0413148280b {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.fdpzm6a0413148280b {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.fdpzm6a0413148280b {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"mciso6a041314827f8\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.mciso6a041314827f8 {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.mciso6a041314827f8 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.mciso6a041314827f8 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.mciso6a041314827f8 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.mciso6a041314827f8 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.mciso6a041314827f8 {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>O uso das vagas disponibilizadas ser\u00e1 efetivado a partir de um cadastramento eletr\u00f4nico previamente realizado pela OAB\/RN. As informa\u00e7\u00f5es sobre o cadastramento ser\u00e3o divulgadas nos pr\u00f3ximos dias.<\/p>\n\n\n\n<p><em>Fonte: OAB\/RN<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O processo de amplia\u00e7\u00e3o das vagas j\u00e1 est\u00e1 em andamento e todas as vagas devem estar dispon\u00edveis para uso da advocacia potiguar e de membros do sistema de justi\u00e7a at\u00e9 o dia 30 de maio.<br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2025\/05\/06\/advocacia-potiguar-tera-50-vagas-para-uso-no-estacionamento-interno-do-tribunal-de-justica-do-rn\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/41818"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=41818"}],"version-history":[{"count":3,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/41818\/revisions"}],"predecessor-version":[{"id":41827,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/41818\/revisions\/41827"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=41818"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=41818"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=41818"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}