{"id":41757,"date":"2025-05-04T16:15:00","date_gmt":"2025-05-04T19:15:00","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=41757"},"modified":"2025-05-05T08:35:03","modified_gmt":"2025-05-05T11:35:03","slug":"justica-condena-varejista-a-indenizar-moradora-de-currais-novos-que-nao-recebeu-smartphone-comprado-pela-internet","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2025\/05\/04\/justica-condena-varejista-a-indenizar-moradora-de-currais-novos-que-nao-recebeu-smartphone-comprado-pela-internet\/","title":{"rendered":"Justi\u00e7a condena varejista a indenizar mulher que n\u00e3o recebeu smartphone comprado pela Internet"},"content":{"rendered":"\n<p>Uma empresa varejista foi condenada a indenizar em R$ 3 mil, por danos morais, uma cliente de Currais Novos que comprou um smartphone em seu site e n\u00e3o recebeu o produto. A decis\u00e3o \u00e9 da ju\u00edza Maria Nadja Bezerra Cavalcanti, do Juizado Especial C\u00edvel e Criminal da Comarca de Currais Novos.<\/p>\n\n\n\n<p>De acordo com os autos do processo, a cliente comprou um celular no site da varejista, junto a uma empresa que utilizava a loja virtual da varejista, entretanto, o produto nunca foi entregue. Ainda, foi identificado que a parte autora tentou, durante quatro meses, a resolu\u00e7\u00e3o do problema diretamente com a gestora do site, conseguindo a devolu\u00e7\u00e3o do valor pago somente ap\u00f3s recorrer \u00e0 Justi\u00e7a.<\/p>\n\n\n\n<p>A empresa r\u00e9 se defendeu, afirmando que a responsabilidade pelo problema era exclusivamente do vendedor, sendo encarregada somente pela manuten\u00e7\u00e3o da loja virtual. A varejista ainda refor\u00e7ou ter atendido o pedido de estorno da compra.<\/p><div class=\"oaped6a042029643b7\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.oaped6a042029643b7 {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.oaped6a042029643b7 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.oaped6a042029643b7 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.oaped6a042029643b7 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.oaped6a042029643b7 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.oaped6a042029643b7 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"qlred6a042029643a3\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.qlred6a042029643a3 {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.qlred6a042029643a3 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.qlred6a042029643a3 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.qlred6a042029643a3 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.qlred6a042029643a3 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.qlred6a042029643a3 {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>Ao analisar o caso, a magistrada refutou o argumento da empresa varejista, j\u00e1 que, independente do produto ser de outra loja, a compra foi realizada por meio de sua plataforma. \u201cSendo assim, a empresa que opera o marketplace integra e tem responsabilidade na cadeia de fornecimento, devendo, desse modo, responder pelos fatos relacionados aos bens adquiridos por consumidores em seu site, independentemente de quem seja o lojista\u201d, refor\u00e7ou.<\/p>\n\n\n\n<p>A ju\u00edza Maria Nadja Bezerra Cavalcanti tamb\u00e9m ressaltou a demora na devolu\u00e7\u00e3o do valor pago, o que aconteceu somente ap\u00f3s a consumidora procurar a Justi\u00e7a, refor\u00e7ando, assim, a inefici\u00eancia do servi\u00e7o prestado pela gestora do site, ultrapassando o \u201cmero dissabor e ensejando dano moral a ser reparado\u201d. Diante do material colhido e da rela\u00e7\u00e3o de consumo, amparada pelo C\u00f3digo de Defesa do Consumidor (CDC), ficou configurado o dano moral.<\/p>\n\n\n\n<p>TJRN<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A empresa r\u00e9 se defendeu, afirmando que a responsabilidade pelo problema era exclusivamente do vendedor, sendo encarregada somente pela manuten\u00e7\u00e3o da loja virtual. <br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2025\/05\/04\/justica-condena-varejista-a-indenizar-moradora-de-currais-novos-que-nao-recebeu-smartphone-comprado-pela-internet\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/41757"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=41757"}],"version-history":[{"count":4,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/41757\/revisions"}],"predecessor-version":[{"id":41778,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/41757\/revisions\/41778"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=41757"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=41757"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=41757"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}