{"id":41658,"date":"2025-04-30T07:27:22","date_gmt":"2025-04-30T10:27:22","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=41658"},"modified":"2025-04-30T07:27:22","modified_gmt":"2025-04-30T10:27:22","slug":"mpf-reforca-urgencia-de-consulta-a-comunidade-sobre-obras-e-gestao-do-complexo-turistico-da-redinha","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2025\/04\/30\/mpf-reforca-urgencia-de-consulta-a-comunidade-sobre-obras-e-gestao-do-complexo-turistico-da-redinha\/","title":{"rendered":"MPF refor\u00e7a urg\u00eancia de consulta \u00e0 comunidade sobre obras e gest\u00e3o do complexo tur\u00edstico da Redinha"},"content":{"rendered":"\n<p>O Minist\u00e9rio P\u00fablico Federal (MPF) reiterou a necessidade urgente de consulta pr\u00e9via, livre e informada (CPLI) \u00e0 comunidade tradicional local sobre obras e gest\u00e3o do Complexo Tur\u00edstico da Redinha, em Natal (RN). Ribeirinhos, pescadores artesanais, marisqueiras, barraqueiros e pequenos comerciantes est\u00e3o exclu\u00eddos das decis\u00f5es, mesmo sendo reconhecidos pela Uni\u00e3o como comunidade tradicional.<\/p>\n\n\n\n<p>Em&nbsp;<strong><a href=\"https:\/\/novoportal.mpf.mp.br\/mpf\/rn\/sala-de-imprensa\/noticias-rn\/mpf-cobra-consulta-a-comunidade-tradicional-sobre-obras-e-gestao-do-complexo-turistico-da-redinha-em-natal-rn\" target=\"_blank\" rel=\"noreferrer noopener\">a\u00e7\u00e3o civil p\u00fablica<\/a><\/strong>&nbsp;j\u00e1 em andamento, o MPF pede que a Justi\u00e7a Federal pro\u00edba o munic\u00edpio de Natal de adotar qualquer nova medida administrativa ou legislativa na \u00e1rea sem a participa\u00e7\u00e3o da comunidade. O pedido \u00e9 urgente porque o Mercado da Redinha, fonte de subsist\u00eancia dos locais, est\u00e1 prestes a ser concedido \u00e0 iniciativa privada, o que pode acontecer nos pr\u00f3ximos 60 dias sem uma interven\u00e7\u00e3o judicial.<\/p>\n\n\n\n<p>O MPF aponta que a Uni\u00e3o reconheceu a exist\u00eancia da comunidade tradicional costeira ao firmar dois Termos de Autoriza\u00e7\u00e3o de Uso Sustent\u00e1vel (TAUS) com a Col\u00f4nia de Pescadores Z-04 de Pesca e Aquicultura Jos\u00e9 Bonif\u00e1cio. O TAUS \u00e9 um instrumento espec\u00edfico para a preserva\u00e7\u00e3o de comunidades tradicionais. Portanto, o reconhecimento leva \u00e0 necessidade de consulta pr\u00e9via \u00e0 comunidade antes das interven\u00e7\u00f5es, conforme a Conven\u00e7\u00e3o n\u00ba 169 da Organiza\u00e7\u00e3o Internacional do Trabalho (OIT).<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"640\" height=\"480\" src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/04\/images-2025-04-30T072638.145.jpeg\" alt=\"\" class=\"wp-image-41659\" srcset=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/04\/images-2025-04-30T072638.145.jpeg 640w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/04\/images-2025-04-30T072638.145-300x225.jpeg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><figcaption>Reprodu\u00e7\u00e3o<\/figcaption><\/figure>\n\n\n\n<p>O procurador da Rep\u00fablica Cam\u00f5es Boaventura refor\u00e7a que \u201ca aus\u00eancia de consulta, de participa\u00e7\u00e3o efetiva e de medidas de repara\u00e7\u00e3o agrava, a cada dia, o risco de desarticula\u00e7\u00e3o e destrui\u00e7\u00e3o desse modo de vida tradicional, amea\u00e7ando de forma irrepar\u00e1vel a continuidade hist\u00f3rica, cultural e social das comunidades pesqueiras e ribeirinhas que h\u00e1 gera\u00e7\u00f5es habitam e dependem daquele espa\u00e7o\u201d.<\/p><div class=\"gtpqc6a042cfb14b6e\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.gtpqc6a042cfb14b6e {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.gtpqc6a042cfb14b6e {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.gtpqc6a042cfb14b6e {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.gtpqc6a042cfb14b6e {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.gtpqc6a042cfb14b6e {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.gtpqc6a042cfb14b6e {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"fckrx6a042cfb14b4c\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.fckrx6a042cfb14b4c {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.fckrx6a042cfb14b4c {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.fckrx6a042cfb14b4c {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.fckrx6a042cfb14b4c {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.fckrx6a042cfb14b4c {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.fckrx6a042cfb14b4c {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p><strong>Complexo<\/strong>&nbsp;&#8211; As obras do Complexo Tur\u00edstico da Redinha incluem o mercado p\u00fablico, os quiosques da praia e o espa\u00e7o de guarda, entrada e sa\u00edda de embarca\u00e7\u00f5es. Passados mais de dois anos e meio de paralisa\u00e7\u00e3o das obras, motivada por atrasos em sua execu\u00e7\u00e3o, e com mais de 30 milh\u00f5es de reais investidos, o espa\u00e7o permanece fechado e sem qualquer utilidade pr\u00e1tica.<\/p>\n\n\n\n<p>O processo de concess\u00e3o est\u00e1 atualmente na fase de an\u00e1lise de duas propostas de estudos t\u00e9cnicos e econ\u00f4micos, apresentadas para a defini\u00e7\u00e3o do modelo de concess\u00e3o. Se o procedimento proposto pelo munic\u00edpio seguir, a prefeitura analisar\u00e1 as propostas apresentadas e a empresa vencedora ter\u00e1 o prazo de 60 dias para concluir os estudos, com o objetivo de subsidiar a elabora\u00e7\u00e3o do edital de licita\u00e7\u00e3o do espa\u00e7o.<\/p>\n\n\n\n<p><strong>Consulta \u00e0 comunidade<\/strong>&nbsp;&#8211; A realiza\u00e7\u00e3o de consulta pr\u00e9via, livre e informada (CPLI) \u00e0s comunidades tradicionais sobre interven\u00e7\u00f5es em seus territ\u00f3rios est\u00e1 prevista na Conven\u00e7\u00e3o n\u00ba 169 da Organiza\u00e7\u00e3o Internacional do Trabalho (OIT) sobre Povos Ind\u00edgenas e tribais, da qual o Brasil \u00e9 signat\u00e1rio. Os princ\u00edpios que estabelecem esse direito visam garantir a legitimidade e a efetividade das a\u00e7\u00f5es governamentais, considerando o impacto das decis\u00f5es na vida dessas popula\u00e7\u00f5es.<\/p>\n\n\n\n<p>A\u00e7\u00e3o Civil P\u00fablica n\u00ba 0801942-04.2025.4.05.8400.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Minist\u00e9rio P\u00fablico Federal (MPF) reiterou a necessidade urgente de consulta pr\u00e9via, livre e informada (CPLI) \u00e0 comunidade tradicional local sobre obras e gest\u00e3o do Complexo Tur\u00edstico da Redinha, em Natal (RN). Ribeirinhos, pescadores artesanais, marisqueiras, barraqueiros e pequenos comerciantes est\u00e3o exclu\u00eddos das decis\u00f5es, mesmo sendo reconhecidos pela Uni\u00e3o como comunidade tradicional. Em&nbsp;a\u00e7\u00e3o civil p\u00fablica&nbsp;j\u00e1<br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2025\/04\/30\/mpf-reforca-urgencia-de-consulta-a-comunidade-sobre-obras-e-gestao-do-complexo-turistico-da-redinha\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/41658"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=41658"}],"version-history":[{"count":1,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/41658\/revisions"}],"predecessor-version":[{"id":41660,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/41658\/revisions\/41660"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=41658"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=41658"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=41658"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}