{"id":41644,"date":"2025-04-29T13:15:30","date_gmt":"2025-04-29T16:15:30","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=41644"},"modified":"2025-04-29T13:15:30","modified_gmt":"2025-04-29T16:15:30","slug":"tre-rn-firma-parceria-com-defensoria-publica-e-itep","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2025\/04\/29\/tre-rn-firma-parceria-com-defensoria-publica-e-itep\/","title":{"rendered":"TRE-RN firma parceria com Defensoria P\u00fablica e ITEP"},"content":{"rendered":"\n<p>Nesta segunda-feira (28), o Tribunal Regional Eleitoral do Rio Grande do Norte (TRE-RN) deu mais um importante passo em sua atua\u00e7\u00e3o social ao promover uma reuni\u00e3o que consolidou uma parceria estrat\u00e9gica com a Defensoria P\u00fablica do Estado e o Instituto T\u00e9cnico-Cient\u00edfico de Per\u00edcia (ITEP\/RN). O encontro, conduzido pela ju\u00edza auxiliar da Presid\u00eancia, Dra. Ana Paula Barbosa, ocorreu no gabinete da diretoria-geral e teve como foco o fortalecimento das a\u00e7\u00f5es de cidadania direcionadas a comunidades ind\u00edgenas e quilombolas no estado, dentro da Agenda pela Equidade e Diversidade do TRE-RN.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"818\" height=\"409\" src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/04\/fe321d48-4e3d-4064-b920-fb98d17905bf.jpeg\" alt=\"\" class=\"wp-image-41645\" srcset=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/04\/fe321d48-4e3d-4064-b920-fb98d17905bf.jpeg 818w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/04\/fe321d48-4e3d-4064-b920-fb98d17905bf-300x150.jpeg 300w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2025\/04\/fe321d48-4e3d-4064-b920-fb98d17905bf-768x384.jpeg 768w\" sizes=\"(max-width: 818px) 100vw, 818px\" \/><\/figure>\n\n\n\n<p>A reuni\u00e3o marcou o alinhamento das institui\u00e7\u00f5es para viabilizar atendimentos conjuntos, possibilitando que, al\u00e9m dos servi\u00e7os eleitorais, sejam ofertados documentos b\u00e1sicos de identifica\u00e7\u00e3o civil e orienta\u00e7\u00f5es jur\u00eddicas a popula\u00e7\u00f5es historicamente vulnerabilizadas.<\/p>\n\n\n\n<p>De acordo com a ju\u00edza Ana Paula Barbosa, a iniciativa busca levar dignidade e cidadania a quem mais precisa. \u201cEssa parceria com o TRE \u00e9 extremamente interessante porque vamos atender popula\u00e7\u00f5es que n\u00e3o t\u00eam acesso r\u00e1pido ao servi\u00e7o p\u00fablico, principalmente ao servi\u00e7o de emiss\u00e3o de identidade, que \u00e9 o documento prim\u00e1rio para qualquer cidad\u00e3o. Assim, conseguimos levar esse servi\u00e7o junto com o atendimento do TRE para perto das comunidades, garantindo cidadania a quem realmente precisa\u201d, afirmou.<\/p><div class=\"fuboj6a042cd7cef8e\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.fuboj6a042cd7cef8e {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.fuboj6a042cd7cef8e {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.fuboj6a042cd7cef8e {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.fuboj6a042cd7cef8e {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.fuboj6a042cd7cef8e {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.fuboj6a042cd7cef8e {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"melxb6a042cd7cef75\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.melxb6a042cd7cef75 {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.melxb6a042cd7cef75 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.melxb6a042cd7cef75 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.melxb6a042cd7cef75 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.melxb6a042cd7cef75 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.melxb6a042cd7cef75 {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>O ITEP tamb\u00e9m demonstrou entusiasmo com a parceria. Segundo o diretor Marcos Brand\u00e3o, a uni\u00e3o das institui\u00e7\u00f5es permitir\u00e1 alcan\u00e7ar p\u00fablicos que, muitas vezes, n\u00e3o conseguem acessar os servi\u00e7os p\u00fablicos essenciais. \u201cFicamos muito felizes em saber que h\u00e1 interesse m\u00fatuo em levar nossos servi\u00e7os para comunidades ind\u00edgenas e quilombolas. Dessa forma, traremos mais benef\u00edcios a essas popula\u00e7\u00f5es\u201d, destacou. E segundo o chefe de conv\u00eanios do ITEP-RN, Canind\u00e9 Barbalho, o Instituto dever\u00e1 participar de algumas a\u00e7\u00f5es a partir do segundo semestre do ano.<\/p>\n\n\n\n<p>O defensor p\u00fablico-geral, Marcos Vin\u00edcius Soares&nbsp; Alves, refor\u00e7ou o compromisso do \u00f3rg\u00e3o em ampliar o acesso \u00e0 justi\u00e7a. \u201cA Defensoria vem manifestar com muito entusiasmo o interesse de se integrar \u00e0s a\u00e7\u00f5es do TRE-RN para participar dessas iniciativas t\u00e3o importantes, levando direitos a pessoas que historicamente s\u00e3o esquecidas pela sociedade\u201d, declarou.<\/p>\n\n\n\n<p>A a\u00e7\u00e3o conjunta refor\u00e7a o compromisso do TRE-RN com a promo\u00e7\u00e3o da inclus\u00e3o, da diversidade e da equidade social. A parceria entre os \u00f3rg\u00e3os \u00e9 mais um passo para aproximar os servi\u00e7os p\u00fablicos da popula\u00e7\u00e3o, especialmente daquelas comunidades que enfrentam maiores barreiras para o exerc\u00edcio pleno da cidadania.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nesta segunda-feira (28), o Tribunal Regional Eleitoral do Rio Grande do Norte (TRE-RN) deu mais um importante passo em sua atua\u00e7\u00e3o social ao promover uma reuni\u00e3o que consolidou uma parceria estrat\u00e9gica com a Defensoria P\u00fablica do Estado e o Instituto T\u00e9cnico-Cient\u00edfico de Per\u00edcia (ITEP\/RN). O encontro, conduzido pela ju\u00edza auxiliar da Presid\u00eancia, Dra. Ana Paula<br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2025\/04\/29\/tre-rn-firma-parceria-com-defensoria-publica-e-itep\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/41644"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=41644"}],"version-history":[{"count":1,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/41644\/revisions"}],"predecessor-version":[{"id":41646,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/41644\/revisions\/41646"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=41644"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=41644"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=41644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}