{"id":41639,"date":"2025-04-29T11:12:21","date_gmt":"2025-04-29T14:12:21","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=41639"},"modified":"2025-04-29T11:12:21","modified_gmt":"2025-04-29T14:12:21","slug":"plano-de-saude-deve-custear-cirurgias-plasticas-reparadoras-apos-procedimento-bariatrico","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2025\/04\/29\/plano-de-saude-deve-custear-cirurgias-plasticas-reparadoras-apos-procedimento-bariatrico\/","title":{"rendered":"Plano de sa\u00fade deve custear cirurgias pl\u00e1sticas reparadoras ap\u00f3s procedimento bari\u00e1trico"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2019\/10\/cirurgia-002-1-1024x683.jpg\" alt=\"\" class=\"wp-image-3306\" srcset=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2019\/10\/cirurgia-002-1-1024x683.jpg 1024w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2019\/10\/cirurgia-002-1-300x200.jpg 300w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2019\/10\/cirurgia-002-1-768x512.jpg 768w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2019\/10\/cirurgia-002-1.jpg 1125w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>Reprodu\u00e7\u00e3o <\/figcaption><\/figure>\n\n\n\n<p>A 2\u00aa C\u00e2mara C\u00edvel do TJRN manteve uma senten\u00e7a inicial, que condenou uma operadora de plano de sa\u00fade ao pagamento de indeniza\u00e7\u00e3o por danos morais e ao custeio das cirurgias pl\u00e1sticas reparadoras p\u00f3s-bari\u00e1tricas indicadas por prescri\u00e7\u00e3o m\u00e9dica.Conforme o \u00f3rg\u00e3o julgador, a operadora deve cobrir cirurgias pl\u00e1sticas reparadoras p\u00f3s-bari\u00e1tricas, quando indicadas por prescri\u00e7\u00e3o m\u00e9dica, independente da previs\u00e3o no rol da Ag\u00eancia Nacional de Sa\u00fade (ANS), desde que possuam car\u00e1ter funcional e reparador.<\/p><div class=\"waccg6a042d0d1ca9e\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.waccg6a042d0d1ca9e {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.waccg6a042d0d1ca9e {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.waccg6a042d0d1ca9e {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.waccg6a042d0d1ca9e {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.waccg6a042d0d1ca9e {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.waccg6a042d0d1ca9e {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"rqhuy6a042d0d1ca8b\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.rqhuy6a042d0d1ca8b {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.rqhuy6a042d0d1ca8b {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.rqhuy6a042d0d1ca8b {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.rqhuy6a042d0d1ca8b {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.rqhuy6a042d0d1ca8b {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.rqhuy6a042d0d1ca8b {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>\u201cA cirurgia pl\u00e1stica reparadora p\u00f3s-bari\u00e1trica integra o tratamento da obesidade m\u00f3rbida quando indicada para assegurar a sa\u00fade e funcionalidade do paciente, sendo obrigat\u00f3ria sua cobertura pelos planos de sa\u00fade, conforme entendimento consolidado pelo STJ no\u00a0Tema\u00a01.069\u201d, explica o relator, o juiz convocado Roberto Guedes, atuando no gabinete da desembargadora Sandra Elali, que assumiu as fun\u00e7\u00f5es de Corregedora Geral de Justi\u00e7a.De acordo com a decis\u00e3o, a cl\u00e1usula contratual que exclui procedimentos est\u00e9ticos n\u00e3o pode ser utilizada para recusar cobertura a cirurgias que possuem car\u00e1ter funcional e reparador, sob pena de afronta ao\u00a0C\u00f3digo\u00a0de Defesa do Consumidor e \u00e0\u00a0Lei\u00a0n\u00ba 9.656\/98.\u201cA recusa indevida da operadora em custear o procedimento essencial ao restabelecimento do paciente configura falha na presta\u00e7\u00e3o do servi\u00e7o e enseja repara\u00e7\u00e3o por danos morais, considerando o sofrimento psicol\u00f3gico adicional imposto ao benefici\u00e1rio\u201d, enfatiza o relator, ao destacar que a demanda caracteriza a garantia ao cumprimento do dever contratual de prover a sa\u00fade e bem-estar do benefici\u00e1rio, n\u00e3o se justificando a invoca\u00e7\u00e3o de quest\u00f5es financeiras para mitigar esse direito essencial.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A 2\u00aa C\u00e2mara C\u00edvel do TJRN manteve uma senten\u00e7a inicial, que condenou uma operadora de plano de sa\u00fade ao pagamento de indeniza\u00e7\u00e3o por danos morais e ao custeio das cirurgias pl\u00e1sticas reparadoras p\u00f3s-bari\u00e1tricas indicadas por prescri\u00e7\u00e3o m\u00e9dica.Conforme o \u00f3rg\u00e3o julgador, a operadora deve cobrir cirurgias pl\u00e1sticas reparadoras p\u00f3s-bari\u00e1tricas, quando indicadas por prescri\u00e7\u00e3o m\u00e9dica, independente da<br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2025\/04\/29\/plano-de-saude-deve-custear-cirurgias-plasticas-reparadoras-apos-procedimento-bariatrico\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/41639"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=41639"}],"version-history":[{"count":1,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/41639\/revisions"}],"predecessor-version":[{"id":41640,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/41639\/revisions\/41640"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=41639"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=41639"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=41639"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}