{"id":41632,"date":"2025-04-29T07:21:00","date_gmt":"2025-04-29T10:21:00","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=41632"},"modified":"2025-04-28T21:24:55","modified_gmt":"2025-04-29T00:24:55","slug":"video-advogada-participa-de-audiencia-em-deslocamento-caso-levanta-debate","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2025\/04\/29\/video-advogada-participa-de-audiencia-em-deslocamento-caso-levanta-debate\/","title":{"rendered":"V\u00cdDEO: Advogada participa de audi\u00eancia em &#8220;deslocamento&#8221;; caso levanta debate"},"content":{"rendered":"\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Juiz e advogados criticam postura de advogada que aparece &quot;em deslocamento&quot; durante audi\u00eancia\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/IAEwIC9Bdqw?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Recentemente, uma advogada participou de audi\u00eancia virtual enquanto &#8220;se deslocava&#8221;, situa\u00e7\u00e3o que causou desconforto e gerou cr\u00edticas tanto do juiz quanto dos demais advogados presentes no ato.<\/p>\n\n\n\n<p>O epis\u00f3dio, embora chamativo, est\u00e1 longe de ser caso isolado na pr\u00e1tica forense contempor\u00e2nea. Em alguns contextos, situa\u00e7\u00f5es como essa refletem des\u00eddia profissional; em outros, resultam da pr\u00f3pria din\u00e2mica acelerada da advocacia moderna.<\/p>\n\n\n\n<p>A correria do dia a dia, os lit\u00edgios em massa e a crescente digitaliza\u00e7\u00e3o do Judici\u00e1rio v\u00eam reformulando a liturgia jur\u00eddica, impondo novos desafios \u00e0 preserva\u00e7\u00e3o do equil\u00edbrio entre respeito aos atos e \u00e0 flexibiliza\u00e7\u00e3o de posturas.<\/p>\n\n\n\n<p><strong>Postura inadequada<\/strong><\/p>\n\n\n\n<p>No caso em quest\u00e3o, ao perceber que a advogada participava da audi\u00eancia de maneira incompat\u00edvel com a solenidade do ato, o magistrado registrou sua insatisfa\u00e7\u00e3o, apontando a falta de aten\u00e7\u00e3o devida ao processo.<\/p><div class=\"wszxl6a042cd7418ee\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.wszxl6a042cd7418ee {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.wszxl6a042cd7418ee {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.wszxl6a042cd7418ee {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.wszxl6a042cd7418ee {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.wszxl6a042cd7418ee {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.wszxl6a042cd7418ee {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"ffxst6a042cd7418d4\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.ffxst6a042cd7418d4 {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.ffxst6a042cd7418d4 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.ffxst6a042cd7418d4 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.ffxst6a042cd7418d4 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.ffxst6a042cd7418d4 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.ffxst6a042cd7418d4 {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>Embora tenha optado por n\u00e3o adotar provid\u00eancias formais, o juiz lamentou publicamente o ocorrido, ressaltando que &#8220;<em>cada um arca com os \u00f4nus e b\u00f4nus de sua atividade<\/em>&#8220;.<\/p>\n\n\n\n<p>A cr\u00edtica refor\u00e7ou a necessidade de preserva\u00e7\u00e3o do respeito aos atos processuais, mesmo em tempos de flexibiliza\u00e7\u00e3o tecnol\u00f3gica.<\/p>\n\n\n\n<p>Os demais caus\u00eddicos presentes tamb\u00e9m se manifestaram, classificando a conduta como inadequada ao exerc\u00edcio da advocacia e refor\u00e7ando a import\u00e2ncia da postura \u00e9tica e respeitosa nos atos judiciais.<\/p>\n\n\n\n<p>A audi\u00eancia foi encerrada em clima de lamento, mas sem aplica\u00e7\u00e3o de san\u00e7\u00f5es disciplinares.<\/p>\n\n\n\n<p>Migalhas<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Recentemente, uma advogada participou de audi\u00eancia virtual enquanto &#8220;se deslocava&#8221;, situa\u00e7\u00e3o que causou desconforto e gerou cr\u00edticas tanto do juiz quanto dos demais advogados presentes no ato. O epis\u00f3dio, embora chamativo, est\u00e1 longe de ser caso isolado na pr\u00e1tica forense contempor\u00e2nea. Em alguns contextos, situa\u00e7\u00f5es como essa refletem des\u00eddia profissional; em outros, resultam da pr\u00f3pria<br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2025\/04\/29\/video-advogada-participa-de-audiencia-em-deslocamento-caso-levanta-debate\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/41632"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=41632"}],"version-history":[{"count":1,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/41632\/revisions"}],"predecessor-version":[{"id":41633,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/41632\/revisions\/41633"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=41632"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=41632"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=41632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}