{"id":41572,"date":"2025-04-24T11:25:09","date_gmt":"2025-04-24T14:25:09","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=41572"},"modified":"2025-04-24T11:25:09","modified_gmt":"2025-04-24T14:25:09","slug":"autismo-obrigatoriedade-de-tratamento-domiciliar-e-tema-em-novo-julgamento","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2025\/04\/24\/autismo-obrigatoriedade-de-tratamento-domiciliar-e-tema-em-novo-julgamento\/","title":{"rendered":"AUTISMO: obrigatoriedade de tratamento domiciliar \u00e9 tema em novo julgamento"},"content":{"rendered":"\n<p>A 3\u00aa C\u00e2mara C\u00edvel do TJRN n\u00e3o deu provimento aos apelos concomitantes, movidos por uma operadora de plano de sa\u00fade e pela benefici\u00e1ria, e manteve, desta forma, uma decis\u00e3o judicial que determinava a autoriza\u00e7\u00e3o e cobertura de tratamento multidisciplinar para o Transtorno do Espectro Autista (TEA), conforme prescri\u00e7\u00e3o m\u00e9dica, sem limita\u00e7\u00f5es de sess\u00f5es<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"800\" height=\"526\" src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/08\/Site-Vara-determina-que-a-Caixa-cubra-assiste\u0302ncia-a\u0300-crianc\u0327a-com-Transtorno-do-Espectro-Autista.jpg\" alt=\"\" class=\"wp-image-33107\" srcset=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/08\/Site-Vara-determina-que-a-Caixa-cubra-assiste\u0302ncia-a\u0300-crianc\u0327a-com-Transtorno-do-Espectro-Autista.jpg 800w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/08\/Site-Vara-determina-que-a-Caixa-cubra-assiste\u0302ncia-a\u0300-crianc\u0327a-com-Transtorno-do-Espectro-Autista-300x197.jpg 300w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/08\/Site-Vara-determina-que-a-Caixa-cubra-assiste\u0302ncia-a\u0300-crianc\u0327a-com-Transtorno-do-Espectro-Autista-768x505.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p>.A genitora do paciente pedia a inclus\u00e3o da assist\u00eancia terap\u00eautica em ambiente domiciliar e escolar. J\u00e1a empresa alegava que a Terapia ABA n\u00e3o fazia parte do rol da Ag\u00eancia Nacional de Sa\u00fade, sobre os procedimentos cl\u00ednicos a serem oferecidos. Nenhum dos argumentos foi acolhido pelo \u00f3rg\u00e3o julgador.<\/p>\n\n\n\n<p>Conforme a decis\u00e3o, o plano de sa\u00fade deve cobrir o tratamento multidisciplinar do TEA, conforme prescri\u00e7\u00e3o m\u00e9dica, sem limita\u00e7\u00f5es de sess\u00f5es, nos termos das Leis n\u00bas 9.656\/1998 e 12.764\/2012 e da Resolu\u00e7\u00e3o Normativa n\u00ba 539\/2022 da ANS, que imp\u00f5em cobertura obrigat\u00f3ria para transtornos enquadrados na CID F84.<\/p><div class=\"dwvoi6a0442815e046\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.dwvoi6a0442815e046 {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.dwvoi6a0442815e046 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.dwvoi6a0442815e046 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.dwvoi6a0442815e046 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.dwvoi6a0442815e046 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.dwvoi6a0442815e046 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"ashjm6a0442815e02d\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.ashjm6a0442815e02d {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.ashjm6a0442815e02d {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.ashjm6a0442815e02d {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.ashjm6a0442815e02d {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.ashjm6a0442815e02d {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.ashjm6a0442815e02d {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>Segundo define o relator, ao contr\u00e1rio da alega\u00e7\u00e3o da empresa, o m\u00e9todo ABA est\u00e1 inclu\u00eddo no rol de procedimentos da ANS, sendo abusiva a negativa de cobertura do tratamento indicada pelo m\u00e9dico respons\u00e1vel, conforme entendimento consolidado pelo STJ, mas o custeio de assist\u00eancia terap\u00eautica em ambiente domiciliar e escolar n\u00e3o \u00e9 obrigat\u00f3rio.<\/p>\n\n\n\n<p>\u201cPois a profiss\u00e3o de assistente terap\u00eautico n\u00e3o \u00e9 regulamentada, al\u00e9m de transcender a especificidade do contrato de plano de sa\u00fade, conforme precedente desta Corte e do STJ e n\u00e3o existem provas de que a crian\u00e7a precise usufruir do tratamento m\u00e9dico especificamente em ambiente domiciliar e\/ou escolar\u201d, esclarece o relator, desembargador Am\u00edlcar Maia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A 3\u00aa C\u00e2mara C\u00edvel do TJRN n\u00e3o deu provimento aos apelos concomitantes, movidos por uma operadora de plano de sa\u00fade e pela benefici\u00e1ria, e manteve, desta forma, uma decis\u00e3o judicial que determinava a autoriza\u00e7\u00e3o e cobertura de tratamento multidisciplinar para o Transtorno do Espectro Autista (TEA), conforme prescri\u00e7\u00e3o m\u00e9dica, sem limita\u00e7\u00f5es de sess\u00f5es .A genitora<br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2025\/04\/24\/autismo-obrigatoriedade-de-tratamento-domiciliar-e-tema-em-novo-julgamento\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/41572"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=41572"}],"version-history":[{"count":1,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/41572\/revisions"}],"predecessor-version":[{"id":41573,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/41572\/revisions\/41573"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=41572"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=41572"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=41572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}